{
    "id": 32949,
    "date": "2026-01-15T15:12:11",
    "date_gmt": "2026-01-15T21:12:11",
    "guid": {
        "rendered": "https:\/\/contratame.online\/es\/candidate\/esdrasmektronix\/"
    },
    "modified": "2026-01-15T15:12:11",
    "modified_gmt": "2026-01-15T21:12:11",
    "slug": "esdrasmektronix",
    "status": "publish",
    "type": "candidate",
    "link": "https:\/\/contratame.online\/en\/candidate\/esdrasmektronix\/",
    "title": {
        "rendered": "esdrasmektronix"
    },
    "content": {
        "rendered": "",
        "protected": false
    },
    "featured_media": 0,
    "comment_status": "open",
    "ping_status": "closed",
    "template": "",
    "candidate_category": [],
    "candidate_location": [],
    "candidate_tag": [],
    "class_list": [
        "post-32949",
        "candidate",
        "type-candidate",
        "status-publish",
        "hentry"
    ],
    "yoast_head": "<!-- This site is optimized with the Yoast SEO plugin v24.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>esdrasmektronix - Contratame.online<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"esdrasmektronix - Contratame.online\" \/>\n<meta property=\"og:url\" content=\"https:\/\/contratame.online\/en\/candidate\/esdrasmektronix\/\" \/>\n<meta property=\"og:site_name\" content=\"Contratame.online\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/contratamegt\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/contratame.online\/es\/candidate\/esdrasmektronix\/\",\"url\":\"https:\/\/contratame.online\/es\/candidate\/esdrasmektronix\/\",\"name\":\"esdrasmektronix - Contratame.online\",\"isPartOf\":{\"@id\":\"https:\/\/contratame.online\/#website\"},\"datePublished\":\"2026-01-15T21:12:11+00:00\",\"dateModified\":\"2026-01-15T21:12:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/contratame.online\/es\/candidate\/esdrasmektronix\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/contratame.online\/es\/candidate\/esdrasmektronix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/contratame.online\/es\/candidate\/esdrasmektronix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/contratame.online\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Candidates\",\"item\":\"https:\/\/contratame.online\/en\/candidate\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"esdrasmektronix\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/contratame.online\/#website\",\"url\":\"https:\/\/contratame.online\/\",\"name\":\"Contratame.online\",\"description\":\"Encuentra el empleo que siempre so\u00f1aste.\",\"publisher\":{\"@id\":\"https:\/\/contratame.online\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/contratame.online\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/contratame.online\/#organization\",\"name\":\"CONTRATA ME\",\"url\":\"https:\/\/contratame.online\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/contratame.online\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/contratame.online\/wp-content\/uploads\/2023\/07\/logohd.png\",\"contentUrl\":\"https:\/\/contratame.online\/wp-content\/uploads\/2023\/07\/logohd.png\",\"width\":150,\"height\":50,\"caption\":\"CONTRATA ME\"},\"image\":{\"@id\":\"https:\/\/contratame.online\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/contratamegt\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->",
    "yoast_head_json": {
        "title": "esdrasmektronix - Contratame.online",
        "robots": {
            "index": "noindex",
            "follow": "follow"
        },
        "og_locale": "en_US",
        "og_type": "article",
        "og_title": "esdrasmektronix - Contratame.online",
        "og_url": "https:\/\/contratame.online\/en\/candidate\/esdrasmektronix\/",
        "og_site_name": "Contratame.online",
        "article_publisher": "https:\/\/www.facebook.com\/contratamegt",
        "twitter_card": "summary_large_image",
        "schema": {
            "@context": "https:\/\/schema.org",
            "@graph": [
                {
                    "@type": "WebPage",
                    "@id": "https:\/\/contratame.online\/es\/candidate\/esdrasmektronix\/",
                    "url": "https:\/\/contratame.online\/es\/candidate\/esdrasmektronix\/",
                    "name": "esdrasmektronix - Contratame.online",
                    "isPartOf": {
                        "@id": "https:\/\/contratame.online\/#website"
                    },
                    "datePublished": "2026-01-15T21:12:11+00:00",
                    "dateModified": "2026-01-15T21:12:11+00:00",
                    "breadcrumb": {
                        "@id": "https:\/\/contratame.online\/es\/candidate\/esdrasmektronix\/#breadcrumb"
                    },
                    "inLanguage": "en-US",
                    "potentialAction": [
                        {
                            "@type": "ReadAction",
                            "target": [
                                "https:\/\/contratame.online\/es\/candidate\/esdrasmektronix\/"
                            ]
                        }
                    ]
                },
                {
                    "@type": "BreadcrumbList",
                    "@id": "https:\/\/contratame.online\/es\/candidate\/esdrasmektronix\/#breadcrumb",
                    "itemListElement": [
                        {
                            "@type": "ListItem",
                            "position": 1,
                            "name": "Portada",
                            "item": "https:\/\/contratame.online\/"
                        },
                        {
                            "@type": "ListItem",
                            "position": 2,
                            "name": "Candidates",
                            "item": "https:\/\/contratame.online\/en\/candidate\/"
                        },
                        {
                            "@type": "ListItem",
                            "position": 3,
                            "name": "esdrasmektronix"
                        }
                    ]
                },
                {
                    "@type": "WebSite",
                    "@id": "https:\/\/contratame.online\/#website",
                    "url": "https:\/\/contratame.online\/",
                    "name": "Contratame.online",
                    "description": "Encuentra el empleo que siempre so\u00f1aste.",
                    "publisher": {
                        "@id": "https:\/\/contratame.online\/#organization"
                    },
                    "potentialAction": [
                        {
                            "@type": "SearchAction",
                            "target": {
                                "@type": "EntryPoint",
                                "urlTemplate": "https:\/\/contratame.online\/?s={search_term_string}"
                            },
                            "query-input": {
                                "@type": "PropertyValueSpecification",
                                "valueRequired": true,
                                "valueName": "search_term_string"
                            }
                        }
                    ],
                    "inLanguage": "en-US"
                },
                {
                    "@type": "Organization",
                    "@id": "https:\/\/contratame.online\/#organization",
                    "name": "CONTRATA ME",
                    "url": "https:\/\/contratame.online\/",
                    "logo": {
                        "@type": "ImageObject",
                        "inLanguage": "en-US",
                        "@id": "https:\/\/contratame.online\/#\/schema\/logo\/image\/",
                        "url": "https:\/\/contratame.online\/wp-content\/uploads\/2023\/07\/logohd.png",
                        "contentUrl": "https:\/\/contratame.online\/wp-content\/uploads\/2023\/07\/logohd.png",
                        "width": 150,
                        "height": 50,
                        "caption": "CONTRATA ME"
                    },
                    "image": {
                        "@id": "https:\/\/contratame.online\/#\/schema\/logo\/image\/"
                    },
                    "sameAs": [
                        "https:\/\/www.facebook.com\/contratamegt"
                    ]
                }
            ]
        }
    },
    "metas": {
        "_candidate_location": [],
        "_candidate_age": "",
        "_candidate_gender": "",
        "_candidate_phone": "",
        "_candidate_email": "Esdrasmektronix@gmail.com",
        "_candidate_qualification": "",
        "_candidate_job_title": "",
        "_candidate_experience_time": "",
        "_candidate_salary": "",
        "_candidate_languages": "",
        "_candidate_skill": "",
        "_candidate_category": [],
        "_candidate_cv_attachment": "",
        "_candidate_education": "",
        "_candidate_experience": ""
    },
    "_links": {
        "self": [
            {
                "href": "https:\/\/contratame.online\/en\/wp-json\/wp\/v2\/candidate\/32949",
                "targetHints": {
                    "allow": [
                        "GET"
                    ]
                }
            }
        ],
        "collection": [
            {
                "href": "https:\/\/contratame.online\/en\/wp-json\/wp\/v2\/candidate"
            }
        ],
        "about": [
            {
                "href": "https:\/\/contratame.online\/en\/wp-json\/wp\/v2\/types\/candidate"
            }
        ],
        "replies": [
            {
                "embeddable": true,
                "href": "https:\/\/contratame.online\/en\/wp-json\/wp\/v2\/comments?post=32949"
            }
        ],
        "version-history": [
            {
                "count": 1,
                "href": "https:\/\/contratame.online\/en\/wp-json\/wp\/v2\/candidate\/32949\/revisions"
            }
        ],
        "predecessor-version": [
            {
                "id": 32950,
                "href": "https:\/\/contratame.online\/en\/wp-json\/wp\/v2\/candidate\/32949\/revisions\/32950"
            }
        ],
        "wp:attachment": [
            {
                "href": "https:\/\/contratame.online\/en\/wp-json\/wp\/v2\/media?parent=32949"
            }
        ],
        "wp:term": [
            {
                "taxonomy": "candidate_category",
                "embeddable": true,
                "href": "https:\/\/contratame.online\/en\/wp-json\/wp\/v2\/candidate_category?post=32949"
            },
            {
                "taxonomy": "candidate_location",
                "embeddable": true,
                "href": "https:\/\/contratame.online\/en\/wp-json\/wp\/v2\/candidate_location?post=32949"
            },
            {
                "taxonomy": "candidate_tag",
                "embeddable": true,
                "href": "https:\/\/contratame.online\/en\/wp-json\/wp\/v2\/candidate_tag?post=32949"
            }
        ],
        "curies": [
            {
                "name": "wp",
                "href": "https:\/\/api.w.org\/{rel}",
                "templated": true
            }
        ]
    }
}