{
    "id": 45069,
    "date": "2026-01-22T19:14:46",
    "date_gmt": "2026-01-23T01:14:46",
    "guid": {
        "rendered": "https:\/\/contratame.online\/es\/candidate\/hgonzalez-2319\/"
    },
    "modified": "2026-01-23T10:46:12",
    "modified_gmt": "2026-01-23T16:46:12",
    "slug": "hgonzalez-2319",
    "status": "publish",
    "type": "candidate",
    "link": "https:\/\/contratame.online\/en\/candidate\/hgonzalez-2319\/",
    "title": {
        "rendered": "Hileanna Gonz\u00e1lez Vargas De P\u00e9rez"
    },
    "content": {
        "rendered": "<p>Experiencia en el \u00e1rea de log\u00edstica, misma donde he desarrollado habilidades, tales como recepci\u00f3n y control de despacho y cumplimiento de entregas, elevando el OTIF del 64% al 95%, elaboraci\u00f3n de reportes diarios, cumplimiento de procedimientos, control de calidad, coordinaci\u00f3n de entregas y tiempos de despachos. Dentro de las herramientas que utilizada, eran\u00a0 CRM, SAP, Excel.<\/p>",
        "protected": false
    },
    "featured_media": 46412,
    "comment_status": "open",
    "ping_status": "closed",
    "template": "",
    "candidate_category": [
        278
    ],
    "candidate_location": [],
    "candidate_tag": [],
    "class_list": [
        "post-45069",
        "candidate",
        "type-candidate",
        "status-publish",
        "has-post-thumbnail",
        "hentry",
        "candidate_category-desarrollador"
    ],
    "yoast_head": "<!-- This site is optimized with the Yoast SEO plugin v24.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Hileanna Gonz\u00e1lez Vargas De P\u00e9rez - Contratame.online<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/contratame.online\/en\/candidate\/hgonzalez-2319\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hileanna Gonz\u00e1lez Vargas De P\u00e9rez - Contratame.online\" \/>\n<meta property=\"og:description\" content=\"Experiencia en el \u00e1rea de log\u00edstica, misma donde he desarrollado habilidades, tales como recepci\u00f3n y control de despacho y cumplimiento de entregas, elevando el OTIF del 64% al 95%, elaboraci\u00f3n de reportes diarios, cumplimiento de procedimientos, control de calidad, coordinaci\u00f3n de entregas y tiempos de despachos. Dentro de las herramientas que utilizada, eran\u00a0 CRM, SAP, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/contratame.online\/en\/candidate\/hgonzalez-2319\/\" \/>\n<meta property=\"og:site_name\" content=\"Contratame.online\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/contratamegt\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-23T16:46:12+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/contratame.online\/es\/candidate\/hgonzalez-2319\/\",\"url\":\"https:\/\/contratame.online\/es\/candidate\/hgonzalez-2319\/\",\"name\":\"Hileanna Gonz\u00e1lez Vargas De P\u00e9rez - Contratame.online\",\"isPartOf\":{\"@id\":\"https:\/\/contratame.online\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/contratame.online\/es\/candidate\/hgonzalez-2319\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/contratame.online\/es\/candidate\/hgonzalez-2319\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/contratame.online\/wp-content\/uploads\/wp-job-board-pro-uploads\/_candidate_featured_image\/2026\/01\/Hileanna-Gonzalez-Vargas_FOTO-scaled.jpg\",\"datePublished\":\"2026-01-23T01:14:46+00:00\",\"dateModified\":\"2026-01-23T16:46:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/contratame.online\/es\/candidate\/hgonzalez-2319\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/contratame.online\/es\/candidate\/hgonzalez-2319\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/contratame.online\/es\/candidate\/hgonzalez-2319\/#primaryimage\",\"url\":\"https:\/\/contratame.online\/wp-content\/uploads\/wp-job-board-pro-uploads\/_candidate_featured_image\/2026\/01\/Hileanna-Gonzalez-Vargas_FOTO-scaled.jpg\",\"contentUrl\":\"https:\/\/contratame.online\/wp-content\/uploads\/wp-job-board-pro-uploads\/_candidate_featured_image\/2026\/01\/Hileanna-Gonzalez-Vargas_FOTO-scaled.jpg\",\"width\":2560,\"height\":2373},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/contratame.online\/es\/candidate\/hgonzalez-2319\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/contratame.online\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Candidates\",\"item\":\"https:\/\/contratame.online\/en\/candidate\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Hileanna Gonz\u00e1lez Vargas De P\u00e9rez\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/contratame.online\/#website\",\"url\":\"https:\/\/contratame.online\/\",\"name\":\"Contratame.online\",\"description\":\"Encuentra el empleo que siempre so\u00f1aste.\",\"publisher\":{\"@id\":\"https:\/\/contratame.online\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/contratame.online\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/contratame.online\/#organization\",\"name\":\"CONTRATA ME\",\"url\":\"https:\/\/contratame.online\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/contratame.online\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/contratame.online\/wp-content\/uploads\/2023\/07\/logohd.png\",\"contentUrl\":\"https:\/\/contratame.online\/wp-content\/uploads\/2023\/07\/logohd.png\",\"width\":150,\"height\":50,\"caption\":\"CONTRATA ME\"},\"image\":{\"@id\":\"https:\/\/contratame.online\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/contratamegt\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->",
    "yoast_head_json": {
        "title": "Hileanna Gonz\u00e1lez Vargas De P\u00e9rez - Contratame.online",
        "robots": {
            "index": "index",
            "follow": "follow",
            "max-snippet": "max-snippet:-1",
            "max-image-preview": "max-image-preview:large",
            "max-video-preview": "max-video-preview:-1"
        },
        "canonical": "https:\/\/contratame.online\/en\/candidate\/hgonzalez-2319\/",
        "og_locale": "en_US",
        "og_type": "article",
        "og_title": "Hileanna Gonz\u00e1lez Vargas De P\u00e9rez - Contratame.online",
        "og_description": "Experiencia en el \u00e1rea de log\u00edstica, misma donde he desarrollado habilidades, tales como recepci\u00f3n y control de despacho y cumplimiento de entregas, elevando el OTIF del 64% al 95%, elaboraci\u00f3n de reportes diarios, cumplimiento de procedimientos, control de calidad, coordinaci\u00f3n de entregas y tiempos de despachos. Dentro de las herramientas que utilizada, eran\u00a0 CRM, SAP, [&hellip;]",
        "og_url": "https:\/\/contratame.online\/en\/candidate\/hgonzalez-2319\/",
        "og_site_name": "Contratame.online",
        "article_publisher": "https:\/\/www.facebook.com\/contratamegt",
        "article_modified_time": "2026-01-23T16:46:12+00:00",
        "twitter_card": "summary_large_image",
        "schema": {
            "@context": "https:\/\/schema.org",
            "@graph": [
                {
                    "@type": "WebPage",
                    "@id": "https:\/\/contratame.online\/es\/candidate\/hgonzalez-2319\/",
                    "url": "https:\/\/contratame.online\/es\/candidate\/hgonzalez-2319\/",
                    "name": "Hileanna Gonz\u00e1lez Vargas De P\u00e9rez - Contratame.online",
                    "isPartOf": {
                        "@id": "https:\/\/contratame.online\/#website"
                    },
                    "primaryImageOfPage": {
                        "@id": "https:\/\/contratame.online\/es\/candidate\/hgonzalez-2319\/#primaryimage"
                    },
                    "image": {
                        "@id": "https:\/\/contratame.online\/es\/candidate\/hgonzalez-2319\/#primaryimage"
                    },
                    "thumbnailUrl": "https:\/\/contratame.online\/wp-content\/uploads\/wp-job-board-pro-uploads\/_candidate_featured_image\/2026\/01\/Hileanna-Gonzalez-Vargas_FOTO-scaled.jpg",
                    "datePublished": "2026-01-23T01:14:46+00:00",
                    "dateModified": "2026-01-23T16:46:12+00:00",
                    "breadcrumb": {
                        "@id": "https:\/\/contratame.online\/es\/candidate\/hgonzalez-2319\/#breadcrumb"
                    },
                    "inLanguage": "en-US",
                    "potentialAction": [
                        {
                            "@type": "ReadAction",
                            "target": [
                                "https:\/\/contratame.online\/es\/candidate\/hgonzalez-2319\/"
                            ]
                        }
                    ]
                },
                {
                    "@type": "ImageObject",
                    "inLanguage": "en-US",
                    "@id": "https:\/\/contratame.online\/es\/candidate\/hgonzalez-2319\/#primaryimage",
                    "url": "https:\/\/contratame.online\/wp-content\/uploads\/wp-job-board-pro-uploads\/_candidate_featured_image\/2026\/01\/Hileanna-Gonzalez-Vargas_FOTO-scaled.jpg",
                    "contentUrl": "https:\/\/contratame.online\/wp-content\/uploads\/wp-job-board-pro-uploads\/_candidate_featured_image\/2026\/01\/Hileanna-Gonzalez-Vargas_FOTO-scaled.jpg",
                    "width": 2560,
                    "height": 2373
                },
                {
                    "@type": "BreadcrumbList",
                    "@id": "https:\/\/contratame.online\/es\/candidate\/hgonzalez-2319\/#breadcrumb",
                    "itemListElement": [
                        {
                            "@type": "ListItem",
                            "position": 1,
                            "name": "Portada",
                            "item": "https:\/\/contratame.online\/"
                        },
                        {
                            "@type": "ListItem",
                            "position": 2,
                            "name": "Candidates",
                            "item": "https:\/\/contratame.online\/en\/candidate\/"
                        },
                        {
                            "@type": "ListItem",
                            "position": 3,
                            "name": "Hileanna Gonz\u00e1lez Vargas De P\u00e9rez"
                        }
                    ]
                },
                {
                    "@type": "WebSite",
                    "@id": "https:\/\/contratame.online\/#website",
                    "url": "https:\/\/contratame.online\/",
                    "name": "Contratame.online",
                    "description": "Encuentra el empleo que siempre so\u00f1aste.",
                    "publisher": {
                        "@id": "https:\/\/contratame.online\/#organization"
                    },
                    "potentialAction": [
                        {
                            "@type": "SearchAction",
                            "target": {
                                "@type": "EntryPoint",
                                "urlTemplate": "https:\/\/contratame.online\/?s={search_term_string}"
                            },
                            "query-input": {
                                "@type": "PropertyValueSpecification",
                                "valueRequired": true,
                                "valueName": "search_term_string"
                            }
                        }
                    ],
                    "inLanguage": "en-US"
                },
                {
                    "@type": "Organization",
                    "@id": "https:\/\/contratame.online\/#organization",
                    "name": "CONTRATA ME",
                    "url": "https:\/\/contratame.online\/",
                    "logo": {
                        "@type": "ImageObject",
                        "inLanguage": "en-US",
                        "@id": "https:\/\/contratame.online\/#\/schema\/logo\/image\/",
                        "url": "https:\/\/contratame.online\/wp-content\/uploads\/2023\/07\/logohd.png",
                        "contentUrl": "https:\/\/contratame.online\/wp-content\/uploads\/2023\/07\/logohd.png",
                        "width": 150,
                        "height": 50,
                        "caption": "CONTRATA ME"
                    },
                    "image": {
                        "@id": "https:\/\/contratame.online\/#\/schema\/logo\/image\/"
                    },
                    "sameAs": [
                        "https:\/\/www.facebook.com\/contratamegt"
                    ]
                }
            ]
        }
    },
    "metas": {
        "_candidate_location": [],
        "_candidate_age": "29",
        "_candidate_gender": "Femenino",
        "_candidate_phone": "46889257",
        "_candidate_email": "hgonzalez.2319@gmail.com",
        "_candidate_qualification": "Licenciatura",
        "_candidate_job_title": "Cierre de Pensum en Ingenier\u00eda Industrial",
        "_candidate_experience_time": "1 A\u00f1o",
        "_candidate_salary": "Q6,000",
        "_candidate_languages": [
            "Espa\u00f1ol"
        ],
        "_candidate_skill": "",
        "_candidate_category": {
            "278": "Desarrollador"
        },
        "_candidate_cv_attachment": {
            "45071": "https:\/\/contratame.online\/wp-content\/uploads\/2026\/01\/CV_Hileanna-Gonzalez.pdf"
        },
        "_candidate_education": "",
        "_candidate_experience": "",
        "_candidate_logo": "https:\/\/contratame.online\/wp-content\/uploads\/wp-job-board-pro-uploads\/_candidate_featured_image\/2026\/01\/Hileanna-Gonzalez-Vargas_FOTO-150x150.jpg"
    },
    "_links": {
        "self": [
            {
                "href": "https:\/\/contratame.online\/en\/wp-json\/wp\/v2\/candidate\/45069",
                "targetHints": {
                    "allow": [
                        "GET"
                    ]
                }
            }
        ],
        "collection": [
            {
                "href": "https:\/\/contratame.online\/en\/wp-json\/wp\/v2\/candidate"
            }
        ],
        "about": [
            {
                "href": "https:\/\/contratame.online\/en\/wp-json\/wp\/v2\/types\/candidate"
            }
        ],
        "replies": [
            {
                "embeddable": true,
                "href": "https:\/\/contratame.online\/en\/wp-json\/wp\/v2\/comments?post=45069"
            }
        ],
        "version-history": [
            {
                "count": 1,
                "href": "https:\/\/contratame.online\/en\/wp-json\/wp\/v2\/candidate\/45069\/revisions"
            }
        ],
        "predecessor-version": [
            {
                "id": 45070,
                "href": "https:\/\/contratame.online\/en\/wp-json\/wp\/v2\/candidate\/45069\/revisions\/45070"
            }
        ],
        "wp:featuredmedia": [
            {
                "embeddable": true,
                "href": "https:\/\/contratame.online\/en\/wp-json\/wp\/v2\/media\/46412"
            }
        ],
        "wp:attachment": [
            {
                "href": "https:\/\/contratame.online\/en\/wp-json\/wp\/v2\/media?parent=45069"
            }
        ],
        "wp:term": [
            {
                "taxonomy": "candidate_category",
                "embeddable": true,
                "href": "https:\/\/contratame.online\/en\/wp-json\/wp\/v2\/candidate_category?post=45069"
            },
            {
                "taxonomy": "candidate_location",
                "embeddable": true,
                "href": "https:\/\/contratame.online\/en\/wp-json\/wp\/v2\/candidate_location?post=45069"
            },
            {
                "taxonomy": "candidate_tag",
                "embeddable": true,
                "href": "https:\/\/contratame.online\/en\/wp-json\/wp\/v2\/candidate_tag?post=45069"
            }
        ],
        "curies": [
            {
                "name": "wp",
                "href": "https:\/\/api.w.org\/{rel}",
                "templated": true
            }
        ]
    }
}