{
    "id": 45635,
    "date": "2026-01-22T22:37:35",
    "date_gmt": "2026-01-23T04:37:35",
    "guid": {
        "rendered": "https:\/\/contratame.online\/es\/candidate\/sjimenezrpinto\/"
    },
    "modified": "2026-02-05T16:40:32",
    "modified_gmt": "2026-02-05T22:40:32",
    "slug": "sjimenezrpinto",
    "status": "publish",
    "type": "candidate",
    "link": "https:\/\/contratame.online\/en\/candidate\/sjimenezrpinto\/",
    "title": {
        "rendered": "SERGIO RENE JIMENEZ PINTO"
    },
    "content": {
        "rendered": "<p>He tenido experiencia laboral en el ramo de tecnologia logre en cierto momento ser subkefe de sistemas teniendo a cargo 7 personas luego pase siendo desarrollador de software en diferentes plataformas, integracion de apis, reporteria (c$, genexus, gluware, reporting services, integration services, bases de datos sqlserver y oracle)<\/p>",
        "protected": false
    },
    "featured_media": 47394,
    "comment_status": "open",
    "ping_status": "closed",
    "template": "",
    "candidate_category": [
        278
    ],
    "candidate_location": [],
    "candidate_tag": [],
    "class_list": [
        "post-45635",
        "candidate",
        "type-candidate",
        "status-publish",
        "has-post-thumbnail",
        "hentry",
        "candidate_category-desarrollador"
    ],
    "yoast_head": "<!-- This site is optimized with the Yoast SEO plugin v24.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>SERGIO RENE JIMENEZ PINTO - Contratame.online<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/contratame.online\/en\/candidate\/sjimenezrpinto\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SERGIO RENE JIMENEZ PINTO - Contratame.online\" \/>\n<meta property=\"og:description\" content=\"He tenido experiencia laboral en el ramo de tecnologia logre en cierto momento ser subkefe de sistemas teniendo a cargo 7 personas luego pase siendo desarrollador de software en diferentes plataformas, integracion de apis, reporteria (c$, genexus, gluware, reporting services, integration services, bases de datos sqlserver y oracle)\" \/>\n<meta property=\"og:url\" content=\"https:\/\/contratame.online\/en\/candidate\/sjimenezrpinto\/\" \/>\n<meta property=\"og:site_name\" content=\"Contratame.online\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/contratamegt\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-05T22:40:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/contratame.online\/wp-content\/uploads\/wp-job-board-pro-uploads\/_candidate_featured_image\/2026\/01\/inbound7653307795855352028-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/contratame.online\/es\/candidate\/sjimenezrpinto\/\",\"url\":\"https:\/\/contratame.online\/es\/candidate\/sjimenezrpinto\/\",\"name\":\"SERGIO RENE JIMENEZ PINTO - Contratame.online\",\"isPartOf\":{\"@id\":\"https:\/\/contratame.online\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/contratame.online\/es\/candidate\/sjimenezrpinto\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/contratame.online\/es\/candidate\/sjimenezrpinto\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/contratame.online\/wp-content\/uploads\/wp-job-board-pro-uploads\/_candidate_featured_image\/2026\/01\/inbound7653307795855352028-scaled.jpg\",\"datePublished\":\"2026-01-23T04:37:35+00:00\",\"dateModified\":\"2026-02-05T22:40:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/contratame.online\/es\/candidate\/sjimenezrpinto\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/contratame.online\/es\/candidate\/sjimenezrpinto\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/contratame.online\/es\/candidate\/sjimenezrpinto\/#primaryimage\",\"url\":\"https:\/\/contratame.online\/wp-content\/uploads\/wp-job-board-pro-uploads\/_candidate_featured_image\/2026\/01\/inbound7653307795855352028-scaled.jpg\",\"contentUrl\":\"https:\/\/contratame.online\/wp-content\/uploads\/wp-job-board-pro-uploads\/_candidate_featured_image\/2026\/01\/inbound7653307795855352028-scaled.jpg\",\"width\":1920,\"height\":2560},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/contratame.online\/es\/candidate\/sjimenezrpinto\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/contratame.online\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Candidates\",\"item\":\"https:\/\/contratame.online\/en\/candidate\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"SERGIO RENE JIMENEZ PINTO\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/contratame.online\/#website\",\"url\":\"https:\/\/contratame.online\/\",\"name\":\"Contratame.online\",\"description\":\"Encuentra el empleo que siempre so\u00f1aste.\",\"publisher\":{\"@id\":\"https:\/\/contratame.online\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/contratame.online\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/contratame.online\/#organization\",\"name\":\"CONTRATA ME\",\"url\":\"https:\/\/contratame.online\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/contratame.online\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/contratame.online\/wp-content\/uploads\/2023\/07\/logohd.png\",\"contentUrl\":\"https:\/\/contratame.online\/wp-content\/uploads\/2023\/07\/logohd.png\",\"width\":150,\"height\":50,\"caption\":\"CONTRATA ME\"},\"image\":{\"@id\":\"https:\/\/contratame.online\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/contratamegt\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->",
    "yoast_head_json": {
        "title": "SERGIO RENE JIMENEZ PINTO - Contratame.online",
        "robots": {
            "index": "index",
            "follow": "follow",
            "max-snippet": "max-snippet:-1",
            "max-image-preview": "max-image-preview:large",
            "max-video-preview": "max-video-preview:-1"
        },
        "canonical": "https:\/\/contratame.online\/en\/candidate\/sjimenezrpinto\/",
        "og_locale": "en_US",
        "og_type": "article",
        "og_title": "SERGIO RENE JIMENEZ PINTO - Contratame.online",
        "og_description": "He tenido experiencia laboral en el ramo de tecnologia logre en cierto momento ser subkefe de sistemas teniendo a cargo 7 personas luego pase siendo desarrollador de software en diferentes plataformas, integracion de apis, reporteria (c$, genexus, gluware, reporting services, integration services, bases de datos sqlserver y oracle)",
        "og_url": "https:\/\/contratame.online\/en\/candidate\/sjimenezrpinto\/",
        "og_site_name": "Contratame.online",
        "article_publisher": "https:\/\/www.facebook.com\/contratamegt",
        "article_modified_time": "2026-02-05T22:40:32+00:00",
        "og_image": [
            {
                "width": 1920,
                "height": 2560,
                "url": "https:\/\/contratame.online\/wp-content\/uploads\/wp-job-board-pro-uploads\/_candidate_featured_image\/2026\/01\/inbound7653307795855352028-scaled.jpg",
                "type": "image\/jpeg"
            }
        ],
        "twitter_card": "summary_large_image",
        "schema": {
            "@context": "https:\/\/schema.org",
            "@graph": [
                {
                    "@type": "WebPage",
                    "@id": "https:\/\/contratame.online\/es\/candidate\/sjimenezrpinto\/",
                    "url": "https:\/\/contratame.online\/es\/candidate\/sjimenezrpinto\/",
                    "name": "SERGIO RENE JIMENEZ PINTO - Contratame.online",
                    "isPartOf": {
                        "@id": "https:\/\/contratame.online\/#website"
                    },
                    "primaryImageOfPage": {
                        "@id": "https:\/\/contratame.online\/es\/candidate\/sjimenezrpinto\/#primaryimage"
                    },
                    "image": {
                        "@id": "https:\/\/contratame.online\/es\/candidate\/sjimenezrpinto\/#primaryimage"
                    },
                    "thumbnailUrl": "https:\/\/contratame.online\/wp-content\/uploads\/wp-job-board-pro-uploads\/_candidate_featured_image\/2026\/01\/inbound7653307795855352028-scaled.jpg",
                    "datePublished": "2026-01-23T04:37:35+00:00",
                    "dateModified": "2026-02-05T22:40:32+00:00",
                    "breadcrumb": {
                        "@id": "https:\/\/contratame.online\/es\/candidate\/sjimenezrpinto\/#breadcrumb"
                    },
                    "inLanguage": "en-US",
                    "potentialAction": [
                        {
                            "@type": "ReadAction",
                            "target": [
                                "https:\/\/contratame.online\/es\/candidate\/sjimenezrpinto\/"
                            ]
                        }
                    ]
                },
                {
                    "@type": "ImageObject",
                    "inLanguage": "en-US",
                    "@id": "https:\/\/contratame.online\/es\/candidate\/sjimenezrpinto\/#primaryimage",
                    "url": "https:\/\/contratame.online\/wp-content\/uploads\/wp-job-board-pro-uploads\/_candidate_featured_image\/2026\/01\/inbound7653307795855352028-scaled.jpg",
                    "contentUrl": "https:\/\/contratame.online\/wp-content\/uploads\/wp-job-board-pro-uploads\/_candidate_featured_image\/2026\/01\/inbound7653307795855352028-scaled.jpg",
                    "width": 1920,
                    "height": 2560
                },
                {
                    "@type": "BreadcrumbList",
                    "@id": "https:\/\/contratame.online\/es\/candidate\/sjimenezrpinto\/#breadcrumb",
                    "itemListElement": [
                        {
                            "@type": "ListItem",
                            "position": 1,
                            "name": "Portada",
                            "item": "https:\/\/contratame.online\/"
                        },
                        {
                            "@type": "ListItem",
                            "position": 2,
                            "name": "Candidates",
                            "item": "https:\/\/contratame.online\/en\/candidate\/"
                        },
                        {
                            "@type": "ListItem",
                            "position": 3,
                            "name": "SERGIO RENE JIMENEZ PINTO"
                        }
                    ]
                },
                {
                    "@type": "WebSite",
                    "@id": "https:\/\/contratame.online\/#website",
                    "url": "https:\/\/contratame.online\/",
                    "name": "Contratame.online",
                    "description": "Encuentra el empleo que siempre so\u00f1aste.",
                    "publisher": {
                        "@id": "https:\/\/contratame.online\/#organization"
                    },
                    "potentialAction": [
                        {
                            "@type": "SearchAction",
                            "target": {
                                "@type": "EntryPoint",
                                "urlTemplate": "https:\/\/contratame.online\/?s={search_term_string}"
                            },
                            "query-input": {
                                "@type": "PropertyValueSpecification",
                                "valueRequired": true,
                                "valueName": "search_term_string"
                            }
                        }
                    ],
                    "inLanguage": "en-US"
                },
                {
                    "@type": "Organization",
                    "@id": "https:\/\/contratame.online\/#organization",
                    "name": "CONTRATA ME",
                    "url": "https:\/\/contratame.online\/",
                    "logo": {
                        "@type": "ImageObject",
                        "inLanguage": "en-US",
                        "@id": "https:\/\/contratame.online\/#\/schema\/logo\/image\/",
                        "url": "https:\/\/contratame.online\/wp-content\/uploads\/2023\/07\/logohd.png",
                        "contentUrl": "https:\/\/contratame.online\/wp-content\/uploads\/2023\/07\/logohd.png",
                        "width": 150,
                        "height": 50,
                        "caption": "CONTRATA ME"
                    },
                    "image": {
                        "@id": "https:\/\/contratame.online\/#\/schema\/logo\/image\/"
                    },
                    "sameAs": [
                        "https:\/\/www.facebook.com\/contratamegt"
                    ]
                }
            ]
        }
    },
    "metas": {
        "_candidate_location": [],
        "_candidate_age": "49",
        "_candidate_gender": "Masculino",
        "_candidate_phone": "54115400",
        "_candidate_email": "sjimenezrpinto@gmail.com",
        "_candidate_qualification": "Licenciatura",
        "_candidate_job_title": "Tecnologia",
        "_candidate_experience_time": "+6 A\u00f1os",
        "_candidate_salary": "Q15,000",
        "_candidate_languages": [
            "Espa\u00f1ol"
        ],
        "_candidate_skill": "",
        "_candidate_category": {
            "278": "Desarrollador"
        },
        "_candidate_cv_attachment": {
            "47395": "https:\/\/contratame.online\/wp-content\/uploads\/wp-job-board-pro-uploads\/_candidate_cv_attachment\/2026\/01\/inbound703774817017555219.pdf"
        },
        "_candidate_education": [
            {
                "title": "LICENCIATURA EN INFORMATICA Y ADMINISTRACION DE NEGOCIOS",
                "academy": "UNIVERSIDAD GALILEO",
                "year": "2009",
                "description": "LICENCIADO EN INFORMATICA Y ADMINISTRACION DE NEGOCIOS, CONSIDERO QUE PUEDO OFRECER MIS SERVICIOS DE AMBAS ACTIVIDADES YA QUE MI EXPERIENCIA ES EN DEPARTAMENTOS DE IT Y CONSIDERO QUE TENGO EL CONOCIMIENTO PARA PODER ADMINISTRAR CUALQUIER EMPRESA"
            },
            {
                "title": "PERITO CONTADOR CON ESPECIALIDAD EN COMPUTACION COMERCIAL",
                "academy": "LICEO DE COMPUTACION C.S.S.",
                "year": "1994",
                "description": "GRADUADO DE DIVERSIFICADO"
            }
        ],
        "_candidate_experience": [
            {
                "title": "ANALISTA Y DESARROLLADOR DE SOFTWARE",
                "start_date": "2019",
                "end_date": "2025",
                "company": "FINCA NETWORK SUPPORT B.V.",
                "description": "ANALISIS DE SISTEMAS, DESARROLLO DE SOFTWARE EN C$, DESARROLLO DE REPORTES EN REPORTING SERVICES, CRYSTAL REPORTS, JASPER REPORTS, DESARROLLO DE ESTRUCTURAS DE DATOS CON INTEGRATION SERVICES, ASI COMO EL DESARROLLO DE INTEGRACIONES PARA EL CONSUMO DE APIS EN UNA HERRAMIENTA LLAMADA GLUWARE."
            },
            {
                "title": "MFSI, S.A",
                "start_date": "2014",
                "end_date": "2019",
                "company": "ANALISTA Y DESARROLLADOR DE SOFWARE",
                "description": "POR SERVICIOS PROFESIONALES."
            },
            {
                "title": "TUTOR",
                "start_date": "1998",
                "end_date": "A LA FECHA",
                "company": "UNIVERSIDAD GALILEO",
                "description": "TUTOR DE LOS CURSOS DEL PROGRAMA IDEA EN UNIVERSIDAD GALILEO, TRABAJANDO POR MEDIO DE SERVICIOS PROFESIONALES LOS FINES DE SEMANA."
            }
        ],
        "_candidate_logo": "https:\/\/contratame.online\/wp-content\/uploads\/wp-job-board-pro-uploads\/_candidate_featured_image\/2026\/01\/inbound7653307795855352028-150x150.jpg"
    },
    "_links": {
        "self": [
            {
                "href": "https:\/\/contratame.online\/en\/wp-json\/wp\/v2\/candidate\/45635",
                "targetHints": {
                    "allow": [
                        "GET"
                    ]
                }
            }
        ],
        "collection": [
            {
                "href": "https:\/\/contratame.online\/en\/wp-json\/wp\/v2\/candidate"
            }
        ],
        "about": [
            {
                "href": "https:\/\/contratame.online\/en\/wp-json\/wp\/v2\/types\/candidate"
            }
        ],
        "replies": [
            {
                "embeddable": true,
                "href": "https:\/\/contratame.online\/en\/wp-json\/wp\/v2\/comments?post=45635"
            }
        ],
        "version-history": [
            {
                "count": 1,
                "href": "https:\/\/contratame.online\/en\/wp-json\/wp\/v2\/candidate\/45635\/revisions"
            }
        ],
        "predecessor-version": [
            {
                "id": 45636,
                "href": "https:\/\/contratame.online\/en\/wp-json\/wp\/v2\/candidate\/45635\/revisions\/45636"
            }
        ],
        "wp:featuredmedia": [
            {
                "embeddable": true,
                "href": "https:\/\/contratame.online\/en\/wp-json\/wp\/v2\/media\/47394"
            }
        ],
        "wp:attachment": [
            {
                "href": "https:\/\/contratame.online\/en\/wp-json\/wp\/v2\/media?parent=45635"
            }
        ],
        "wp:term": [
            {
                "taxonomy": "candidate_category",
                "embeddable": true,
                "href": "https:\/\/contratame.online\/en\/wp-json\/wp\/v2\/candidate_category?post=45635"
            },
            {
                "taxonomy": "candidate_location",
                "embeddable": true,
                "href": "https:\/\/contratame.online\/en\/wp-json\/wp\/v2\/candidate_location?post=45635"
            },
            {
                "taxonomy": "candidate_tag",
                "embeddable": true,
                "href": "https:\/\/contratame.online\/en\/wp-json\/wp\/v2\/candidate_tag?post=45635"
            }
        ],
        "curies": [
            {
                "name": "wp",
                "href": "https:\/\/api.w.org\/{rel}",
                "templated": true
            }
        ]
    }
}