{
    "id": 49094,
    "date": "2026-01-24T18:39:24",
    "date_gmt": "2026-01-25T00:39:24",
    "guid": {
        "rendered": "https:\/\/contratame.online\/es\/candidate\/eliuperez123mendez\/"
    },
    "modified": "2026-01-24T18:42:48",
    "modified_gmt": "2026-01-25T00:42:48",
    "slug": "eliuperez123mendez",
    "status": "publish",
    "type": "candidate",
    "link": "https:\/\/contratame.online\/en\/candidate\/eliuperez123mendez\/",
    "title": {
        "rendered": "eliuperez123mendez"
    },
    "content": {
        "rendered": "<p><!--more-->He laborado en grupos de Tiendas asociadas como cajero auxiliar todo relacionado a supermercado<\/p>",
        "protected": false
    },
    "featured_media": 49102,
    "comment_status": "open",
    "ping_status": "closed",
    "template": "",
    "candidate_category": [
        278
    ],
    "candidate_location": [],
    "candidate_tag": [],
    "class_list": [
        "post-49094",
        "candidate",
        "type-candidate",
        "status-publish",
        "has-post-thumbnail",
        "hentry",
        "candidate_category-desarrollador"
    ],
    "yoast_head": "<!-- This site is optimized with the Yoast SEO plugin v24.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>eliuperez123mendez - Contratame.online<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/contratame.online\/en\/candidate\/eliuperez123mendez\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"eliuperez123mendez - Contratame.online\" \/>\n<meta property=\"og:url\" content=\"https:\/\/contratame.online\/en\/candidate\/eliuperez123mendez\/\" \/>\n<meta property=\"og:site_name\" content=\"Contratame.online\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/contratamegt\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-25T00:42:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/contratame.online\/wp-content\/uploads\/wp-job-board-pro-uploads\/_candidate_featured_image\/2026\/01\/inbound734961351645803596-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/contratame.online\/es\/candidate\/eliuperez123mendez\/\",\"url\":\"https:\/\/contratame.online\/es\/candidate\/eliuperez123mendez\/\",\"name\":\"eliuperez123mendez - Contratame.online\",\"isPartOf\":{\"@id\":\"https:\/\/contratame.online\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/contratame.online\/es\/candidate\/eliuperez123mendez\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/contratame.online\/es\/candidate\/eliuperez123mendez\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/contratame.online\/wp-content\/uploads\/wp-job-board-pro-uploads\/_candidate_featured_image\/2026\/01\/inbound734961351645803596-scaled.jpg\",\"datePublished\":\"2026-01-25T00:39:24+00:00\",\"dateModified\":\"2026-01-25T00:42:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/contratame.online\/es\/candidate\/eliuperez123mendez\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/contratame.online\/es\/candidate\/eliuperez123mendez\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/contratame.online\/es\/candidate\/eliuperez123mendez\/#primaryimage\",\"url\":\"https:\/\/contratame.online\/wp-content\/uploads\/wp-job-board-pro-uploads\/_candidate_featured_image\/2026\/01\/inbound734961351645803596-scaled.jpg\",\"contentUrl\":\"https:\/\/contratame.online\/wp-content\/uploads\/wp-job-board-pro-uploads\/_candidate_featured_image\/2026\/01\/inbound734961351645803596-scaled.jpg\",\"width\":1920,\"height\":2560},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/contratame.online\/es\/candidate\/eliuperez123mendez\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/contratame.online\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Candidates\",\"item\":\"https:\/\/contratame.online\/en\/candidate\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"eliuperez123mendez\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/contratame.online\/#website\",\"url\":\"https:\/\/contratame.online\/\",\"name\":\"Contratame.online\",\"description\":\"Encuentra el empleo que siempre so\u00f1aste.\",\"publisher\":{\"@id\":\"https:\/\/contratame.online\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/contratame.online\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/contratame.online\/#organization\",\"name\":\"CONTRATA ME\",\"url\":\"https:\/\/contratame.online\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/contratame.online\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/contratame.online\/wp-content\/uploads\/2023\/07\/logohd.png\",\"contentUrl\":\"https:\/\/contratame.online\/wp-content\/uploads\/2023\/07\/logohd.png\",\"width\":150,\"height\":50,\"caption\":\"CONTRATA ME\"},\"image\":{\"@id\":\"https:\/\/contratame.online\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/contratamegt\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->",
    "yoast_head_json": {
        "title": "eliuperez123mendez - Contratame.online",
        "robots": {
            "index": "index",
            "follow": "follow",
            "max-snippet": "max-snippet:-1",
            "max-image-preview": "max-image-preview:large",
            "max-video-preview": "max-video-preview:-1"
        },
        "canonical": "https:\/\/contratame.online\/en\/candidate\/eliuperez123mendez\/",
        "og_locale": "en_US",
        "og_type": "article",
        "og_title": "eliuperez123mendez - Contratame.online",
        "og_url": "https:\/\/contratame.online\/en\/candidate\/eliuperez123mendez\/",
        "og_site_name": "Contratame.online",
        "article_publisher": "https:\/\/www.facebook.com\/contratamegt",
        "article_modified_time": "2026-01-25T00:42:48+00:00",
        "og_image": [
            {
                "width": 1920,
                "height": 2560,
                "url": "https:\/\/contratame.online\/wp-content\/uploads\/wp-job-board-pro-uploads\/_candidate_featured_image\/2026\/01\/inbound734961351645803596-scaled.jpg",
                "type": "image\/jpeg"
            }
        ],
        "twitter_card": "summary_large_image",
        "schema": {
            "@context": "https:\/\/schema.org",
            "@graph": [
                {
                    "@type": "WebPage",
                    "@id": "https:\/\/contratame.online\/es\/candidate\/eliuperez123mendez\/",
                    "url": "https:\/\/contratame.online\/es\/candidate\/eliuperez123mendez\/",
                    "name": "eliuperez123mendez - Contratame.online",
                    "isPartOf": {
                        "@id": "https:\/\/contratame.online\/#website"
                    },
                    "primaryImageOfPage": {
                        "@id": "https:\/\/contratame.online\/es\/candidate\/eliuperez123mendez\/#primaryimage"
                    },
                    "image": {
                        "@id": "https:\/\/contratame.online\/es\/candidate\/eliuperez123mendez\/#primaryimage"
                    },
                    "thumbnailUrl": "https:\/\/contratame.online\/wp-content\/uploads\/wp-job-board-pro-uploads\/_candidate_featured_image\/2026\/01\/inbound734961351645803596-scaled.jpg",
                    "datePublished": "2026-01-25T00:39:24+00:00",
                    "dateModified": "2026-01-25T00:42:48+00:00",
                    "breadcrumb": {
                        "@id": "https:\/\/contratame.online\/es\/candidate\/eliuperez123mendez\/#breadcrumb"
                    },
                    "inLanguage": "en-US",
                    "potentialAction": [
                        {
                            "@type": "ReadAction",
                            "target": [
                                "https:\/\/contratame.online\/es\/candidate\/eliuperez123mendez\/"
                            ]
                        }
                    ]
                },
                {
                    "@type": "ImageObject",
                    "inLanguage": "en-US",
                    "@id": "https:\/\/contratame.online\/es\/candidate\/eliuperez123mendez\/#primaryimage",
                    "url": "https:\/\/contratame.online\/wp-content\/uploads\/wp-job-board-pro-uploads\/_candidate_featured_image\/2026\/01\/inbound734961351645803596-scaled.jpg",
                    "contentUrl": "https:\/\/contratame.online\/wp-content\/uploads\/wp-job-board-pro-uploads\/_candidate_featured_image\/2026\/01\/inbound734961351645803596-scaled.jpg",
                    "width": 1920,
                    "height": 2560
                },
                {
                    "@type": "BreadcrumbList",
                    "@id": "https:\/\/contratame.online\/es\/candidate\/eliuperez123mendez\/#breadcrumb",
                    "itemListElement": [
                        {
                            "@type": "ListItem",
                            "position": 1,
                            "name": "Portada",
                            "item": "https:\/\/contratame.online\/"
                        },
                        {
                            "@type": "ListItem",
                            "position": 2,
                            "name": "Candidates",
                            "item": "https:\/\/contratame.online\/en\/candidate\/"
                        },
                        {
                            "@type": "ListItem",
                            "position": 3,
                            "name": "eliuperez123mendez"
                        }
                    ]
                },
                {
                    "@type": "WebSite",
                    "@id": "https:\/\/contratame.online\/#website",
                    "url": "https:\/\/contratame.online\/",
                    "name": "Contratame.online",
                    "description": "Encuentra el empleo que siempre so\u00f1aste.",
                    "publisher": {
                        "@id": "https:\/\/contratame.online\/#organization"
                    },
                    "potentialAction": [
                        {
                            "@type": "SearchAction",
                            "target": {
                                "@type": "EntryPoint",
                                "urlTemplate": "https:\/\/contratame.online\/?s={search_term_string}"
                            },
                            "query-input": {
                                "@type": "PropertyValueSpecification",
                                "valueRequired": true,
                                "valueName": "search_term_string"
                            }
                        }
                    ],
                    "inLanguage": "en-US"
                },
                {
                    "@type": "Organization",
                    "@id": "https:\/\/contratame.online\/#organization",
                    "name": "CONTRATA ME",
                    "url": "https:\/\/contratame.online\/",
                    "logo": {
                        "@type": "ImageObject",
                        "inLanguage": "en-US",
                        "@id": "https:\/\/contratame.online\/#\/schema\/logo\/image\/",
                        "url": "https:\/\/contratame.online\/wp-content\/uploads\/2023\/07\/logohd.png",
                        "contentUrl": "https:\/\/contratame.online\/wp-content\/uploads\/2023\/07\/logohd.png",
                        "width": 150,
                        "height": 50,
                        "caption": "CONTRATA ME"
                    },
                    "image": {
                        "@id": "https:\/\/contratame.online\/#\/schema\/logo\/image\/"
                    },
                    "sameAs": [
                        "https:\/\/www.facebook.com\/contratamegt"
                    ]
                }
            ]
        }
    },
    "metas": {
        "_candidate_location": [],
        "_candidate_age": "19",
        "_candidate_gender": "Masculino",
        "_candidate_phone": "3077-5129",
        "_candidate_email": "eliuperez123mendez@gmail.com",
        "_candidate_qualification": "Diversificado",
        "_candidate_job_title": "Bachillerato en computacion",
        "_candidate_experience_time": "1 A\u00f1o",
        "_candidate_salary": "",
        "_candidate_languages": [
            "Espa\u00f1ol"
        ],
        "_candidate_skill": "",
        "_candidate_category": {
            "278": "Desarrollador"
        },
        "_candidate_cv_attachment": {
            "49096": "https:\/\/contratame.online\/wp-content\/uploads\/2026\/01\/inbound663775245462845630.pdf"
        },
        "_candidate_education": "",
        "_candidate_experience": "",
        "_candidate_logo": "https:\/\/contratame.online\/wp-content\/uploads\/wp-job-board-pro-uploads\/_candidate_featured_image\/2026\/01\/inbound734961351645803596-150x150.jpg"
    },
    "_links": {
        "self": [
            {
                "href": "https:\/\/contratame.online\/en\/wp-json\/wp\/v2\/candidate\/49094",
                "targetHints": {
                    "allow": [
                        "GET"
                    ]
                }
            }
        ],
        "collection": [
            {
                "href": "https:\/\/contratame.online\/en\/wp-json\/wp\/v2\/candidate"
            }
        ],
        "about": [
            {
                "href": "https:\/\/contratame.online\/en\/wp-json\/wp\/v2\/types\/candidate"
            }
        ],
        "replies": [
            {
                "embeddable": true,
                "href": "https:\/\/contratame.online\/en\/wp-json\/wp\/v2\/comments?post=49094"
            }
        ],
        "version-history": [
            {
                "count": 1,
                "href": "https:\/\/contratame.online\/en\/wp-json\/wp\/v2\/candidate\/49094\/revisions"
            }
        ],
        "predecessor-version": [
            {
                "id": 49095,
                "href": "https:\/\/contratame.online\/en\/wp-json\/wp\/v2\/candidate\/49094\/revisions\/49095"
            }
        ],
        "wp:featuredmedia": [
            {
                "embeddable": true,
                "href": "https:\/\/contratame.online\/en\/wp-json\/wp\/v2\/media\/49102"
            }
        ],
        "wp:attachment": [
            {
                "href": "https:\/\/contratame.online\/en\/wp-json\/wp\/v2\/media?parent=49094"
            }
        ],
        "wp:term": [
            {
                "taxonomy": "candidate_category",
                "embeddable": true,
                "href": "https:\/\/contratame.online\/en\/wp-json\/wp\/v2\/candidate_category?post=49094"
            },
            {
                "taxonomy": "candidate_location",
                "embeddable": true,
                "href": "https:\/\/contratame.online\/en\/wp-json\/wp\/v2\/candidate_location?post=49094"
            },
            {
                "taxonomy": "candidate_tag",
                "embeddable": true,
                "href": "https:\/\/contratame.online\/en\/wp-json\/wp\/v2\/candidate_tag?post=49094"
            }
        ],
        "curies": [
            {
                "name": "wp",
                "href": "https:\/\/api.w.org\/{rel}",
                "templated": true
            }
        ]
    }
}