{
    "id": 76962,
    "date": "2026-08-03T21:12:13",
    "date_gmt": "2026-08-04T03:12:13",
    "guid": {
        "rendered": "https:\/\/contratame.online\/es\/candidate\/luismendizabal774\/"
    },
    "modified": "2026-08-03T21:17:15",
    "modified_gmt": "2026-08-04T03:17:15",
    "slug": "luismendizabal774",
    "status": "publish",
    "type": "candidate",
    "link": "https:\/\/contratame.online\/en\/candidate\/luismendizabal774\/",
    "title": {
        "rendered": "luismendizabal774"
    },
    "content": {
        "rendered": "<ol>\n<li>Receptor pagador (Banco G&amp;T continental)<\/li>\n<li>Log\u00edstica ,supervisor de eventos masivos y corporativos , BTL (RGS Global)<\/li>\n<li>logistica , bodega y operador en area de campo ( Isemi S.A.)<\/li>\n<li>axiliar de bodega (alimentos idealsa )<\/li>\n<\/ol>",
        "protected": false
    },
    "featured_media": 76965,
    "comment_status": "open",
    "ping_status": "closed",
    "template": "",
    "candidate_category": [],
    "candidate_location": [
        167
    ],
    "candidate_tag": [],
    "class_list": [
        "post-76962",
        "candidate",
        "type-candidate",
        "status-publish",
        "has-post-thumbnail",
        "hentry",
        "candidate_location-guatemala"
    ],
    "yoast_head": "<!-- This site is optimized with the Yoast SEO plugin v24.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>luismendizabal774 - Contratame.online<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"luismendizabal774 - Contratame.online\" \/>\n<meta property=\"og:description\" content=\"Receptor pagador (Banco G&amp;T continental) Log\u00edstica ,supervisor de eventos masivos y corporativos , BTL (RGS Global) logistica , bodega y operador en area de campo ( Isemi S.A.) axiliar de bodega (alimentos idealsa )\" \/>\n<meta property=\"og:url\" content=\"https:\/\/contratame.online\/en\/candidate\/luismendizabal774\/\" \/>\n<meta property=\"og:site_name\" content=\"Contratame.online\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/contratamegt\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-04T03:17:15+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/contratame.online\/es\/candidate\/luismendizabal774\/\",\"url\":\"https:\/\/contratame.online\/es\/candidate\/luismendizabal774\/\",\"name\":\"luismendizabal774 - Contratame.online\",\"isPartOf\":{\"@id\":\"https:\/\/contratame.online\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/contratame.online\/es\/candidate\/luismendizabal774\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/contratame.online\/es\/candidate\/luismendizabal774\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/contratame.online\/wp-content\/uploads\/wp-job-board-pro-uploads\/_candidate_featured_image\/2026\/08\/72A51337-413B-4F29-8D99-32C03E1715CA.jpeg\",\"datePublished\":\"2026-08-04T03:12:13+00:00\",\"dateModified\":\"2026-08-04T03:17:15+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/contratame.online\/es\/candidate\/luismendizabal774\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/contratame.online\/es\/candidate\/luismendizabal774\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/contratame.online\/es\/candidate\/luismendizabal774\/#primaryimage\",\"url\":\"https:\/\/contratame.online\/wp-content\/uploads\/wp-job-board-pro-uploads\/_candidate_featured_image\/2026\/08\/72A51337-413B-4F29-8D99-32C03E1715CA.jpeg\",\"contentUrl\":\"https:\/\/contratame.online\/wp-content\/uploads\/wp-job-board-pro-uploads\/_candidate_featured_image\/2026\/08\/72A51337-413B-4F29-8D99-32C03E1715CA.jpeg\",\"width\":1290,\"height\":2293},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/contratame.online\/es\/candidate\/luismendizabal774\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/contratame.online\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Candidates\",\"item\":\"https:\/\/contratame.online\/en\/candidate\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"luismendizabal774\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/contratame.online\/#website\",\"url\":\"https:\/\/contratame.online\/\",\"name\":\"Contratame.online\",\"description\":\"Encuentra el empleo que siempre so\u00f1aste.\",\"publisher\":{\"@id\":\"https:\/\/contratame.online\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/contratame.online\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/contratame.online\/#organization\",\"name\":\"CONTRATA ME\",\"url\":\"https:\/\/contratame.online\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/contratame.online\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/contratame.online\/wp-content\/uploads\/2023\/07\/logohd.png\",\"contentUrl\":\"https:\/\/contratame.online\/wp-content\/uploads\/2023\/07\/logohd.png\",\"width\":150,\"height\":50,\"caption\":\"CONTRATA ME\"},\"image\":{\"@id\":\"https:\/\/contratame.online\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/contratamegt\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->",
    "yoast_head_json": {
        "title": "luismendizabal774 - Contratame.online",
        "robots": {
            "index": "noindex",
            "follow": "follow"
        },
        "og_locale": "en_US",
        "og_type": "article",
        "og_title": "luismendizabal774 - Contratame.online",
        "og_description": "Receptor pagador (Banco G&amp;T continental) Log\u00edstica ,supervisor de eventos masivos y corporativos , BTL (RGS Global) logistica , bodega y operador en area de campo ( Isemi S.A.) axiliar de bodega (alimentos idealsa )",
        "og_url": "https:\/\/contratame.online\/en\/candidate\/luismendizabal774\/",
        "og_site_name": "Contratame.online",
        "article_publisher": "https:\/\/www.facebook.com\/contratamegt",
        "article_modified_time": "2026-08-04T03:17:15+00:00",
        "twitter_card": "summary_large_image",
        "schema": {
            "@context": "https:\/\/schema.org",
            "@graph": [
                {
                    "@type": "WebPage",
                    "@id": "https:\/\/contratame.online\/es\/candidate\/luismendizabal774\/",
                    "url": "https:\/\/contratame.online\/es\/candidate\/luismendizabal774\/",
                    "name": "luismendizabal774 - Contratame.online",
                    "isPartOf": {
                        "@id": "https:\/\/contratame.online\/#website"
                    },
                    "primaryImageOfPage": {
                        "@id": "https:\/\/contratame.online\/es\/candidate\/luismendizabal774\/#primaryimage"
                    },
                    "image": {
                        "@id": "https:\/\/contratame.online\/es\/candidate\/luismendizabal774\/#primaryimage"
                    },
                    "thumbnailUrl": "https:\/\/contratame.online\/wp-content\/uploads\/wp-job-board-pro-uploads\/_candidate_featured_image\/2026\/08\/72A51337-413B-4F29-8D99-32C03E1715CA.jpeg",
                    "datePublished": "2026-08-04T03:12:13+00:00",
                    "dateModified": "2026-08-04T03:17:15+00:00",
                    "breadcrumb": {
                        "@id": "https:\/\/contratame.online\/es\/candidate\/luismendizabal774\/#breadcrumb"
                    },
                    "inLanguage": "en-US",
                    "potentialAction": [
                        {
                            "@type": "ReadAction",
                            "target": [
                                "https:\/\/contratame.online\/es\/candidate\/luismendizabal774\/"
                            ]
                        }
                    ]
                },
                {
                    "@type": "ImageObject",
                    "inLanguage": "en-US",
                    "@id": "https:\/\/contratame.online\/es\/candidate\/luismendizabal774\/#primaryimage",
                    "url": "https:\/\/contratame.online\/wp-content\/uploads\/wp-job-board-pro-uploads\/_candidate_featured_image\/2026\/08\/72A51337-413B-4F29-8D99-32C03E1715CA.jpeg",
                    "contentUrl": "https:\/\/contratame.online\/wp-content\/uploads\/wp-job-board-pro-uploads\/_candidate_featured_image\/2026\/08\/72A51337-413B-4F29-8D99-32C03E1715CA.jpeg",
                    "width": 1290,
                    "height": 2293
                },
                {
                    "@type": "BreadcrumbList",
                    "@id": "https:\/\/contratame.online\/es\/candidate\/luismendizabal774\/#breadcrumb",
                    "itemListElement": [
                        {
                            "@type": "ListItem",
                            "position": 1,
                            "name": "Portada",
                            "item": "https:\/\/contratame.online\/"
                        },
                        {
                            "@type": "ListItem",
                            "position": 2,
                            "name": "Candidates",
                            "item": "https:\/\/contratame.online\/en\/candidate\/"
                        },
                        {
                            "@type": "ListItem",
                            "position": 3,
                            "name": "luismendizabal774"
                        }
                    ]
                },
                {
                    "@type": "WebSite",
                    "@id": "https:\/\/contratame.online\/#website",
                    "url": "https:\/\/contratame.online\/",
                    "name": "Contratame.online",
                    "description": "Encuentra el empleo que siempre so\u00f1aste.",
                    "publisher": {
                        "@id": "https:\/\/contratame.online\/#organization"
                    },
                    "potentialAction": [
                        {
                            "@type": "SearchAction",
                            "target": {
                                "@type": "EntryPoint",
                                "urlTemplate": "https:\/\/contratame.online\/?s={search_term_string}"
                            },
                            "query-input": {
                                "@type": "PropertyValueSpecification",
                                "valueRequired": true,
                                "valueName": "search_term_string"
                            }
                        }
                    ],
                    "inLanguage": "en-US"
                },
                {
                    "@type": "Organization",
                    "@id": "https:\/\/contratame.online\/#organization",
                    "name": "CONTRATA ME",
                    "url": "https:\/\/contratame.online\/",
                    "logo": {
                        "@type": "ImageObject",
                        "inLanguage": "en-US",
                        "@id": "https:\/\/contratame.online\/#\/schema\/logo\/image\/",
                        "url": "https:\/\/contratame.online\/wp-content\/uploads\/2023\/07\/logohd.png",
                        "contentUrl": "https:\/\/contratame.online\/wp-content\/uploads\/2023\/07\/logohd.png",
                        "width": 150,
                        "height": 50,
                        "caption": "CONTRATA ME"
                    },
                    "image": {
                        "@id": "https:\/\/contratame.online\/#\/schema\/logo\/image\/"
                    },
                    "sameAs": [
                        "https:\/\/www.facebook.com\/contratamegt"
                    ]
                }
            ]
        }
    },
    "metas": {
        "_candidate_location": {
            "167": "Guatemala"
        },
        "_candidate_age": "24",
        "_candidate_gender": "Masculino",
        "_candidate_phone": "36295907",
        "_candidate_email": "luismendizabal774@gmail.com",
        "_candidate_qualification": "Diversificado",
        "_candidate_job_title": "Estudiante",
        "_candidate_experience_time": "4 A\u00f1os",
        "_candidate_salary": "",
        "_candidate_languages": [
            "Espa\u00f1ol"
        ],
        "_candidate_skill": "",
        "_candidate_category": [],
        "_candidate_cv_attachment": {
            "76964": "https:\/\/contratame.online\/wp-content\/uploads\/2026\/08\/CV-Luis-Mendizabal-.pdf"
        },
        "_candidate_education": "",
        "_candidate_experience": "",
        "_candidate_logo": "https:\/\/contratame.online\/wp-content\/uploads\/wp-job-board-pro-uploads\/_candidate_featured_image\/2026\/08\/72A51337-413B-4F29-8D99-32C03E1715CA-150x150.jpeg"
    },
    "_links": {
        "self": [
            {
                "href": "https:\/\/contratame.online\/en\/wp-json\/wp\/v2\/candidate\/76962",
                "targetHints": {
                    "allow": [
                        "GET"
                    ]
                }
            }
        ],
        "collection": [
            {
                "href": "https:\/\/contratame.online\/en\/wp-json\/wp\/v2\/candidate"
            }
        ],
        "about": [
            {
                "href": "https:\/\/contratame.online\/en\/wp-json\/wp\/v2\/types\/candidate"
            }
        ],
        "replies": [
            {
                "embeddable": true,
                "href": "https:\/\/contratame.online\/en\/wp-json\/wp\/v2\/comments?post=76962"
            }
        ],
        "version-history": [
            {
                "count": 1,
                "href": "https:\/\/contratame.online\/en\/wp-json\/wp\/v2\/candidate\/76962\/revisions"
            }
        ],
        "predecessor-version": [
            {
                "id": 76963,
                "href": "https:\/\/contratame.online\/en\/wp-json\/wp\/v2\/candidate\/76962\/revisions\/76963"
            }
        ],
        "wp:featuredmedia": [
            {
                "embeddable": true,
                "href": "https:\/\/contratame.online\/en\/wp-json\/wp\/v2\/media\/76965"
            }
        ],
        "wp:attachment": [
            {
                "href": "https:\/\/contratame.online\/en\/wp-json\/wp\/v2\/media?parent=76962"
            }
        ],
        "wp:term": [
            {
                "taxonomy": "candidate_category",
                "embeddable": true,
                "href": "https:\/\/contratame.online\/en\/wp-json\/wp\/v2\/candidate_category?post=76962"
            },
            {
                "taxonomy": "candidate_location",
                "embeddable": true,
                "href": "https:\/\/contratame.online\/en\/wp-json\/wp\/v2\/candidate_location?post=76962"
            },
            {
                "taxonomy": "candidate_tag",
                "embeddable": true,
                "href": "https:\/\/contratame.online\/en\/wp-json\/wp\/v2\/candidate_tag?post=76962"
            }
        ],
        "curies": [
            {
                "name": "wp",
                "href": "https:\/\/api.w.org\/{rel}",
                "templated": true
            }
        ]
    }
}