{
    "id": 79873,
    "date": "2026-08-11T16:11:56",
    "date_gmt": "2026-08-11T22:11:56",
    "guid": {
        "rendered": "https:\/\/contratame.online\/es\/candidate\/diegogutierrez070778\/"
    },
    "modified": "2026-08-11T16:16:29",
    "modified_gmt": "2026-08-11T22:16:29",
    "slug": "diegogutierrez070778",
    "status": "publish",
    "type": "candidate",
    "link": "https:\/\/contratame.online\/en\/candidate\/diegogutierrez070778\/",
    "title": {
        "rendered": "diegogutierrez070778"
    },
    "content": {
        "rendered": "<p>Conocimiento de las ramas bancarias<\/p>",
        "protected": false
    },
    "featured_media": 79880,
    "comment_status": "open",
    "ping_status": "closed",
    "template": "",
    "candidate_category": [],
    "candidate_location": [
        167
    ],
    "candidate_tag": [],
    "class_list": [
        "post-79873",
        "candidate",
        "type-candidate",
        "status-publish",
        "has-post-thumbnail",
        "hentry",
        "candidate_location-guatemala"
    ],
    "yoast_head": "<!-- This site is optimized with the Yoast SEO plugin v24.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>diegogutierrez070778 - Contratame.online<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"diegogutierrez070778 - Contratame.online\" \/>\n<meta property=\"og:description\" content=\"Conocimiento de las ramas bancarias\" \/>\n<meta property=\"og:url\" content=\"https:\/\/contratame.online\/en\/candidate\/diegogutierrez070778\/\" \/>\n<meta property=\"og:site_name\" content=\"Contratame.online\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/contratamegt\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-11T22:16:29+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/contratame.online\/es\/candidate\/diegogutierrez070778\/\",\"url\":\"https:\/\/contratame.online\/es\/candidate\/diegogutierrez070778\/\",\"name\":\"diegogutierrez070778 - Contratame.online\",\"isPartOf\":{\"@id\":\"https:\/\/contratame.online\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/contratame.online\/es\/candidate\/diegogutierrez070778\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/contratame.online\/es\/candidate\/diegogutierrez070778\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/contratame.online\/wp-content\/uploads\/wp-job-board-pro-uploads\/_candidate_featured_image\/2026\/08\/IMG-20260730-WA0004.jpeg\",\"datePublished\":\"2026-08-11T22:11:56+00:00\",\"dateModified\":\"2026-08-11T22:16:29+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/contratame.online\/es\/candidate\/diegogutierrez070778\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/contratame.online\/es\/candidate\/diegogutierrez070778\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/contratame.online\/es\/candidate\/diegogutierrez070778\/#primaryimage\",\"url\":\"https:\/\/contratame.online\/wp-content\/uploads\/wp-job-board-pro-uploads\/_candidate_featured_image\/2026\/08\/IMG-20260730-WA0004.jpeg\",\"contentUrl\":\"https:\/\/contratame.online\/wp-content\/uploads\/wp-job-board-pro-uploads\/_candidate_featured_image\/2026\/08\/IMG-20260730-WA0004.jpeg\",\"width\":1440,\"height\":2560},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/contratame.online\/es\/candidate\/diegogutierrez070778\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/contratame.online\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Candidates\",\"item\":\"https:\/\/contratame.online\/en\/candidate\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"diegogutierrez070778\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/contratame.online\/#website\",\"url\":\"https:\/\/contratame.online\/\",\"name\":\"Contratame.online\",\"description\":\"Encuentra el empleo que siempre so\u00f1aste.\",\"publisher\":{\"@id\":\"https:\/\/contratame.online\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/contratame.online\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/contratame.online\/#organization\",\"name\":\"CONTRATA ME\",\"url\":\"https:\/\/contratame.online\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/contratame.online\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/contratame.online\/wp-content\/uploads\/2023\/07\/logohd.png\",\"contentUrl\":\"https:\/\/contratame.online\/wp-content\/uploads\/2023\/07\/logohd.png\",\"width\":150,\"height\":50,\"caption\":\"CONTRATA ME\"},\"image\":{\"@id\":\"https:\/\/contratame.online\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/contratamegt\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->",
    "yoast_head_json": {
        "title": "diegogutierrez070778 - Contratame.online",
        "robots": {
            "index": "noindex",
            "follow": "follow"
        },
        "og_locale": "en_US",
        "og_type": "article",
        "og_title": "diegogutierrez070778 - Contratame.online",
        "og_description": "Conocimiento de las ramas bancarias",
        "og_url": "https:\/\/contratame.online\/en\/candidate\/diegogutierrez070778\/",
        "og_site_name": "Contratame.online",
        "article_publisher": "https:\/\/www.facebook.com\/contratamegt",
        "article_modified_time": "2026-08-11T22:16:29+00:00",
        "twitter_card": "summary_large_image",
        "schema": {
            "@context": "https:\/\/schema.org",
            "@graph": [
                {
                    "@type": "WebPage",
                    "@id": "https:\/\/contratame.online\/es\/candidate\/diegogutierrez070778\/",
                    "url": "https:\/\/contratame.online\/es\/candidate\/diegogutierrez070778\/",
                    "name": "diegogutierrez070778 - Contratame.online",
                    "isPartOf": {
                        "@id": "https:\/\/contratame.online\/#website"
                    },
                    "primaryImageOfPage": {
                        "@id": "https:\/\/contratame.online\/es\/candidate\/diegogutierrez070778\/#primaryimage"
                    },
                    "image": {
                        "@id": "https:\/\/contratame.online\/es\/candidate\/diegogutierrez070778\/#primaryimage"
                    },
                    "thumbnailUrl": "https:\/\/contratame.online\/wp-content\/uploads\/wp-job-board-pro-uploads\/_candidate_featured_image\/2026\/08\/IMG-20260730-WA0004.jpeg",
                    "datePublished": "2026-08-11T22:11:56+00:00",
                    "dateModified": "2026-08-11T22:16:29+00:00",
                    "breadcrumb": {
                        "@id": "https:\/\/contratame.online\/es\/candidate\/diegogutierrez070778\/#breadcrumb"
                    },
                    "inLanguage": "en-US",
                    "potentialAction": [
                        {
                            "@type": "ReadAction",
                            "target": [
                                "https:\/\/contratame.online\/es\/candidate\/diegogutierrez070778\/"
                            ]
                        }
                    ]
                },
                {
                    "@type": "ImageObject",
                    "inLanguage": "en-US",
                    "@id": "https:\/\/contratame.online\/es\/candidate\/diegogutierrez070778\/#primaryimage",
                    "url": "https:\/\/contratame.online\/wp-content\/uploads\/wp-job-board-pro-uploads\/_candidate_featured_image\/2026\/08\/IMG-20260730-WA0004.jpeg",
                    "contentUrl": "https:\/\/contratame.online\/wp-content\/uploads\/wp-job-board-pro-uploads\/_candidate_featured_image\/2026\/08\/IMG-20260730-WA0004.jpeg",
                    "width": 1440,
                    "height": 2560
                },
                {
                    "@type": "BreadcrumbList",
                    "@id": "https:\/\/contratame.online\/es\/candidate\/diegogutierrez070778\/#breadcrumb",
                    "itemListElement": [
                        {
                            "@type": "ListItem",
                            "position": 1,
                            "name": "Portada",
                            "item": "https:\/\/contratame.online\/"
                        },
                        {
                            "@type": "ListItem",
                            "position": 2,
                            "name": "Candidates",
                            "item": "https:\/\/contratame.online\/en\/candidate\/"
                        },
                        {
                            "@type": "ListItem",
                            "position": 3,
                            "name": "diegogutierrez070778"
                        }
                    ]
                },
                {
                    "@type": "WebSite",
                    "@id": "https:\/\/contratame.online\/#website",
                    "url": "https:\/\/contratame.online\/",
                    "name": "Contratame.online",
                    "description": "Encuentra el empleo que siempre so\u00f1aste.",
                    "publisher": {
                        "@id": "https:\/\/contratame.online\/#organization"
                    },
                    "potentialAction": [
                        {
                            "@type": "SearchAction",
                            "target": {
                                "@type": "EntryPoint",
                                "urlTemplate": "https:\/\/contratame.online\/?s={search_term_string}"
                            },
                            "query-input": {
                                "@type": "PropertyValueSpecification",
                                "valueRequired": true,
                                "valueName": "search_term_string"
                            }
                        }
                    ],
                    "inLanguage": "en-US"
                },
                {
                    "@type": "Organization",
                    "@id": "https:\/\/contratame.online\/#organization",
                    "name": "CONTRATA ME",
                    "url": "https:\/\/contratame.online\/",
                    "logo": {
                        "@type": "ImageObject",
                        "inLanguage": "en-US",
                        "@id": "https:\/\/contratame.online\/#\/schema\/logo\/image\/",
                        "url": "https:\/\/contratame.online\/wp-content\/uploads\/2023\/07\/logohd.png",
                        "contentUrl": "https:\/\/contratame.online\/wp-content\/uploads\/2023\/07\/logohd.png",
                        "width": 150,
                        "height": 50,
                        "caption": "CONTRATA ME"
                    },
                    "image": {
                        "@id": "https:\/\/contratame.online\/#\/schema\/logo\/image\/"
                    },
                    "sameAs": [
                        "https:\/\/www.facebook.com\/contratamegt"
                    ]
                }
            ]
        }
    },
    "metas": {
        "_candidate_location": {
            "167": "Guatemala"
        },
        "_candidate_age": "48",
        "_candidate_gender": "Masculino",
        "_candidate_phone": "36269803",
        "_candidate_email": "diegogutierrez070778@gmail.com",
        "_candidate_qualification": "Diversificado",
        "_candidate_job_title": "Perito Contador con orientaci\u00f3n en computaci\u00f3n",
        "_candidate_experience_time": "+6 A\u00f1os",
        "_candidate_salary": "Q4,250.00",
        "_candidate_languages": [
            "Espa\u00f1ol"
        ],
        "_candidate_skill": "",
        "_candidate_category": [],
        "_candidate_cv_attachment": {
            "79875": "https:\/\/contratame.online\/wp-content\/uploads\/2026\/08\/20251128133340.pdf"
        },
        "_candidate_education": "",
        "_candidate_experience": "",
        "_candidate_logo": "https:\/\/contratame.online\/wp-content\/uploads\/wp-job-board-pro-uploads\/_candidate_featured_image\/2026\/08\/IMG-20260730-WA0004-150x150.jpeg"
    },
    "_links": {
        "self": [
            {
                "href": "https:\/\/contratame.online\/en\/wp-json\/wp\/v2\/candidate\/79873",
                "targetHints": {
                    "allow": [
                        "GET"
                    ]
                }
            }
        ],
        "collection": [
            {
                "href": "https:\/\/contratame.online\/en\/wp-json\/wp\/v2\/candidate"
            }
        ],
        "about": [
            {
                "href": "https:\/\/contratame.online\/en\/wp-json\/wp\/v2\/types\/candidate"
            }
        ],
        "replies": [
            {
                "embeddable": true,
                "href": "https:\/\/contratame.online\/en\/wp-json\/wp\/v2\/comments?post=79873"
            }
        ],
        "version-history": [
            {
                "count": 1,
                "href": "https:\/\/contratame.online\/en\/wp-json\/wp\/v2\/candidate\/79873\/revisions"
            }
        ],
        "predecessor-version": [
            {
                "id": 79874,
                "href": "https:\/\/contratame.online\/en\/wp-json\/wp\/v2\/candidate\/79873\/revisions\/79874"
            }
        ],
        "wp:featuredmedia": [
            {
                "embeddable": true,
                "href": "https:\/\/contratame.online\/en\/wp-json\/wp\/v2\/media\/79880"
            }
        ],
        "wp:attachment": [
            {
                "href": "https:\/\/contratame.online\/en\/wp-json\/wp\/v2\/media?parent=79873"
            }
        ],
        "wp:term": [
            {
                "taxonomy": "candidate_category",
                "embeddable": true,
                "href": "https:\/\/contratame.online\/en\/wp-json\/wp\/v2\/candidate_category?post=79873"
            },
            {
                "taxonomy": "candidate_location",
                "embeddable": true,
                "href": "https:\/\/contratame.online\/en\/wp-json\/wp\/v2\/candidate_location?post=79873"
            },
            {
                "taxonomy": "candidate_tag",
                "embeddable": true,
                "href": "https:\/\/contratame.online\/en\/wp-json\/wp\/v2\/candidate_tag?post=79873"
            }
        ],
        "curies": [
            {
                "name": "wp",
                "href": "https:\/\/api.w.org\/{rel}",
                "templated": true
            }
        ]
    }
}