{
    "id": 80448,
    "date": "2026-08-12T07:49:54",
    "date_gmt": "2026-08-12T13:49:54",
    "guid": {
        "rendered": "https:\/\/contratame.online\/es\/candidate\/m-janeth-rodriguez2004\/"
    },
    "modified": "2026-08-12T08:28:22",
    "modified_gmt": "2026-08-12T14:28:22",
    "slug": "m-janeth-rodriguez2004",
    "status": "publish",
    "type": "candidate",
    "link": "https:\/\/contratame.online\/en\/candidate\/m-janeth-rodriguez2004\/",
    "title": {
        "rendered": "m.janeth.rodriguez2004"
    },
    "content": {
        "rendered": "<p>Trabaje temporalmente en Atento en atenci\u00f3n al cliente y 2 a\u00f1os trabaje en Allied Global como asesor telef\u00f3nico en el \u00e1rea de telemarketing, ahi estaba encargado en la colocaci\u00f3n de tarjetas de cr\u00e9dito de Banrural<\/p>",
        "protected": false
    },
    "featured_media": 0,
    "comment_status": "open",
    "ping_status": "closed",
    "template": "",
    "candidate_category": [
        281
    ],
    "candidate_location": [
        167
    ],
    "candidate_tag": [],
    "class_list": [
        "post-80448",
        "candidate",
        "type-candidate",
        "status-publish",
        "hentry",
        "candidate_category-finanzas",
        "candidate_location-guatemala"
    ],
    "yoast_head": "<!-- This site is optimized with the Yoast SEO plugin v24.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>m.janeth.rodriguez2004 - Contratame.online<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"m.janeth.rodriguez2004 - Contratame.online\" \/>\n<meta property=\"og:description\" content=\"Trabaje temporalmente en Atento en atenci\u00f3n al cliente y 2 a\u00f1os trabaje en Allied Global como asesor telef\u00f3nico en el \u00e1rea de telemarketing, ahi estaba encargado en la colocaci\u00f3n de tarjetas de cr\u00e9dito de Banrural\" \/>\n<meta property=\"og:url\" content=\"https:\/\/contratame.online\/en\/candidate\/m-janeth-rodriguez2004\/\" \/>\n<meta property=\"og:site_name\" content=\"Contratame.online\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/contratamegt\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-12T14:28:22+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/contratame.online\/es\/candidate\/m-janeth-rodriguez2004\/\",\"url\":\"https:\/\/contratame.online\/es\/candidate\/m-janeth-rodriguez2004\/\",\"name\":\"m.janeth.rodriguez2004 - Contratame.online\",\"isPartOf\":{\"@id\":\"https:\/\/contratame.online\/#website\"},\"datePublished\":\"2026-08-12T13:49:54+00:00\",\"dateModified\":\"2026-08-12T14:28:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/contratame.online\/es\/candidate\/m-janeth-rodriguez2004\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/contratame.online\/es\/candidate\/m-janeth-rodriguez2004\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/contratame.online\/es\/candidate\/m-janeth-rodriguez2004\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/contratame.online\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Candidates\",\"item\":\"https:\/\/contratame.online\/en\/candidate\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"m.janeth.rodriguez2004\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/contratame.online\/#website\",\"url\":\"https:\/\/contratame.online\/\",\"name\":\"Contratame.online\",\"description\":\"Encuentra el empleo que siempre so\u00f1aste.\",\"publisher\":{\"@id\":\"https:\/\/contratame.online\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/contratame.online\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/contratame.online\/#organization\",\"name\":\"CONTRATA ME\",\"url\":\"https:\/\/contratame.online\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/contratame.online\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/contratame.online\/wp-content\/uploads\/2023\/07\/logohd.png\",\"contentUrl\":\"https:\/\/contratame.online\/wp-content\/uploads\/2023\/07\/logohd.png\",\"width\":150,\"height\":50,\"caption\":\"CONTRATA ME\"},\"image\":{\"@id\":\"https:\/\/contratame.online\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/contratamegt\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->",
    "yoast_head_json": {
        "title": "m.janeth.rodriguez2004 - Contratame.online",
        "robots": {
            "index": "noindex",
            "follow": "follow"
        },
        "og_locale": "en_US",
        "og_type": "article",
        "og_title": "m.janeth.rodriguez2004 - Contratame.online",
        "og_description": "Trabaje temporalmente en Atento en atenci\u00f3n al cliente y 2 a\u00f1os trabaje en Allied Global como asesor telef\u00f3nico en el \u00e1rea de telemarketing, ahi estaba encargado en la colocaci\u00f3n de tarjetas de cr\u00e9dito de Banrural",
        "og_url": "https:\/\/contratame.online\/en\/candidate\/m-janeth-rodriguez2004\/",
        "og_site_name": "Contratame.online",
        "article_publisher": "https:\/\/www.facebook.com\/contratamegt",
        "article_modified_time": "2026-08-12T14:28:22+00:00",
        "twitter_card": "summary_large_image",
        "schema": {
            "@context": "https:\/\/schema.org",
            "@graph": [
                {
                    "@type": "WebPage",
                    "@id": "https:\/\/contratame.online\/es\/candidate\/m-janeth-rodriguez2004\/",
                    "url": "https:\/\/contratame.online\/es\/candidate\/m-janeth-rodriguez2004\/",
                    "name": "m.janeth.rodriguez2004 - Contratame.online",
                    "isPartOf": {
                        "@id": "https:\/\/contratame.online\/#website"
                    },
                    "datePublished": "2026-08-12T13:49:54+00:00",
                    "dateModified": "2026-08-12T14:28:22+00:00",
                    "breadcrumb": {
                        "@id": "https:\/\/contratame.online\/es\/candidate\/m-janeth-rodriguez2004\/#breadcrumb"
                    },
                    "inLanguage": "en-US",
                    "potentialAction": [
                        {
                            "@type": "ReadAction",
                            "target": [
                                "https:\/\/contratame.online\/es\/candidate\/m-janeth-rodriguez2004\/"
                            ]
                        }
                    ]
                },
                {
                    "@type": "BreadcrumbList",
                    "@id": "https:\/\/contratame.online\/es\/candidate\/m-janeth-rodriguez2004\/#breadcrumb",
                    "itemListElement": [
                        {
                            "@type": "ListItem",
                            "position": 1,
                            "name": "Portada",
                            "item": "https:\/\/contratame.online\/"
                        },
                        {
                            "@type": "ListItem",
                            "position": 2,
                            "name": "Candidates",
                            "item": "https:\/\/contratame.online\/en\/candidate\/"
                        },
                        {
                            "@type": "ListItem",
                            "position": 3,
                            "name": "m.janeth.rodriguez2004"
                        }
                    ]
                },
                {
                    "@type": "WebSite",
                    "@id": "https:\/\/contratame.online\/#website",
                    "url": "https:\/\/contratame.online\/",
                    "name": "Contratame.online",
                    "description": "Encuentra el empleo que siempre so\u00f1aste.",
                    "publisher": {
                        "@id": "https:\/\/contratame.online\/#organization"
                    },
                    "potentialAction": [
                        {
                            "@type": "SearchAction",
                            "target": {
                                "@type": "EntryPoint",
                                "urlTemplate": "https:\/\/contratame.online\/?s={search_term_string}"
                            },
                            "query-input": {
                                "@type": "PropertyValueSpecification",
                                "valueRequired": true,
                                "valueName": "search_term_string"
                            }
                        }
                    ],
                    "inLanguage": "en-US"
                },
                {
                    "@type": "Organization",
                    "@id": "https:\/\/contratame.online\/#organization",
                    "name": "CONTRATA ME",
                    "url": "https:\/\/contratame.online\/",
                    "logo": {
                        "@type": "ImageObject",
                        "inLanguage": "en-US",
                        "@id": "https:\/\/contratame.online\/#\/schema\/logo\/image\/",
                        "url": "https:\/\/contratame.online\/wp-content\/uploads\/2023\/07\/logohd.png",
                        "contentUrl": "https:\/\/contratame.online\/wp-content\/uploads\/2023\/07\/logohd.png",
                        "width": 150,
                        "height": 50,
                        "caption": "CONTRATA ME"
                    },
                    "image": {
                        "@id": "https:\/\/contratame.online\/#\/schema\/logo\/image\/"
                    },
                    "sameAs": [
                        "https:\/\/www.facebook.com\/contratamegt"
                    ]
                }
            ]
        }
    },
    "metas": {
        "_candidate_location": {
            "167": "Guatemala"
        },
        "_candidate_age": "21",
        "_candidate_gender": "Femenino",
        "_candidate_phone": "55915173",
        "_candidate_email": "m.janeth.rodriguez2004@gmail.com",
        "_candidate_qualification": "Diversificado",
        "_candidate_job_title": "Asesora telef\u00f3nica",
        "_candidate_experience_time": "2 A\u00f1os",
        "_candidate_salary": "",
        "_candidate_languages": [
            "Espa\u00f1ol"
        ],
        "_candidate_skill": "",
        "_candidate_category": {
            "281": "Finanzas"
        },
        "_candidate_cv_attachment": {
            "80450": "https:\/\/contratame.online\/wp-content\/uploads\/2026\/08\/Curriculum-vitae-Mirna-Rodriguez.pdf"
        },
        "_candidate_education": "",
        "_candidate_experience": ""
    },
    "_links": {
        "self": [
            {
                "href": "https:\/\/contratame.online\/en\/wp-json\/wp\/v2\/candidate\/80448",
                "targetHints": {
                    "allow": [
                        "GET"
                    ]
                }
            }
        ],
        "collection": [
            {
                "href": "https:\/\/contratame.online\/en\/wp-json\/wp\/v2\/candidate"
            }
        ],
        "about": [
            {
                "href": "https:\/\/contratame.online\/en\/wp-json\/wp\/v2\/types\/candidate"
            }
        ],
        "replies": [
            {
                "embeddable": true,
                "href": "https:\/\/contratame.online\/en\/wp-json\/wp\/v2\/comments?post=80448"
            }
        ],
        "version-history": [
            {
                "count": 1,
                "href": "https:\/\/contratame.online\/en\/wp-json\/wp\/v2\/candidate\/80448\/revisions"
            }
        ],
        "predecessor-version": [
            {
                "id": 80449,
                "href": "https:\/\/contratame.online\/en\/wp-json\/wp\/v2\/candidate\/80448\/revisions\/80449"
            }
        ],
        "wp:attachment": [
            {
                "href": "https:\/\/contratame.online\/en\/wp-json\/wp\/v2\/media?parent=80448"
            }
        ],
        "wp:term": [
            {
                "taxonomy": "candidate_category",
                "embeddable": true,
                "href": "https:\/\/contratame.online\/en\/wp-json\/wp\/v2\/candidate_category?post=80448"
            },
            {
                "taxonomy": "candidate_location",
                "embeddable": true,
                "href": "https:\/\/contratame.online\/en\/wp-json\/wp\/v2\/candidate_location?post=80448"
            },
            {
                "taxonomy": "candidate_tag",
                "embeddable": true,
                "href": "https:\/\/contratame.online\/en\/wp-json\/wp\/v2\/candidate_tag?post=80448"
            }
        ],
        "curies": [
            {
                "name": "wp",
                "href": "https:\/\/api.w.org\/{rel}",
                "templated": true
            }
        ]
    }
}