{
    "id": 80634,
    "date": "2026-08-12T09:26:34",
    "date_gmt": "2026-08-12T15:26:34",
    "guid": {
        "rendered": "https:\/\/contratame.online\/es\/candidate\/aguidsa28\/"
    },
    "modified": "2026-08-12T09:31:45",
    "modified_gmt": "2026-08-12T15:31:45",
    "slug": "aguidsa28",
    "status": "publish",
    "type": "candidate",
    "link": "https:\/\/contratame.online\/en\/candidate\/aguidsa28\/",
    "title": {
        "rendered": "aguidsa28"
    },
    "content": {
        "rendered": "<p>Profesional en Recursos Humanos con m\u00e1s de 5 a\u00f1os de experiencia en gesti\u00f3n de personal, procesos administrativos y atenci\u00f3n al cliente. Me he destacado por mi organizaci\u00f3n, responsabilidad, liderazgo y capacidad para trabajar en equipo. Cuento con experiencia en reclutamiento y selecci\u00f3n, contrataci\u00f3n de personal, administraci\u00f3n de expedientes, control de vacaciones y permisos, supervisi\u00f3n operativa y coordinaci\u00f3n de equipos de trabajo. Me caracterizo por mi compromiso, proactividad y orientaci\u00f3n a resultados, buscando siempre optimizar los procesos y contribuir al buen funcionamiento de la organizaci\u00f3n.<\/p>",
        "protected": false
    },
    "featured_media": 80644,
    "comment_status": "open",
    "ping_status": "closed",
    "template": "",
    "candidate_category": [
        281
    ],
    "candidate_location": [
        167
    ],
    "candidate_tag": [],
    "class_list": [
        "post-80634",
        "candidate",
        "type-candidate",
        "status-publish",
        "has-post-thumbnail",
        "hentry",
        "candidate_category-finanzas",
        "candidate_location-guatemala"
    ],
    "yoast_head": "<!-- This site is optimized with the Yoast SEO plugin v24.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>aguidsa28 - Contratame.online<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"aguidsa28 - Contratame.online\" \/>\n<meta property=\"og:description\" content=\"Profesional en Recursos Humanos con m\u00e1s de 5 a\u00f1os de experiencia en gesti\u00f3n de personal, procesos administrativos y atenci\u00f3n al cliente. Me he destacado por mi organizaci\u00f3n, responsabilidad, liderazgo y capacidad para trabajar en equipo. Cuento con experiencia en reclutamiento y selecci\u00f3n, contrataci\u00f3n de personal, administraci\u00f3n de expedientes, control de vacaciones y permisos, supervisi\u00f3n operativa [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/contratame.online\/en\/candidate\/aguidsa28\/\" \/>\n<meta property=\"og:site_name\" content=\"Contratame.online\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/contratamegt\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-12T15:31:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/contratame.online\/wp-content\/uploads\/wp-job-board-pro-uploads\/_candidate_featured_image\/2026\/08\/IMG_6734.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"704\" \/>\n\t<meta property=\"og:image:height\" content=\"902\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/contratame.online\/es\/candidate\/aguidsa28\/\",\"url\":\"https:\/\/contratame.online\/es\/candidate\/aguidsa28\/\",\"name\":\"aguidsa28 - Contratame.online\",\"isPartOf\":{\"@id\":\"https:\/\/contratame.online\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/contratame.online\/es\/candidate\/aguidsa28\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/contratame.online\/es\/candidate\/aguidsa28\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/contratame.online\/wp-content\/uploads\/wp-job-board-pro-uploads\/_candidate_featured_image\/2026\/08\/IMG_6734.jpeg\",\"datePublished\":\"2026-08-12T15:26:34+00:00\",\"dateModified\":\"2026-08-12T15:31:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/contratame.online\/es\/candidate\/aguidsa28\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/contratame.online\/es\/candidate\/aguidsa28\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/contratame.online\/es\/candidate\/aguidsa28\/#primaryimage\",\"url\":\"https:\/\/contratame.online\/wp-content\/uploads\/wp-job-board-pro-uploads\/_candidate_featured_image\/2026\/08\/IMG_6734.jpeg\",\"contentUrl\":\"https:\/\/contratame.online\/wp-content\/uploads\/wp-job-board-pro-uploads\/_candidate_featured_image\/2026\/08\/IMG_6734.jpeg\",\"width\":704,\"height\":902},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/contratame.online\/es\/candidate\/aguidsa28\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/contratame.online\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Candidates\",\"item\":\"https:\/\/contratame.online\/en\/candidate\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"aguidsa28\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/contratame.online\/#website\",\"url\":\"https:\/\/contratame.online\/\",\"name\":\"Contratame.online\",\"description\":\"Encuentra el empleo que siempre so\u00f1aste.\",\"publisher\":{\"@id\":\"https:\/\/contratame.online\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/contratame.online\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/contratame.online\/#organization\",\"name\":\"CONTRATA ME\",\"url\":\"https:\/\/contratame.online\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/contratame.online\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/contratame.online\/wp-content\/uploads\/2023\/07\/logohd.png\",\"contentUrl\":\"https:\/\/contratame.online\/wp-content\/uploads\/2023\/07\/logohd.png\",\"width\":150,\"height\":50,\"caption\":\"CONTRATA ME\"},\"image\":{\"@id\":\"https:\/\/contratame.online\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/contratamegt\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->",
    "yoast_head_json": {
        "title": "aguidsa28 - Contratame.online",
        "robots": {
            "index": "noindex",
            "follow": "follow"
        },
        "og_locale": "en_US",
        "og_type": "article",
        "og_title": "aguidsa28 - Contratame.online",
        "og_description": "Profesional en Recursos Humanos con m\u00e1s de 5 a\u00f1os de experiencia en gesti\u00f3n de personal, procesos administrativos y atenci\u00f3n al cliente. Me he destacado por mi organizaci\u00f3n, responsabilidad, liderazgo y capacidad para trabajar en equipo. Cuento con experiencia en reclutamiento y selecci\u00f3n, contrataci\u00f3n de personal, administraci\u00f3n de expedientes, control de vacaciones y permisos, supervisi\u00f3n operativa [&hellip;]",
        "og_url": "https:\/\/contratame.online\/en\/candidate\/aguidsa28\/",
        "og_site_name": "Contratame.online",
        "article_publisher": "https:\/\/www.facebook.com\/contratamegt",
        "article_modified_time": "2026-08-12T15:31:45+00:00",
        "og_image": [
            {
                "width": 704,
                "height": 902,
                "url": "https:\/\/contratame.online\/wp-content\/uploads\/wp-job-board-pro-uploads\/_candidate_featured_image\/2026\/08\/IMG_6734.jpeg",
                "type": "image\/jpeg"
            }
        ],
        "twitter_card": "summary_large_image",
        "schema": {
            "@context": "https:\/\/schema.org",
            "@graph": [
                {
                    "@type": "WebPage",
                    "@id": "https:\/\/contratame.online\/es\/candidate\/aguidsa28\/",
                    "url": "https:\/\/contratame.online\/es\/candidate\/aguidsa28\/",
                    "name": "aguidsa28 - Contratame.online",
                    "isPartOf": {
                        "@id": "https:\/\/contratame.online\/#website"
                    },
                    "primaryImageOfPage": {
                        "@id": "https:\/\/contratame.online\/es\/candidate\/aguidsa28\/#primaryimage"
                    },
                    "image": {
                        "@id": "https:\/\/contratame.online\/es\/candidate\/aguidsa28\/#primaryimage"
                    },
                    "thumbnailUrl": "https:\/\/contratame.online\/wp-content\/uploads\/wp-job-board-pro-uploads\/_candidate_featured_image\/2026\/08\/IMG_6734.jpeg",
                    "datePublished": "2026-08-12T15:26:34+00:00",
                    "dateModified": "2026-08-12T15:31:45+00:00",
                    "breadcrumb": {
                        "@id": "https:\/\/contratame.online\/es\/candidate\/aguidsa28\/#breadcrumb"
                    },
                    "inLanguage": "en-US",
                    "potentialAction": [
                        {
                            "@type": "ReadAction",
                            "target": [
                                "https:\/\/contratame.online\/es\/candidate\/aguidsa28\/"
                            ]
                        }
                    ]
                },
                {
                    "@type": "ImageObject",
                    "inLanguage": "en-US",
                    "@id": "https:\/\/contratame.online\/es\/candidate\/aguidsa28\/#primaryimage",
                    "url": "https:\/\/contratame.online\/wp-content\/uploads\/wp-job-board-pro-uploads\/_candidate_featured_image\/2026\/08\/IMG_6734.jpeg",
                    "contentUrl": "https:\/\/contratame.online\/wp-content\/uploads\/wp-job-board-pro-uploads\/_candidate_featured_image\/2026\/08\/IMG_6734.jpeg",
                    "width": 704,
                    "height": 902
                },
                {
                    "@type": "BreadcrumbList",
                    "@id": "https:\/\/contratame.online\/es\/candidate\/aguidsa28\/#breadcrumb",
                    "itemListElement": [
                        {
                            "@type": "ListItem",
                            "position": 1,
                            "name": "Portada",
                            "item": "https:\/\/contratame.online\/"
                        },
                        {
                            "@type": "ListItem",
                            "position": 2,
                            "name": "Candidates",
                            "item": "https:\/\/contratame.online\/en\/candidate\/"
                        },
                        {
                            "@type": "ListItem",
                            "position": 3,
                            "name": "aguidsa28"
                        }
                    ]
                },
                {
                    "@type": "WebSite",
                    "@id": "https:\/\/contratame.online\/#website",
                    "url": "https:\/\/contratame.online\/",
                    "name": "Contratame.online",
                    "description": "Encuentra el empleo que siempre so\u00f1aste.",
                    "publisher": {
                        "@id": "https:\/\/contratame.online\/#organization"
                    },
                    "potentialAction": [
                        {
                            "@type": "SearchAction",
                            "target": {
                                "@type": "EntryPoint",
                                "urlTemplate": "https:\/\/contratame.online\/?s={search_term_string}"
                            },
                            "query-input": {
                                "@type": "PropertyValueSpecification",
                                "valueRequired": true,
                                "valueName": "search_term_string"
                            }
                        }
                    ],
                    "inLanguage": "en-US"
                },
                {
                    "@type": "Organization",
                    "@id": "https:\/\/contratame.online\/#organization",
                    "name": "CONTRATA ME",
                    "url": "https:\/\/contratame.online\/",
                    "logo": {
                        "@type": "ImageObject",
                        "inLanguage": "en-US",
                        "@id": "https:\/\/contratame.online\/#\/schema\/logo\/image\/",
                        "url": "https:\/\/contratame.online\/wp-content\/uploads\/2023\/07\/logohd.png",
                        "contentUrl": "https:\/\/contratame.online\/wp-content\/uploads\/2023\/07\/logohd.png",
                        "width": 150,
                        "height": 50,
                        "caption": "CONTRATA ME"
                    },
                    "image": {
                        "@id": "https:\/\/contratame.online\/#\/schema\/logo\/image\/"
                    },
                    "sameAs": [
                        "https:\/\/www.facebook.com\/contratamegt"
                    ]
                }
            ]
        }
    },
    "metas": {
        "_candidate_location": {
            "167": "Guatemala"
        },
        "_candidate_age": "25",
        "_candidate_gender": "Femenino",
        "_candidate_phone": "54427243",
        "_candidate_email": "Aguidsa28@gmail.com",
        "_candidate_qualification": "Licenciatura",
        "_candidate_job_title": "Licenciada en Tecnolog\u00eda y Administraci\u00f3n y Desarrollo de Recursos Humanos.",
        "_candidate_experience_time": "5 A\u00f1os",
        "_candidate_salary": "",
        "_candidate_languages": [
            "Espa\u00f1ol"
        ],
        "_candidate_skill": "",
        "_candidate_category": {
            "281": "Finanzas"
        },
        "_candidate_cv_attachment": {
            "80636": "https:\/\/contratame.online\/wp-content\/uploads\/2026\/08\/CV_Debora_Aguirre.pdf"
        },
        "_candidate_education": "",
        "_candidate_experience": "",
        "_candidate_logo": "https:\/\/contratame.online\/wp-content\/uploads\/wp-job-board-pro-uploads\/_candidate_featured_image\/2026\/08\/IMG_6734-150x150.jpeg"
    },
    "_links": {
        "self": [
            {
                "href": "https:\/\/contratame.online\/en\/wp-json\/wp\/v2\/candidate\/80634",
                "targetHints": {
                    "allow": [
                        "GET"
                    ]
                }
            }
        ],
        "collection": [
            {
                "href": "https:\/\/contratame.online\/en\/wp-json\/wp\/v2\/candidate"
            }
        ],
        "about": [
            {
                "href": "https:\/\/contratame.online\/en\/wp-json\/wp\/v2\/types\/candidate"
            }
        ],
        "replies": [
            {
                "embeddable": true,
                "href": "https:\/\/contratame.online\/en\/wp-json\/wp\/v2\/comments?post=80634"
            }
        ],
        "version-history": [
            {
                "count": 1,
                "href": "https:\/\/contratame.online\/en\/wp-json\/wp\/v2\/candidate\/80634\/revisions"
            }
        ],
        "predecessor-version": [
            {
                "id": 80635,
                "href": "https:\/\/contratame.online\/en\/wp-json\/wp\/v2\/candidate\/80634\/revisions\/80635"
            }
        ],
        "wp:featuredmedia": [
            {
                "embeddable": true,
                "href": "https:\/\/contratame.online\/en\/wp-json\/wp\/v2\/media\/80644"
            }
        ],
        "wp:attachment": [
            {
                "href": "https:\/\/contratame.online\/en\/wp-json\/wp\/v2\/media?parent=80634"
            }
        ],
        "wp:term": [
            {
                "taxonomy": "candidate_category",
                "embeddable": true,
                "href": "https:\/\/contratame.online\/en\/wp-json\/wp\/v2\/candidate_category?post=80634"
            },
            {
                "taxonomy": "candidate_location",
                "embeddable": true,
                "href": "https:\/\/contratame.online\/en\/wp-json\/wp\/v2\/candidate_location?post=80634"
            },
            {
                "taxonomy": "candidate_tag",
                "embeddable": true,
                "href": "https:\/\/contratame.online\/en\/wp-json\/wp\/v2\/candidate_tag?post=80634"
            }
        ],
        "curies": [
            {
                "name": "wp",
                "href": "https:\/\/api.w.org\/{rel}",
                "templated": true
            }
        ]
    }
}