{"id":10145,"date":"2024-07-25T09:54:22","date_gmt":"2024-07-25T15:54:22","guid":{"rendered":"https:\/\/contratame.online\/candidate\/acusindi\/"},"modified":"2024-07-25T09:54:22","modified_gmt":"2024-07-25T15:54:22","slug":"acusindi","status":"publish","type":"candidate","link":"https:\/\/contratame.online\/es\/candidate\/acusindi\/","title":{"rendered":"acusindi"},"content":{"rendered":"","protected":false},"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","candidate_category":[],"candidate_location":[],"candidate_tag":[],"class_list":["post-10145","candidate","type-candidate","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>acusindi - Contratame.online<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/contratame.online\/es\/candidate\/acusindi\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"acusindi - Contratame.online\" \/>\n<meta property=\"og:url\" content=\"https:\/\/contratame.online\/es\/candidate\/acusindi\/\" \/>\n<meta property=\"og:site_name\" content=\"Contratame.online\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/contratamegt\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/contratame.online\/candidate\/acusindi\/\",\"url\":\"https:\/\/contratame.online\/candidate\/acusindi\/\",\"name\":\"acusindi - Contratame.online\",\"isPartOf\":{\"@id\":\"https:\/\/contratame.online\/#website\"},\"datePublished\":\"2024-07-25T15:54:22+00:00\",\"dateModified\":\"2024-07-25T15:54:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/contratame.online\/candidate\/acusindi\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/contratame.online\/candidate\/acusindi\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/contratame.online\/candidate\/acusindi\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/contratame.online\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Candidates\",\"item\":\"https:\/\/contratame.online\/en\/candidate\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"acusindi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/contratame.online\/#website\",\"url\":\"https:\/\/contratame.online\/\",\"name\":\"Contratame.online\",\"description\":\"Encuentra el empleo que siempre so\u00f1aste.\",\"publisher\":{\"@id\":\"https:\/\/contratame.online\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/contratame.online\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/contratame.online\/#organization\",\"name\":\"CONTRATA ME\",\"url\":\"https:\/\/contratame.online\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/contratame.online\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/contratame.online\/wp-content\/uploads\/2023\/07\/logohd.png\",\"contentUrl\":\"https:\/\/contratame.online\/wp-content\/uploads\/2023\/07\/logohd.png\",\"width\":150,\"height\":50,\"caption\":\"CONTRATA ME\"},\"image\":{\"@id\":\"https:\/\/contratame.online\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/contratamegt\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"acusindi - Contratame.online","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/contratame.online\/es\/candidate\/acusindi\/","og_locale":"es_ES","og_type":"article","og_title":"acusindi - Contratame.online","og_url":"https:\/\/contratame.online\/es\/candidate\/acusindi\/","og_site_name":"Contratame.online","article_publisher":"https:\/\/www.facebook.com\/contratamegt","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/contratame.online\/candidate\/acusindi\/","url":"https:\/\/contratame.online\/candidate\/acusindi\/","name":"acusindi - Contratame.online","isPartOf":{"@id":"https:\/\/contratame.online\/#website"},"datePublished":"2024-07-25T15:54:22+00:00","dateModified":"2024-07-25T15:54:22+00:00","breadcrumb":{"@id":"https:\/\/contratame.online\/candidate\/acusindi\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/contratame.online\/candidate\/acusindi\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/contratame.online\/candidate\/acusindi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/contratame.online\/"},{"@type":"ListItem","position":2,"name":"Candidates","item":"https:\/\/contratame.online\/en\/candidate\/"},{"@type":"ListItem","position":3,"name":"acusindi"}]},{"@type":"WebSite","@id":"https:\/\/contratame.online\/#website","url":"https:\/\/contratame.online\/","name":"Contratame.online","description":"Encuentra el empleo que siempre so\u00f1aste.","publisher":{"@id":"https:\/\/contratame.online\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/contratame.online\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/contratame.online\/#organization","name":"CONTRATA ME","url":"https:\/\/contratame.online\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/contratame.online\/#\/schema\/logo\/image\/","url":"https:\/\/contratame.online\/wp-content\/uploads\/2023\/07\/logohd.png","contentUrl":"https:\/\/contratame.online\/wp-content\/uploads\/2023\/07\/logohd.png","width":150,"height":50,"caption":"CONTRATA ME"},"image":{"@id":"https:\/\/contratame.online\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/contratamegt"]}]}},"metas":{"_candidate_location":[],"_candidate_age":"","_candidate_gender":"","_candidate_phone":"","_candidate_email":"acusindi@gmail.com","_candidate_qualification":"","_candidate_job_title":"","_candidate_experience_time":"","_candidate_salary":"","_candidate_languages":"","_candidate_skill":"","_candidate_category":[],"_candidate_cv_attachment":{"10146":"https:\/\/contratame.online\/wp-content\/uploads\/2024\/07\/CURRICULUM-SINDI-VIVIANA-CHIQUIEJ-ACU.pdf"},"_candidate_education":"","_candidate_experience":""},"_links":{"self":[{"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/candidate\/10145","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/candidate"}],"about":[{"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/types\/candidate"}],"replies":[{"embeddable":true,"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/comments?post=10145"}],"version-history":[{"count":0,"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/candidate\/10145\/revisions"}],"wp:attachment":[{"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/media?parent=10145"}],"wp:term":[{"taxonomy":"candidate_category","embeddable":true,"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/candidate_category?post=10145"},{"taxonomy":"candidate_location","embeddable":true,"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/candidate_location?post=10145"},{"taxonomy":"candidate_tag","embeddable":true,"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/candidate_tag?post=10145"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}