{"id":10219,"date":"2024-07-25T10:12:06","date_gmt":"2024-07-25T16:12:06","guid":{"rendered":"https:\/\/contratame.online\/candidate\/nahochonay12\/"},"modified":"2024-07-25T10:24:53","modified_gmt":"2024-07-25T16:24:53","slug":"nahochonay12","status":"publish","type":"candidate","link":"https:\/\/contratame.online\/es\/candidate\/nahochonay12\/","title":{"rendered":"Nahomy Hern\u00e1ndez"},"content":{"rendered":"<p>Servicio al cliente<\/p>\n","protected":false},"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","candidate_category":[],"candidate_location":[],"candidate_tag":[],"class_list":["post-10219","candidate","type-candidate","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Nahomy Hern\u00e1ndez - Contratame.online<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/contratame.online\/es\/candidate\/nahochonay12\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nahomy Hern\u00e1ndez - Contratame.online\" \/>\n<meta property=\"og:description\" content=\"Servicio al cliente\" \/>\n<meta property=\"og:url\" content=\"https:\/\/contratame.online\/es\/candidate\/nahochonay12\/\" \/>\n<meta property=\"og:site_name\" content=\"Contratame.online\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/contratamegt\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-25T16:24:53+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/contratame.online\/candidate\/nahochonay12\/\",\"url\":\"https:\/\/contratame.online\/candidate\/nahochonay12\/\",\"name\":\"Nahomy Hern\u00e1ndez - Contratame.online\",\"isPartOf\":{\"@id\":\"https:\/\/contratame.online\/#website\"},\"datePublished\":\"2024-07-25T16:12:06+00:00\",\"dateModified\":\"2024-07-25T16:24:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/contratame.online\/candidate\/nahochonay12\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/contratame.online\/candidate\/nahochonay12\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/contratame.online\/candidate\/nahochonay12\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/contratame.online\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Candidates\",\"item\":\"https:\/\/contratame.online\/en\/candidate\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Nahomy Hern\u00e1ndez\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/contratame.online\/#website\",\"url\":\"https:\/\/contratame.online\/\",\"name\":\"Contratame.online\",\"description\":\"Encuentra el empleo que siempre so\u00f1aste.\",\"publisher\":{\"@id\":\"https:\/\/contratame.online\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/contratame.online\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/contratame.online\/#organization\",\"name\":\"CONTRATA ME\",\"url\":\"https:\/\/contratame.online\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/contratame.online\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/contratame.online\/wp-content\/uploads\/2023\/07\/logohd.png\",\"contentUrl\":\"https:\/\/contratame.online\/wp-content\/uploads\/2023\/07\/logohd.png\",\"width\":150,\"height\":50,\"caption\":\"CONTRATA ME\"},\"image\":{\"@id\":\"https:\/\/contratame.online\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/contratamegt\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nahomy Hern\u00e1ndez - Contratame.online","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/contratame.online\/es\/candidate\/nahochonay12\/","og_locale":"es_ES","og_type":"article","og_title":"Nahomy Hern\u00e1ndez - Contratame.online","og_description":"Servicio al cliente","og_url":"https:\/\/contratame.online\/es\/candidate\/nahochonay12\/","og_site_name":"Contratame.online","article_publisher":"https:\/\/www.facebook.com\/contratamegt","article_modified_time":"2024-07-25T16:24:53+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/contratame.online\/candidate\/nahochonay12\/","url":"https:\/\/contratame.online\/candidate\/nahochonay12\/","name":"Nahomy Hern\u00e1ndez - Contratame.online","isPartOf":{"@id":"https:\/\/contratame.online\/#website"},"datePublished":"2024-07-25T16:12:06+00:00","dateModified":"2024-07-25T16:24:53+00:00","breadcrumb":{"@id":"https:\/\/contratame.online\/candidate\/nahochonay12\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/contratame.online\/candidate\/nahochonay12\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/contratame.online\/candidate\/nahochonay12\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/contratame.online\/"},{"@type":"ListItem","position":2,"name":"Candidates","item":"https:\/\/contratame.online\/en\/candidate\/"},{"@type":"ListItem","position":3,"name":"Nahomy Hern\u00e1ndez"}]},{"@type":"WebSite","@id":"https:\/\/contratame.online\/#website","url":"https:\/\/contratame.online\/","name":"Contratame.online","description":"Encuentra el empleo que siempre so\u00f1aste.","publisher":{"@id":"https:\/\/contratame.online\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/contratame.online\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/contratame.online\/#organization","name":"CONTRATA ME","url":"https:\/\/contratame.online\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/contratame.online\/#\/schema\/logo\/image\/","url":"https:\/\/contratame.online\/wp-content\/uploads\/2023\/07\/logohd.png","contentUrl":"https:\/\/contratame.online\/wp-content\/uploads\/2023\/07\/logohd.png","width":150,"height":50,"caption":"CONTRATA ME"},"image":{"@id":"https:\/\/contratame.online\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/contratamegt"]}]}},"metas":{"_candidate_location":[],"_candidate_age":"24","_candidate_gender":"Femenino","_candidate_phone":"55662014","_candidate_email":"Nahochonay12@gmail.com","_candidate_qualification":"Diversificado","_candidate_job_title":"Ninguno","_candidate_experience_time":"","_candidate_salary":"","_candidate_languages":["Espa\u00f1ol"],"_candidate_skill":"","_candidate_category":[],"_candidate_cv_attachment":{"10220":"https:\/\/contratame.online\/wp-content\/uploads\/2024\/07\/Documentos-pdf.pdf"},"_candidate_education":"","_candidate_experience":""},"_links":{"self":[{"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/candidate\/10219","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/candidate"}],"about":[{"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/types\/candidate"}],"replies":[{"embeddable":true,"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/comments?post=10219"}],"version-history":[{"count":0,"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/candidate\/10219\/revisions"}],"wp:attachment":[{"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/media?parent=10219"}],"wp:term":[{"taxonomy":"candidate_category","embeddable":true,"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/candidate_category?post=10219"},{"taxonomy":"candidate_location","embeddable":true,"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/candidate_location?post=10219"},{"taxonomy":"candidate_tag","embeddable":true,"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/candidate_tag?post=10219"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}