{"id":32561,"date":"2026-01-06T10:54:59","date_gmt":"2026-01-06T16:54:59","guid":{"rendered":"https:\/\/contratame.online\/es\/candidate\/libni-jabson\/"},"modified":"2026-01-23T13:53:43","modified_gmt":"2026-01-23T19:53:43","slug":"libni-jabson","status":"publish","type":"candidate","link":"https:\/\/contratame.online\/es\/candidate\/libni-jabson\/","title":{"rendered":"Libni Jabson Donis Osorio"},"content":{"rendered":"<p>Profesional en Tecnolog\u00eda, Telecomunicaciones y Administraci\u00f3n con una trayectoria de m\u00e1s de 25 a\u00f1os liderando proyectos tecnol\u00f3gicos, de infraestructura y administrativos. me he centrado en roles de alta responsabilidad, tales como:<\/p>\n<p><strong>Gerencia de Servicios e Instalaciones<\/strong>: He fungido como Gerente de Instalaciones y Servicios de Oficina, dirigiendo proyectos de infraestructura y optimizando espacios de trabajo.\u00a0 Encargado de la gesti\u00f3n integral de servicios corporativos, incluyendo mantenimiento, log\u00edstica y soporte t\u00e9cnico.<\/p>\n<p><strong>Gesti\u00f3n de Proyectos y Operaciones<\/strong>: Supervisor Senior de Gesti\u00f3n de Proyectos, lidere iniciativas de actualizaci\u00f3n de hardware y migraciones, asegurando la continuidad operativa.<\/p>\n<p><strong>Liderazgo en TI<\/strong>: He ocupado cargos como Jefe de IT y Staff, as\u00ed como Analista de Soporte, especializ\u00e1ndose en la administraci\u00f3n de redes, servidores y bases de datos.<\/p>\n<p><strong>Gesti\u00f3n de Talento<\/strong>: He actuado como Hiring Manager para contrataciones masivas en Guatemala y Jamaica, gestionando accesos y credenciales corporativas.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"featured_media":32564,"comment_status":"open","ping_status":"closed","template":"","candidate_category":[],"candidate_location":[],"candidate_tag":[],"class_list":["post-32561","candidate","type-candidate","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Libni Jabson Donis Osorio - Contratame.online<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Libni Jabson Donis Osorio - Contratame.online\" \/>\n<meta property=\"og:description\" content=\"Profesional en Tecnolog\u00eda, Telecomunicaciones y Administraci\u00f3n con una trayectoria de m\u00e1s de 25 a\u00f1os liderando proyectos tecnol\u00f3gicos, de infraestructura y administrativos. me he centrado en roles de alta responsabilidad, tales como: Gerencia de Servicios e Instalaciones: He fungido como Gerente de Instalaciones y Servicios de Oficina, dirigiendo proyectos de infraestructura y optimizando espacios de trabajo.\u00a0 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/contratame.online\/es\/candidate\/libni-jabson\/\" \/>\n<meta property=\"og:site_name\" content=\"Contratame.online\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/contratamegt\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-23T19:53:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/contratame.online\/wp-content\/uploads\/wp-job-board-pro-uploads\/_candidate_featured_image\/2026\/01\/shared-image.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/contratame.online\/es\/candidate\/libni-jabson\/\",\"url\":\"https:\/\/contratame.online\/es\/candidate\/libni-jabson\/\",\"name\":\"Libni Jabson Donis Osorio - Contratame.online\",\"isPartOf\":{\"@id\":\"https:\/\/contratame.online\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/contratame.online\/es\/candidate\/libni-jabson\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/contratame.online\/es\/candidate\/libni-jabson\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/contratame.online\/wp-content\/uploads\/wp-job-board-pro-uploads\/_candidate_featured_image\/2026\/01\/shared-image.jpg\",\"datePublished\":\"2026-01-06T16:54:59+00:00\",\"dateModified\":\"2026-01-23T19:53:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/contratame.online\/es\/candidate\/libni-jabson\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/contratame.online\/es\/candidate\/libni-jabson\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/contratame.online\/es\/candidate\/libni-jabson\/#primaryimage\",\"url\":\"https:\/\/contratame.online\/wp-content\/uploads\/wp-job-board-pro-uploads\/_candidate_featured_image\/2026\/01\/shared-image.jpg\",\"contentUrl\":\"https:\/\/contratame.online\/wp-content\/uploads\/wp-job-board-pro-uploads\/_candidate_featured_image\/2026\/01\/shared-image.jpg\",\"width\":1200,\"height\":1600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/contratame.online\/es\/candidate\/libni-jabson\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/contratame.online\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Candidates\",\"item\":\"https:\/\/contratame.online\/en\/candidate\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Libni Jabson Donis Osorio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/contratame.online\/#website\",\"url\":\"https:\/\/contratame.online\/\",\"name\":\"Contratame.online\",\"description\":\"Encuentra el empleo que siempre so\u00f1aste.\",\"publisher\":{\"@id\":\"https:\/\/contratame.online\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/contratame.online\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/contratame.online\/#organization\",\"name\":\"CONTRATA ME\",\"url\":\"https:\/\/contratame.online\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/contratame.online\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/contratame.online\/wp-content\/uploads\/2023\/07\/logohd.png\",\"contentUrl\":\"https:\/\/contratame.online\/wp-content\/uploads\/2023\/07\/logohd.png\",\"width\":150,\"height\":50,\"caption\":\"CONTRATA ME\"},\"image\":{\"@id\":\"https:\/\/contratame.online\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/contratamegt\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Libni Jabson Donis Osorio - Contratame.online","robots":{"index":"noindex","follow":"follow"},"og_locale":"es_ES","og_type":"article","og_title":"Libni Jabson Donis Osorio - Contratame.online","og_description":"Profesional en Tecnolog\u00eda, Telecomunicaciones y Administraci\u00f3n con una trayectoria de m\u00e1s de 25 a\u00f1os liderando proyectos tecnol\u00f3gicos, de infraestructura y administrativos. me he centrado en roles de alta responsabilidad, tales como: Gerencia de Servicios e Instalaciones: He fungido como Gerente de Instalaciones y Servicios de Oficina, dirigiendo proyectos de infraestructura y optimizando espacios de trabajo.\u00a0 [&hellip;]","og_url":"https:\/\/contratame.online\/es\/candidate\/libni-jabson\/","og_site_name":"Contratame.online","article_publisher":"https:\/\/www.facebook.com\/contratamegt","article_modified_time":"2026-01-23T19:53:43+00:00","og_image":[{"width":1200,"height":1600,"url":"https:\/\/contratame.online\/wp-content\/uploads\/wp-job-board-pro-uploads\/_candidate_featured_image\/2026\/01\/shared-image.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/contratame.online\/es\/candidate\/libni-jabson\/","url":"https:\/\/contratame.online\/es\/candidate\/libni-jabson\/","name":"Libni Jabson Donis Osorio - Contratame.online","isPartOf":{"@id":"https:\/\/contratame.online\/#website"},"primaryImageOfPage":{"@id":"https:\/\/contratame.online\/es\/candidate\/libni-jabson\/#primaryimage"},"image":{"@id":"https:\/\/contratame.online\/es\/candidate\/libni-jabson\/#primaryimage"},"thumbnailUrl":"https:\/\/contratame.online\/wp-content\/uploads\/wp-job-board-pro-uploads\/_candidate_featured_image\/2026\/01\/shared-image.jpg","datePublished":"2026-01-06T16:54:59+00:00","dateModified":"2026-01-23T19:53:43+00:00","breadcrumb":{"@id":"https:\/\/contratame.online\/es\/candidate\/libni-jabson\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/contratame.online\/es\/candidate\/libni-jabson\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/contratame.online\/es\/candidate\/libni-jabson\/#primaryimage","url":"https:\/\/contratame.online\/wp-content\/uploads\/wp-job-board-pro-uploads\/_candidate_featured_image\/2026\/01\/shared-image.jpg","contentUrl":"https:\/\/contratame.online\/wp-content\/uploads\/wp-job-board-pro-uploads\/_candidate_featured_image\/2026\/01\/shared-image.jpg","width":1200,"height":1600},{"@type":"BreadcrumbList","@id":"https:\/\/contratame.online\/es\/candidate\/libni-jabson\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/contratame.online\/"},{"@type":"ListItem","position":2,"name":"Candidates","item":"https:\/\/contratame.online\/en\/candidate\/"},{"@type":"ListItem","position":3,"name":"Libni Jabson Donis Osorio"}]},{"@type":"WebSite","@id":"https:\/\/contratame.online\/#website","url":"https:\/\/contratame.online\/","name":"Contratame.online","description":"Encuentra el empleo que siempre so\u00f1aste.","publisher":{"@id":"https:\/\/contratame.online\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/contratame.online\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/contratame.online\/#organization","name":"CONTRATA ME","url":"https:\/\/contratame.online\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/contratame.online\/#\/schema\/logo\/image\/","url":"https:\/\/contratame.online\/wp-content\/uploads\/2023\/07\/logohd.png","contentUrl":"https:\/\/contratame.online\/wp-content\/uploads\/2023\/07\/logohd.png","width":150,"height":50,"caption":"CONTRATA ME"},"image":{"@id":"https:\/\/contratame.online\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/contratamegt"]}]}},"metas":{"_candidate_location":[],"_candidate_age":"47","_candidate_gender":"Masculino","_candidate_phone":"35159065","_candidate_email":"libni.jabson@gmail.com","_candidate_qualification":"Licenciatura","_candidate_job_title":"Administrador","_candidate_experience_time":"+6 A\u00f1os","_candidate_salary":"Q10,000","_candidate_languages":["Espa\u00f1ol"],"_candidate_skill":"","_candidate_category":[],"_candidate_cv_attachment":{"32563":"https:\/\/contratame.online\/wp-content\/uploads\/2026\/01\/CV-Jabson-Donis.pdf"},"_candidate_education":[{"title":"LICENCIADO EN TECNOLOG\u00cdA Y ADMINISTRACI\u00d3N DE LAS TELECOMUNICACIONES","academy":"Universidad Galileo","year":"2024","description":"Profesional en Tecnolog\u00eda, Telecomunicaciones y Administraci\u00f3n experiencia liderando proyectos tecnol\u00f3gicos, de infraestructura y administrativos. Experto en planificaci\u00f3n, control presupuestario y ejecuci\u00f3n de proyectos con enfoque en eficiencia operativa y transformaci\u00f3n digital."}],"_candidate_experience":[{"title":"Gerente de Instalaciones y Servicios de Oficina","start_date":"15 de Marzo 2025","end_date":"31 de Diciembre 2025","company":"ATHENA, LTDA","description":"Facilities and Office Services Manager \r\n\r\n- Direcci\u00f3n de proyectos de infraestructura y optimizaci\u00f3n de espacios de trabajo.\r\n- Implementaci\u00f3n de sistemas de gesti\u00f3n de activos tecnol\u00f3gicos y procesos administrativos.\r\n- Coordinaci\u00f3n de equipos t\u00e9cnicos, proveedores y stakeholders internos para cumplir objetivos de contrataci\u00f3n\r\n- Supervisi\u00f3n de presupuestos, control de recursos y seguimiento de cronogramas del departamento de Capital Investment\r\n- Gesti\u00f3n integral de servicios corporativos: mantenimiento, log\u00edstica, TI y soporte t\u00e9cnico.\r\n- TI y soporte t\u00e9cnico, Inventario de activos fijos y Equipo Tecnol\u00f3gico \u00a8MAC\u00a8\r\n- Log\u00edstica de viajes, reservas de hotel y alojamiento de Asistentes Ejecutivos y Staff\r\n\uf0a7\tEjecuci\u00f3n de proyectos de mejora continua en procesos operativos y tecnol\u00f3gicos del departamento de Facilities\r\n"},{"title":"Supervisor Senior Project Managment","start_date":"14 de marzo 2022","end_date":"14 de marzo 2025","company":"CONDUENT","description":"Coordinador de Proyectos Operativos \r\n\r\n- Direcci\u00f3n de proyectos de actualizaci\u00f3n de hardware, migraciones de dominio y reemplazo de equipos, asegurando la continuidad operativa y el cumplimiento de pol\u00edticas corporativas.\r\n- Dise\u00f1o e implementaci\u00f3n de procesos estandarizados para el onboarding para nuevas contrataciones, alcanzando una reducci\u00f3n hasta de un 35 % de los tiempos de incorporaci\u00f3n de los empleados a la empresa, los mejorando la productividad inicial. Y reduciendo costes de contrataci\u00f3n en la misma medida.\r\n- Hiring Manager de las contrataciones masivas de empleados de Guatemala, Jamaica y Brazil, que incluyo la gesti\u00f3n, creaci\u00f3n de credenciales, accesos y cuentas corporativas da los sistemas de la compa\u00f1\u00eda, as\u00ed como como la creaci\u00f3n de usuarios dentro de los sistemas de clientes.\r\n- Supervisi\u00f3n del equipo de @yourservice, servicio a usuarios finales y correcto mantenimiento de cuentas y perfiles de usuarios activos en la compa\u00f1\u00eda, coordinando sus actividades diarias para garantizar precisi\u00f3n y cumplimiento de seguridad de la informaci\u00f3n de nuestros clientes internos como externos.\r\n- L\u00edder del Proyecto DEPOT, enfocado en la recuperaci\u00f3n, actualizaci\u00f3n y redistribuci\u00f3n de equipos de c\u00f3mputo, alcanzando un 92.5 % de recuperaci\u00f3n efectiva y garantizando la trazabilidad completa de activos tecnol\u00f3gicos de la compa\u00f1\u00eda con un alcance de m\u00e1s de 7,000 empleados\r\n- Supervisi\u00f3n del Depot y monitoreo de actividades tales como control, recepci\u00f3n, entrega y reasignaci\u00f3n de equipos de c\u00f3mputo a colaboradores y nuevos ingresos, optimizando el control del inventario y los tiempos de implementaci\u00f3n.\r\n"},{"title":"Jefe de IT y Staff","start_date":"Septiembre 2015","end_date":"Agosto 2020","company":"ONLYTEL","description":"L\u00edder de Proyectos Operativos y Tecnol\u00f3gicos\r\n\t \t \t \r\n- Implementaci\u00f3n de proceso de reconciliaci\u00f3n de recolecci\u00f3n de efectivo, utilizando el sistema de control de tel\u00e9fonos p\u00fablicos, logrando incrementar la eficiencia de entre un 40 % y 50 % en todas las rutas activas.\r\n- Dise\u00f1o y Ejecuci\u00f3n del plan de reorganizaci\u00f3n de horarios laborales, reduciendo la jornada de trabajo de 12 a 8 horas diarias sin afectar la productividad, optimizando los recursos humanos y operativos financieros de la empresa.\t\r\n- Implementaci\u00f3n de una estructura organizacional de acuerdo con las necesidades del negocio, as\u00ed como la Coordinaci\u00f3n de Supervisores de Operaciones, mejorando la coordinaci\u00f3n entre equipos de campo y administraci\u00f3n.\t\t\r\n- Desarrollo, implementaci\u00f3n y configuraci\u00f3n del sistema de reportes de fallas automatizado, para reducir el 60 % los incidentes reportados en tel\u00e9fonos p\u00fablicos, aumentando la disponibilidad del servicio y la satisfacci\u00f3n de los clientes\r\n- Creaci\u00f3n de propuestas de Expansi\u00f3n, implementada exitosamente en el \u00e1rea de operaci\u00f3n log\u00edstica, abriendo dos nuevas rutas y duplicando las rutas existentes, fortaleciendo la cobertura nacional y la eficiencia del servicio.\t\r\n"}],"_candidate_logo":"https:\/\/contratame.online\/wp-content\/uploads\/wp-job-board-pro-uploads\/_candidate_featured_image\/2026\/01\/shared-image-150x150.jpg"},"_links":{"self":[{"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/candidate\/32561","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/candidate"}],"about":[{"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/types\/candidate"}],"replies":[{"embeddable":true,"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/comments?post=32561"}],"version-history":[{"count":1,"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/candidate\/32561\/revisions"}],"predecessor-version":[{"id":32562,"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/candidate\/32561\/revisions\/32562"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/media\/32564"}],"wp:attachment":[{"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/media?parent=32561"}],"wp:term":[{"taxonomy":"candidate_category","embeddable":true,"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/candidate_category?post=32561"},{"taxonomy":"candidate_location","embeddable":true,"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/candidate_location?post=32561"},{"taxonomy":"candidate_tag","embeddable":true,"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/candidate_tag?post=32561"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}