{"id":34807,"date":"2026-01-18T21:48:19","date_gmt":"2026-01-19T03:48:19","guid":{"rendered":"https:\/\/contratame.online\/es\/candidate\/victoriaeguizabal-97\/"},"modified":"2026-01-18T22:05:24","modified_gmt":"2026-01-19T04:05:24","slug":"victoriaeguizabal-97","status":"publish","type":"candidate","link":"https:\/\/contratame.online\/es\/candidate\/victoriaeguizabal-97\/","title":{"rendered":"Katherine Victoria Eguizabal Figueroa"},"content":{"rendered":"<p>En el \u00e1mbito laboral, me he\u00a0 destacado mediante el apoyo para la gesti\u00f3n de recepcionar, inventariar y entrega de equipo y accesorios de comput\u00f3. As\u00ed mismo la atenci\u00f3n al cliente y proveedores de diferentes empresas.<\/p>\n","protected":false},"featured_media":34864,"comment_status":"open","ping_status":"closed","template":"","candidate_category":[278],"candidate_location":[],"candidate_tag":[],"class_list":["post-34807","candidate","type-candidate","status-publish","has-post-thumbnail","hentry","candidate_category-desarrollador"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Katherine Victoria Eguizabal Figueroa - Contratame.online<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/contratame.online\/es\/candidate\/victoriaeguizabal-97\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Katherine Victoria Eguizabal Figueroa - Contratame.online\" \/>\n<meta property=\"og:description\" content=\"En el \u00e1mbito laboral, me he\u00a0 destacado mediante el apoyo para la gesti\u00f3n de recepcionar, inventariar y entrega de equipo y accesorios de comput\u00f3. As\u00ed mismo la atenci\u00f3n al cliente y proveedores de diferentes empresas.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/contratame.online\/es\/candidate\/victoriaeguizabal-97\/\" \/>\n<meta property=\"og:site_name\" content=\"Contratame.online\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/contratamegt\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-19T04:05:24+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/contratame.online\/es\/candidate\/victoriaeguizabal-97\/\",\"url\":\"https:\/\/contratame.online\/es\/candidate\/victoriaeguizabal-97\/\",\"name\":\"Katherine Victoria Eguizabal Figueroa - Contratame.online\",\"isPartOf\":{\"@id\":\"https:\/\/contratame.online\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/contratame.online\/es\/candidate\/victoriaeguizabal-97\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/contratame.online\/es\/candidate\/victoriaeguizabal-97\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/contratame.online\/wp-content\/uploads\/wp-job-board-pro-uploads\/_candidate_featured_image\/2026\/01\/inbound7717331094580253981.jpg\",\"datePublished\":\"2026-01-19T03:48:19+00:00\",\"dateModified\":\"2026-01-19T04:05:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/contratame.online\/es\/candidate\/victoriaeguizabal-97\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/contratame.online\/es\/candidate\/victoriaeguizabal-97\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/contratame.online\/es\/candidate\/victoriaeguizabal-97\/#primaryimage\",\"url\":\"https:\/\/contratame.online\/wp-content\/uploads\/wp-job-board-pro-uploads\/_candidate_featured_image\/2026\/01\/inbound7717331094580253981.jpg\",\"contentUrl\":\"https:\/\/contratame.online\/wp-content\/uploads\/wp-job-board-pro-uploads\/_candidate_featured_image\/2026\/01\/inbound7717331094580253981.jpg\",\"width\":1201,\"height\":1600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/contratame.online\/es\/candidate\/victoriaeguizabal-97\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/contratame.online\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Candidates\",\"item\":\"https:\/\/contratame.online\/en\/candidate\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Katherine Victoria Eguizabal Figueroa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/contratame.online\/#website\",\"url\":\"https:\/\/contratame.online\/\",\"name\":\"Contratame.online\",\"description\":\"Encuentra el empleo que siempre so\u00f1aste.\",\"publisher\":{\"@id\":\"https:\/\/contratame.online\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/contratame.online\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/contratame.online\/#organization\",\"name\":\"CONTRATA ME\",\"url\":\"https:\/\/contratame.online\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/contratame.online\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/contratame.online\/wp-content\/uploads\/2023\/07\/logohd.png\",\"contentUrl\":\"https:\/\/contratame.online\/wp-content\/uploads\/2023\/07\/logohd.png\",\"width\":150,\"height\":50,\"caption\":\"CONTRATA ME\"},\"image\":{\"@id\":\"https:\/\/contratame.online\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/contratamegt\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Katherine Victoria Eguizabal Figueroa - Contratame.online","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/contratame.online\/es\/candidate\/victoriaeguizabal-97\/","og_locale":"es_ES","og_type":"article","og_title":"Katherine Victoria Eguizabal Figueroa - Contratame.online","og_description":"En el \u00e1mbito laboral, me he\u00a0 destacado mediante el apoyo para la gesti\u00f3n de recepcionar, inventariar y entrega de equipo y accesorios de comput\u00f3. As\u00ed mismo la atenci\u00f3n al cliente y proveedores de diferentes empresas.","og_url":"https:\/\/contratame.online\/es\/candidate\/victoriaeguizabal-97\/","og_site_name":"Contratame.online","article_publisher":"https:\/\/www.facebook.com\/contratamegt","article_modified_time":"2026-01-19T04:05:24+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/contratame.online\/es\/candidate\/victoriaeguizabal-97\/","url":"https:\/\/contratame.online\/es\/candidate\/victoriaeguizabal-97\/","name":"Katherine Victoria Eguizabal Figueroa - Contratame.online","isPartOf":{"@id":"https:\/\/contratame.online\/#website"},"primaryImageOfPage":{"@id":"https:\/\/contratame.online\/es\/candidate\/victoriaeguizabal-97\/#primaryimage"},"image":{"@id":"https:\/\/contratame.online\/es\/candidate\/victoriaeguizabal-97\/#primaryimage"},"thumbnailUrl":"https:\/\/contratame.online\/wp-content\/uploads\/wp-job-board-pro-uploads\/_candidate_featured_image\/2026\/01\/inbound7717331094580253981.jpg","datePublished":"2026-01-19T03:48:19+00:00","dateModified":"2026-01-19T04:05:24+00:00","breadcrumb":{"@id":"https:\/\/contratame.online\/es\/candidate\/victoriaeguizabal-97\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/contratame.online\/es\/candidate\/victoriaeguizabal-97\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/contratame.online\/es\/candidate\/victoriaeguizabal-97\/#primaryimage","url":"https:\/\/contratame.online\/wp-content\/uploads\/wp-job-board-pro-uploads\/_candidate_featured_image\/2026\/01\/inbound7717331094580253981.jpg","contentUrl":"https:\/\/contratame.online\/wp-content\/uploads\/wp-job-board-pro-uploads\/_candidate_featured_image\/2026\/01\/inbound7717331094580253981.jpg","width":1201,"height":1600},{"@type":"BreadcrumbList","@id":"https:\/\/contratame.online\/es\/candidate\/victoriaeguizabal-97\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/contratame.online\/"},{"@type":"ListItem","position":2,"name":"Candidates","item":"https:\/\/contratame.online\/en\/candidate\/"},{"@type":"ListItem","position":3,"name":"Katherine Victoria Eguizabal Figueroa"}]},{"@type":"WebSite","@id":"https:\/\/contratame.online\/#website","url":"https:\/\/contratame.online\/","name":"Contratame.online","description":"Encuentra el empleo que siempre so\u00f1aste.","publisher":{"@id":"https:\/\/contratame.online\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/contratame.online\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/contratame.online\/#organization","name":"CONTRATA ME","url":"https:\/\/contratame.online\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/contratame.online\/#\/schema\/logo\/image\/","url":"https:\/\/contratame.online\/wp-content\/uploads\/2023\/07\/logohd.png","contentUrl":"https:\/\/contratame.online\/wp-content\/uploads\/2023\/07\/logohd.png","width":150,"height":50,"caption":"CONTRATA ME"},"image":{"@id":"https:\/\/contratame.online\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/contratamegt"]}]}},"metas":{"_candidate_location":[],"_candidate_age":"28","_candidate_gender":"Femenino","_candidate_phone":"55935278","_candidate_email":"victoriaeguizabal.97@gmail.com","_candidate_qualification":"Diversificado","_candidate_job_title":"Estudiante","_candidate_experience_time":"4 A\u00f1os","_candidate_salary":"Q5,500","_candidate_languages":["Espa\u00f1ol"],"_candidate_skill":"","_candidate_category":{"278":"Desarrollador"},"_candidate_cv_attachment":{"34809":"https:\/\/contratame.online\/wp-content\/uploads\/2026\/01\/inbound2182252760405826469.pdf"},"_candidate_education":"","_candidate_experience":"","_candidate_logo":"https:\/\/contratame.online\/wp-content\/uploads\/wp-job-board-pro-uploads\/_candidate_featured_image\/2026\/01\/inbound7717331094580253981-150x150.jpg"},"_links":{"self":[{"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/candidate\/34807","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/candidate"}],"about":[{"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/types\/candidate"}],"replies":[{"embeddable":true,"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/comments?post=34807"}],"version-history":[{"count":1,"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/candidate\/34807\/revisions"}],"predecessor-version":[{"id":34808,"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/candidate\/34807\/revisions\/34808"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/media\/34864"}],"wp:attachment":[{"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/media?parent=34807"}],"wp:term":[{"taxonomy":"candidate_category","embeddable":true,"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/candidate_category?post=34807"},{"taxonomy":"candidate_location","embeddable":true,"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/candidate_location?post=34807"},{"taxonomy":"candidate_tag","embeddable":true,"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/candidate_tag?post=34807"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}