{"id":76714,"date":"2026-07-30T12:51:41","date_gmt":"2026-07-30T18:51:41","guid":{"rendered":"https:\/\/contratame.online\/es\/candidate\/brandontocm2000\/"},"modified":"2026-07-30T12:57:11","modified_gmt":"2026-07-30T18:57:11","slug":"brandontocm2000","status":"publish","type":"candidate","link":"https:\/\/contratame.online\/es\/candidate\/brandontocm2000\/","title":{"rendered":"brandontocm2000"},"content":{"rendered":"<p>Cuento con experiencia en implementaci\u00f3n y soporte t\u00e9cnico, tanto en entornos empresariales como de forma independiente. He brindado soporte a usuarios finales, gerentes y \u00e1reas cr\u00edticas, resolviendo incidencias de hardware, software, conectividad y configuraci\u00f3n de equipos, siempre con enfoque en el servicio. Particip\u00e9 en la implementaci\u00f3n de un sistema corporativo de impresi\u00f3n segura para m\u00e1s de 200 usuarios, as\u00ed como en cambios masivos de laptops, computadoras y monitores. Tambi\u00e9n realic\u00e9 configuraci\u00f3n y asignaci\u00f3n de equipos y tel\u00e9fonos corporativos, instalaci\u00f3n de aplicaciones, gesti\u00f3n de inventario, creaci\u00f3n y seguimiento de tickets, administraci\u00f3n de activos y apoyo en aperturas de sedes. Adem\u00e1s, particip\u00e9 en la instalaci\u00f3n de estaciones de trabajo para distintos clientes, garantizando la continuidad operativa y una atenci\u00f3n profesional a los usuarios.<\/p>\n","protected":false},"featured_media":76717,"comment_status":"open","ping_status":"closed","template":"","candidate_category":[],"candidate_location":[167],"candidate_tag":[],"class_list":["post-76714","candidate","type-candidate","status-publish","has-post-thumbnail","hentry","candidate_location-guatemala"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>brandontocm2000 - Contratame.online<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"brandontocm2000 - Contratame.online\" \/>\n<meta property=\"og:description\" content=\"Cuento con experiencia en implementaci\u00f3n y soporte t\u00e9cnico, tanto en entornos empresariales como de forma independiente. He brindado soporte a usuarios finales, gerentes y \u00e1reas cr\u00edticas, resolviendo incidencias de hardware, software, conectividad y configuraci\u00f3n de equipos, siempre con enfoque en el servicio. Particip\u00e9 en la implementaci\u00f3n de un sistema corporativo de impresi\u00f3n segura para m\u00e1s [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/contratame.online\/es\/candidate\/brandontocm2000\/\" \/>\n<meta property=\"og:site_name\" content=\"Contratame.online\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/contratamegt\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-30T18:57:11+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/contratame.online\/es\/candidate\/brandontocm2000\/\",\"url\":\"https:\/\/contratame.online\/es\/candidate\/brandontocm2000\/\",\"name\":\"brandontocm2000 - Contratame.online\",\"isPartOf\":{\"@id\":\"https:\/\/contratame.online\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/contratame.online\/es\/candidate\/brandontocm2000\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/contratame.online\/es\/candidate\/brandontocm2000\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/contratame.online\/wp-content\/uploads\/wp-job-board-pro-uploads\/_candidate_featured_image\/2026\/07\/Imagen-de-WhatsApp-2025-06-09-a-las-11.12.32_4d9b760d.jpg\",\"datePublished\":\"2026-07-30T18:51:41+00:00\",\"dateModified\":\"2026-07-30T18:57:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/contratame.online\/es\/candidate\/brandontocm2000\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/contratame.online\/es\/candidate\/brandontocm2000\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/contratame.online\/es\/candidate\/brandontocm2000\/#primaryimage\",\"url\":\"https:\/\/contratame.online\/wp-content\/uploads\/wp-job-board-pro-uploads\/_candidate_featured_image\/2026\/07\/Imagen-de-WhatsApp-2025-06-09-a-las-11.12.32_4d9b760d.jpg\",\"contentUrl\":\"https:\/\/contratame.online\/wp-content\/uploads\/wp-job-board-pro-uploads\/_candidate_featured_image\/2026\/07\/Imagen-de-WhatsApp-2025-06-09-a-las-11.12.32_4d9b760d.jpg\",\"width\":872,\"height\":1084},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/contratame.online\/es\/candidate\/brandontocm2000\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/contratame.online\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Candidates\",\"item\":\"https:\/\/contratame.online\/en\/candidate\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"brandontocm2000\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/contratame.online\/#website\",\"url\":\"https:\/\/contratame.online\/\",\"name\":\"Contratame.online\",\"description\":\"Encuentra el empleo que siempre so\u00f1aste.\",\"publisher\":{\"@id\":\"https:\/\/contratame.online\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/contratame.online\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/contratame.online\/#organization\",\"name\":\"CONTRATA ME\",\"url\":\"https:\/\/contratame.online\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/contratame.online\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/contratame.online\/wp-content\/uploads\/2023\/07\/logohd.png\",\"contentUrl\":\"https:\/\/contratame.online\/wp-content\/uploads\/2023\/07\/logohd.png\",\"width\":150,\"height\":50,\"caption\":\"CONTRATA ME\"},\"image\":{\"@id\":\"https:\/\/contratame.online\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/contratamegt\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"brandontocm2000 - Contratame.online","robots":{"index":"noindex","follow":"follow"},"og_locale":"es_ES","og_type":"article","og_title":"brandontocm2000 - Contratame.online","og_description":"Cuento con experiencia en implementaci\u00f3n y soporte t\u00e9cnico, tanto en entornos empresariales como de forma independiente. He brindado soporte a usuarios finales, gerentes y \u00e1reas cr\u00edticas, resolviendo incidencias de hardware, software, conectividad y configuraci\u00f3n de equipos, siempre con enfoque en el servicio. Particip\u00e9 en la implementaci\u00f3n de un sistema corporativo de impresi\u00f3n segura para m\u00e1s [&hellip;]","og_url":"https:\/\/contratame.online\/es\/candidate\/brandontocm2000\/","og_site_name":"Contratame.online","article_publisher":"https:\/\/www.facebook.com\/contratamegt","article_modified_time":"2026-07-30T18:57:11+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/contratame.online\/es\/candidate\/brandontocm2000\/","url":"https:\/\/contratame.online\/es\/candidate\/brandontocm2000\/","name":"brandontocm2000 - Contratame.online","isPartOf":{"@id":"https:\/\/contratame.online\/#website"},"primaryImageOfPage":{"@id":"https:\/\/contratame.online\/es\/candidate\/brandontocm2000\/#primaryimage"},"image":{"@id":"https:\/\/contratame.online\/es\/candidate\/brandontocm2000\/#primaryimage"},"thumbnailUrl":"https:\/\/contratame.online\/wp-content\/uploads\/wp-job-board-pro-uploads\/_candidate_featured_image\/2026\/07\/Imagen-de-WhatsApp-2025-06-09-a-las-11.12.32_4d9b760d.jpg","datePublished":"2026-07-30T18:51:41+00:00","dateModified":"2026-07-30T18:57:11+00:00","breadcrumb":{"@id":"https:\/\/contratame.online\/es\/candidate\/brandontocm2000\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/contratame.online\/es\/candidate\/brandontocm2000\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/contratame.online\/es\/candidate\/brandontocm2000\/#primaryimage","url":"https:\/\/contratame.online\/wp-content\/uploads\/wp-job-board-pro-uploads\/_candidate_featured_image\/2026\/07\/Imagen-de-WhatsApp-2025-06-09-a-las-11.12.32_4d9b760d.jpg","contentUrl":"https:\/\/contratame.online\/wp-content\/uploads\/wp-job-board-pro-uploads\/_candidate_featured_image\/2026\/07\/Imagen-de-WhatsApp-2025-06-09-a-las-11.12.32_4d9b760d.jpg","width":872,"height":1084},{"@type":"BreadcrumbList","@id":"https:\/\/contratame.online\/es\/candidate\/brandontocm2000\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/contratame.online\/"},{"@type":"ListItem","position":2,"name":"Candidates","item":"https:\/\/contratame.online\/en\/candidate\/"},{"@type":"ListItem","position":3,"name":"brandontocm2000"}]},{"@type":"WebSite","@id":"https:\/\/contratame.online\/#website","url":"https:\/\/contratame.online\/","name":"Contratame.online","description":"Encuentra el empleo que siempre so\u00f1aste.","publisher":{"@id":"https:\/\/contratame.online\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/contratame.online\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/contratame.online\/#organization","name":"CONTRATA ME","url":"https:\/\/contratame.online\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/contratame.online\/#\/schema\/logo\/image\/","url":"https:\/\/contratame.online\/wp-content\/uploads\/2023\/07\/logohd.png","contentUrl":"https:\/\/contratame.online\/wp-content\/uploads\/2023\/07\/logohd.png","width":150,"height":50,"caption":"CONTRATA ME"},"image":{"@id":"https:\/\/contratame.online\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/contratamegt"]}]}},"metas":{"_candidate_location":{"167":"Guatemala"},"_candidate_age":"26","_candidate_gender":"Masculino","_candidate_phone":"4747 8698","_candidate_email":"brandontocm2000@gmail.com","_candidate_qualification":"Licenciatura","_candidate_job_title":"Soporte Tecnico","_candidate_experience_time":"2 A\u00f1os","_candidate_salary":"Q5,500","_candidate_languages":["Espa\u00f1ol"],"_candidate_skill":[{"title":"Introduccion a la Ciberseguridad","percentage":"100"},{"title":"Analisis e Interpretacion de datos","percentage":"100"}],"_candidate_category":[],"_candidate_cv_attachment":{"76716":"https:\/\/contratame.online\/wp-content\/uploads\/2026\/07\/CV-2026.docx.pdf"},"_candidate_education":"","_candidate_experience":"","_candidate_logo":"https:\/\/contratame.online\/wp-content\/uploads\/wp-job-board-pro-uploads\/_candidate_featured_image\/2026\/07\/Imagen-de-WhatsApp-2025-06-09-a-las-11.12.32_4d9b760d-150x150.jpg"},"_links":{"self":[{"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/candidate\/76714","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/candidate"}],"about":[{"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/types\/candidate"}],"replies":[{"embeddable":true,"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/comments?post=76714"}],"version-history":[{"count":1,"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/candidate\/76714\/revisions"}],"predecessor-version":[{"id":76715,"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/candidate\/76714\/revisions\/76715"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/media\/76717"}],"wp:attachment":[{"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/media?parent=76714"}],"wp:term":[{"taxonomy":"candidate_category","embeddable":true,"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/candidate_category?post=76714"},{"taxonomy":"candidate_location","embeddable":true,"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/candidate_location?post=76714"},{"taxonomy":"candidate_tag","embeddable":true,"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/candidate_tag?post=76714"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}