{"id":77433,"date":"2026-08-07T10:45:29","date_gmt":"2026-08-07T16:45:29","guid":{"rendered":"https:\/\/contratame.online\/es\/candidate\/daravenettias-24\/"},"modified":"2026-08-07T10:53:02","modified_gmt":"2026-08-07T16:53:02","slug":"daravenettias-24","status":"publish","type":"candidate","link":"https:\/\/contratame.online\/es\/candidate\/daravenettias-24\/","title":{"rendered":"Jessica Sierra"},"content":{"rendered":"<ul>\n<li>Educadora\u00a0 y atenci\u00f3n al cliente<\/li>\n<\/ul>\n<p><!--more--><\/p>\n<p><!--more--><\/p>\n","protected":false},"featured_media":77451,"comment_status":"open","ping_status":"closed","template":"","candidate_category":[],"candidate_location":[167],"candidate_tag":[],"class_list":["post-77433","candidate","type-candidate","status-publish","has-post-thumbnail","hentry","candidate_location-guatemala"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Jessica Sierra - Contratame.online<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Jessica Sierra - Contratame.online\" \/>\n<meta property=\"og:description\" content=\"Educadora\u00a0 y atenci\u00f3n al cliente\" \/>\n<meta property=\"og:url\" content=\"https:\/\/contratame.online\/es\/candidate\/daravenettias-24\/\" \/>\n<meta property=\"og:site_name\" content=\"Contratame.online\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/contratamegt\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-07T16:53:02+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/contratame.online\/es\/candidate\/daravenettias-24\/\",\"url\":\"https:\/\/contratame.online\/es\/candidate\/daravenettias-24\/\",\"name\":\"Jessica Sierra - Contratame.online\",\"isPartOf\":{\"@id\":\"https:\/\/contratame.online\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/contratame.online\/es\/candidate\/daravenettias-24\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/contratame.online\/es\/candidate\/daravenettias-24\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/contratame.online\/wp-content\/uploads\/wp-job-board-pro-uploads\/_candidate_featured_image\/2026\/08\/inbound6820353079309020706.jpg\",\"datePublished\":\"2026-08-07T16:45:29+00:00\",\"dateModified\":\"2026-08-07T16:53:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/contratame.online\/es\/candidate\/daravenettias-24\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/contratame.online\/es\/candidate\/daravenettias-24\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/contratame.online\/es\/candidate\/daravenettias-24\/#primaryimage\",\"url\":\"https:\/\/contratame.online\/wp-content\/uploads\/wp-job-board-pro-uploads\/_candidate_featured_image\/2026\/08\/inbound6820353079309020706.jpg\",\"contentUrl\":\"https:\/\/contratame.online\/wp-content\/uploads\/wp-job-board-pro-uploads\/_candidate_featured_image\/2026\/08\/inbound6820353079309020706.jpg\",\"width\":720,\"height\":1600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/contratame.online\/es\/candidate\/daravenettias-24\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/contratame.online\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Candidates\",\"item\":\"https:\/\/contratame.online\/en\/candidate\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Jessica Sierra\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/contratame.online\/#website\",\"url\":\"https:\/\/contratame.online\/\",\"name\":\"Contratame.online\",\"description\":\"Encuentra el empleo que siempre so\u00f1aste.\",\"publisher\":{\"@id\":\"https:\/\/contratame.online\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/contratame.online\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/contratame.online\/#organization\",\"name\":\"CONTRATA ME\",\"url\":\"https:\/\/contratame.online\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/contratame.online\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/contratame.online\/wp-content\/uploads\/2023\/07\/logohd.png\",\"contentUrl\":\"https:\/\/contratame.online\/wp-content\/uploads\/2023\/07\/logohd.png\",\"width\":150,\"height\":50,\"caption\":\"CONTRATA ME\"},\"image\":{\"@id\":\"https:\/\/contratame.online\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/contratamegt\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Jessica Sierra - Contratame.online","robots":{"index":"noindex","follow":"follow"},"og_locale":"es_ES","og_type":"article","og_title":"Jessica Sierra - Contratame.online","og_description":"Educadora\u00a0 y atenci\u00f3n al cliente","og_url":"https:\/\/contratame.online\/es\/candidate\/daravenettias-24\/","og_site_name":"Contratame.online","article_publisher":"https:\/\/www.facebook.com\/contratamegt","article_modified_time":"2026-08-07T16:53:02+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/contratame.online\/es\/candidate\/daravenettias-24\/","url":"https:\/\/contratame.online\/es\/candidate\/daravenettias-24\/","name":"Jessica Sierra - Contratame.online","isPartOf":{"@id":"https:\/\/contratame.online\/#website"},"primaryImageOfPage":{"@id":"https:\/\/contratame.online\/es\/candidate\/daravenettias-24\/#primaryimage"},"image":{"@id":"https:\/\/contratame.online\/es\/candidate\/daravenettias-24\/#primaryimage"},"thumbnailUrl":"https:\/\/contratame.online\/wp-content\/uploads\/wp-job-board-pro-uploads\/_candidate_featured_image\/2026\/08\/inbound6820353079309020706.jpg","datePublished":"2026-08-07T16:45:29+00:00","dateModified":"2026-08-07T16:53:02+00:00","breadcrumb":{"@id":"https:\/\/contratame.online\/es\/candidate\/daravenettias-24\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/contratame.online\/es\/candidate\/daravenettias-24\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/contratame.online\/es\/candidate\/daravenettias-24\/#primaryimage","url":"https:\/\/contratame.online\/wp-content\/uploads\/wp-job-board-pro-uploads\/_candidate_featured_image\/2026\/08\/inbound6820353079309020706.jpg","contentUrl":"https:\/\/contratame.online\/wp-content\/uploads\/wp-job-board-pro-uploads\/_candidate_featured_image\/2026\/08\/inbound6820353079309020706.jpg","width":720,"height":1600},{"@type":"BreadcrumbList","@id":"https:\/\/contratame.online\/es\/candidate\/daravenettias-24\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/contratame.online\/"},{"@type":"ListItem","position":2,"name":"Candidates","item":"https:\/\/contratame.online\/en\/candidate\/"},{"@type":"ListItem","position":3,"name":"Jessica Sierra"}]},{"@type":"WebSite","@id":"https:\/\/contratame.online\/#website","url":"https:\/\/contratame.online\/","name":"Contratame.online","description":"Encuentra el empleo que siempre so\u00f1aste.","publisher":{"@id":"https:\/\/contratame.online\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/contratame.online\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/contratame.online\/#organization","name":"CONTRATA ME","url":"https:\/\/contratame.online\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/contratame.online\/#\/schema\/logo\/image\/","url":"https:\/\/contratame.online\/wp-content\/uploads\/2023\/07\/logohd.png","contentUrl":"https:\/\/contratame.online\/wp-content\/uploads\/2023\/07\/logohd.png","width":150,"height":50,"caption":"CONTRATA ME"},"image":{"@id":"https:\/\/contratame.online\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/contratamegt"]}]}},"metas":{"_candidate_location":{"167":"Guatemala"},"_candidate_age":"49","_candidate_gender":"Femenino","_candidate_phone":"44806787","_candidate_email":"daravenettias.24@gmail.com","_candidate_qualification":"Diversificado","_candidate_job_title":"Educadora","_candidate_experience_time":"+6 A\u00f1os","_candidate_salary":"","_candidate_languages":["Espa\u00f1ol"],"_candidate_skill":"","_candidate_category":[],"_candidate_cv_attachment":{"77435":"https:\/\/contratame.online\/wp-content\/uploads\/2026\/08\/inbound3612055649173050783.pdf"},"_candidate_education":"","_candidate_experience":"","_candidate_logo":"https:\/\/contratame.online\/wp-content\/uploads\/wp-job-board-pro-uploads\/_candidate_featured_image\/2026\/08\/inbound6820353079309020706-150x150.jpg"},"_links":{"self":[{"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/candidate\/77433","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/candidate"}],"about":[{"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/types\/candidate"}],"replies":[{"embeddable":true,"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/comments?post=77433"}],"version-history":[{"count":1,"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/candidate\/77433\/revisions"}],"predecessor-version":[{"id":77434,"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/candidate\/77433\/revisions\/77434"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/media\/77451"}],"wp:attachment":[{"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/media?parent=77433"}],"wp:term":[{"taxonomy":"candidate_category","embeddable":true,"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/candidate_category?post=77433"},{"taxonomy":"candidate_location","embeddable":true,"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/candidate_location?post=77433"},{"taxonomy":"candidate_tag","embeddable":true,"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/candidate_tag?post=77433"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}