{"id":77612,"date":"2026-08-08T15:25:20","date_gmt":"2026-08-08T21:25:20","guid":{"rendered":"https:\/\/contratame.online\/es\/candidate\/noemi1mh\/"},"modified":"2026-08-08T15:27:31","modified_gmt":"2026-08-08T21:27:31","slug":"noemi1mh","status":"publish","type":"candidate","link":"https:\/\/contratame.online\/es\/candidate\/noemi1mh\/","title":{"rendered":"Angelica"},"content":{"rendered":"<p>Experiencia en rrhh, 6 a\u00f1os<\/p>\n","protected":false},"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","candidate_category":[],"candidate_location":[167],"candidate_tag":[],"class_list":["post-77612","candidate","type-candidate","status-publish","hentry","candidate_location-guatemala"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Angelica - Contratame.online<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Angelica - Contratame.online\" \/>\n<meta property=\"og:description\" content=\"Experiencia en rrhh, 6 a\u00f1os\" \/>\n<meta property=\"og:url\" content=\"https:\/\/contratame.online\/es\/candidate\/noemi1mh\/\" \/>\n<meta property=\"og:site_name\" content=\"Contratame.online\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/contratamegt\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-08T21:27:31+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/contratame.online\/es\/candidate\/noemi1mh\/\",\"url\":\"https:\/\/contratame.online\/es\/candidate\/noemi1mh\/\",\"name\":\"Angelica - Contratame.online\",\"isPartOf\":{\"@id\":\"https:\/\/contratame.online\/#website\"},\"datePublished\":\"2026-08-08T21:25:20+00:00\",\"dateModified\":\"2026-08-08T21:27:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/contratame.online\/es\/candidate\/noemi1mh\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/contratame.online\/es\/candidate\/noemi1mh\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/contratame.online\/es\/candidate\/noemi1mh\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/contratame.online\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Candidates\",\"item\":\"https:\/\/contratame.online\/en\/candidate\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Angelica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/contratame.online\/#website\",\"url\":\"https:\/\/contratame.online\/\",\"name\":\"Contratame.online\",\"description\":\"Encuentra el empleo que siempre so\u00f1aste.\",\"publisher\":{\"@id\":\"https:\/\/contratame.online\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/contratame.online\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/contratame.online\/#organization\",\"name\":\"CONTRATA ME\",\"url\":\"https:\/\/contratame.online\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/contratame.online\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/contratame.online\/wp-content\/uploads\/2023\/07\/logohd.png\",\"contentUrl\":\"https:\/\/contratame.online\/wp-content\/uploads\/2023\/07\/logohd.png\",\"width\":150,\"height\":50,\"caption\":\"CONTRATA ME\"},\"image\":{\"@id\":\"https:\/\/contratame.online\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/contratamegt\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Angelica - Contratame.online","robots":{"index":"noindex","follow":"follow"},"og_locale":"es_ES","og_type":"article","og_title":"Angelica - Contratame.online","og_description":"Experiencia en rrhh, 6 a\u00f1os","og_url":"https:\/\/contratame.online\/es\/candidate\/noemi1mh\/","og_site_name":"Contratame.online","article_publisher":"https:\/\/www.facebook.com\/contratamegt","article_modified_time":"2026-08-08T21:27:31+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/contratame.online\/es\/candidate\/noemi1mh\/","url":"https:\/\/contratame.online\/es\/candidate\/noemi1mh\/","name":"Angelica - Contratame.online","isPartOf":{"@id":"https:\/\/contratame.online\/#website"},"datePublished":"2026-08-08T21:25:20+00:00","dateModified":"2026-08-08T21:27:31+00:00","breadcrumb":{"@id":"https:\/\/contratame.online\/es\/candidate\/noemi1mh\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/contratame.online\/es\/candidate\/noemi1mh\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/contratame.online\/es\/candidate\/noemi1mh\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/contratame.online\/"},{"@type":"ListItem","position":2,"name":"Candidates","item":"https:\/\/contratame.online\/en\/candidate\/"},{"@type":"ListItem","position":3,"name":"Angelica"}]},{"@type":"WebSite","@id":"https:\/\/contratame.online\/#website","url":"https:\/\/contratame.online\/","name":"Contratame.online","description":"Encuentra el empleo que siempre so\u00f1aste.","publisher":{"@id":"https:\/\/contratame.online\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/contratame.online\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/contratame.online\/#organization","name":"CONTRATA ME","url":"https:\/\/contratame.online\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/contratame.online\/#\/schema\/logo\/image\/","url":"https:\/\/contratame.online\/wp-content\/uploads\/2023\/07\/logohd.png","contentUrl":"https:\/\/contratame.online\/wp-content\/uploads\/2023\/07\/logohd.png","width":150,"height":50,"caption":"CONTRATA ME"},"image":{"@id":"https:\/\/contratame.online\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/contratamegt"]}]}},"metas":{"_candidate_location":{"167":"Guatemala"},"_candidate_age":"35","_candidate_gender":"Femenino","_candidate_phone":"43234111","_candidate_email":"Noemi1mh@gmail.com","_candidate_qualification":"Licenciatura","_candidate_job_title":"Administracion de empresas","_candidate_experience_time":"+6 A\u00f1os","_candidate_salary":"Q7,000","_candidate_languages":["Espa\u00f1ol"],"_candidate_skill":[{"title":"","percentage":""}],"_candidate_category":[],"_candidate_cv_attachment":{"77614":"https:\/\/contratame.online\/wp-content\/uploads\/2026\/08\/inbound1506277234398126228.pdf"},"_candidate_education":"","_candidate_experience":""},"_links":{"self":[{"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/candidate\/77612","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/candidate"}],"about":[{"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/types\/candidate"}],"replies":[{"embeddable":true,"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/comments?post=77612"}],"version-history":[{"count":1,"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/candidate\/77612\/revisions"}],"predecessor-version":[{"id":77613,"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/candidate\/77612\/revisions\/77613"}],"wp:attachment":[{"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/media?parent=77612"}],"wp:term":[{"taxonomy":"candidate_category","embeddable":true,"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/candidate_category?post=77612"},{"taxonomy":"candidate_location","embeddable":true,"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/candidate_location?post=77612"},{"taxonomy":"candidate_tag","embeddable":true,"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/candidate_tag?post=77612"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}