{"id":77661,"date":"2026-08-08T17:38:23","date_gmt":"2026-08-08T23:38:23","guid":{"rendered":"https:\/\/contratame.online\/es\/candidate\/dmalvarezj43\/"},"modified":"2026-08-08T17:48:14","modified_gmt":"2026-08-08T23:48:14","slug":"dmalvarezj43","status":"publish","type":"candidate","link":"https:\/\/contratame.online\/es\/candidate\/dmalvarezj43\/","title":{"rendered":"Dannia Maryte Alvarez Jimenez"},"content":{"rendered":"<p>Mi experiencia laboral se ha construido alrededor del trabajo t\u00e9cnico de laboratorio y la atenci\u00f3n a procesos con altos est\u00e1ndares de precisi\u00f3n. Como auxiliar de laboratorio y de c\u00e1tedra en Qu\u00edmica Org\u00e1nica I y II y An\u00e1lisis II en la Universidad Rafael Land\u00edvar, garantic\u00e9 el funcionamiento de dos laboratorios anal\u00edticos durante tres semestres consecutivos, preparando los materiales y reactivos necesarios para cada pr\u00e1ctica, supervisando a los estudiantes durante su ejecuci\u00f3n y verificando el cumplimiento de Buenas Pr\u00e1cticas de Laboratorio y normas de seguridad, sin un solo incidente registrado en todo el periodo. Adicionalmente, estuve a cargo de la evaluaci\u00f3n aut\u00f3noma de tareas y ex\u00e1menes. A esto se suma experiencia complementaria en atenci\u00f3n al cliente biling\u00fce dentro del sector alimentos, donde gestion\u00e9 reclamos sobre productos alimenticios y di seguimiento a incidencias de entrega con trazabilidad documental completa, desarrollando una sensibilidad pr\u00e1ctica hacia los puntos donde puede fallar la calidad de un producto una vez fuera de planta.<\/p>\n","protected":false},"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","candidate_category":[],"candidate_location":[167],"candidate_tag":[],"class_list":["post-77661","candidate","type-candidate","status-publish","hentry","candidate_location-guatemala"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Dannia Maryte Alvarez Jimenez - Contratame.online<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dannia Maryte Alvarez Jimenez - Contratame.online\" \/>\n<meta property=\"og:description\" content=\"Mi experiencia laboral se ha construido alrededor del trabajo t\u00e9cnico de laboratorio y la atenci\u00f3n a procesos con altos est\u00e1ndares de precisi\u00f3n. Como auxiliar de laboratorio y de c\u00e1tedra en Qu\u00edmica Org\u00e1nica I y II y An\u00e1lisis II en la Universidad Rafael Land\u00edvar, garantic\u00e9 el funcionamiento de dos laboratorios anal\u00edticos durante tres semestres consecutivos, preparando [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/contratame.online\/es\/candidate\/dmalvarezj43\/\" \/>\n<meta property=\"og:site_name\" content=\"Contratame.online\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/contratamegt\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-08T23:48:14+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/contratame.online\/es\/candidate\/dmalvarezj43\/\",\"url\":\"https:\/\/contratame.online\/es\/candidate\/dmalvarezj43\/\",\"name\":\"Dannia Maryte Alvarez Jimenez - Contratame.online\",\"isPartOf\":{\"@id\":\"https:\/\/contratame.online\/#website\"},\"datePublished\":\"2026-08-08T23:38:23+00:00\",\"dateModified\":\"2026-08-08T23:48:14+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/contratame.online\/es\/candidate\/dmalvarezj43\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/contratame.online\/es\/candidate\/dmalvarezj43\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/contratame.online\/es\/candidate\/dmalvarezj43\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/contratame.online\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Candidates\",\"item\":\"https:\/\/contratame.online\/en\/candidate\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Dannia Maryte Alvarez Jimenez\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/contratame.online\/#website\",\"url\":\"https:\/\/contratame.online\/\",\"name\":\"Contratame.online\",\"description\":\"Encuentra el empleo que siempre so\u00f1aste.\",\"publisher\":{\"@id\":\"https:\/\/contratame.online\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/contratame.online\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/contratame.online\/#organization\",\"name\":\"CONTRATA ME\",\"url\":\"https:\/\/contratame.online\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/contratame.online\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/contratame.online\/wp-content\/uploads\/2023\/07\/logohd.png\",\"contentUrl\":\"https:\/\/contratame.online\/wp-content\/uploads\/2023\/07\/logohd.png\",\"width\":150,\"height\":50,\"caption\":\"CONTRATA ME\"},\"image\":{\"@id\":\"https:\/\/contratame.online\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/contratamegt\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dannia Maryte Alvarez Jimenez - Contratame.online","robots":{"index":"noindex","follow":"follow"},"og_locale":"es_ES","og_type":"article","og_title":"Dannia Maryte Alvarez Jimenez - Contratame.online","og_description":"Mi experiencia laboral se ha construido alrededor del trabajo t\u00e9cnico de laboratorio y la atenci\u00f3n a procesos con altos est\u00e1ndares de precisi\u00f3n. Como auxiliar de laboratorio y de c\u00e1tedra en Qu\u00edmica Org\u00e1nica I y II y An\u00e1lisis II en la Universidad Rafael Land\u00edvar, garantic\u00e9 el funcionamiento de dos laboratorios anal\u00edticos durante tres semestres consecutivos, preparando [&hellip;]","og_url":"https:\/\/contratame.online\/es\/candidate\/dmalvarezj43\/","og_site_name":"Contratame.online","article_publisher":"https:\/\/www.facebook.com\/contratamegt","article_modified_time":"2026-08-08T23:48:14+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/contratame.online\/es\/candidate\/dmalvarezj43\/","url":"https:\/\/contratame.online\/es\/candidate\/dmalvarezj43\/","name":"Dannia Maryte Alvarez Jimenez - Contratame.online","isPartOf":{"@id":"https:\/\/contratame.online\/#website"},"datePublished":"2026-08-08T23:38:23+00:00","dateModified":"2026-08-08T23:48:14+00:00","breadcrumb":{"@id":"https:\/\/contratame.online\/es\/candidate\/dmalvarezj43\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/contratame.online\/es\/candidate\/dmalvarezj43\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/contratame.online\/es\/candidate\/dmalvarezj43\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/contratame.online\/"},{"@type":"ListItem","position":2,"name":"Candidates","item":"https:\/\/contratame.online\/en\/candidate\/"},{"@type":"ListItem","position":3,"name":"Dannia Maryte Alvarez Jimenez"}]},{"@type":"WebSite","@id":"https:\/\/contratame.online\/#website","url":"https:\/\/contratame.online\/","name":"Contratame.online","description":"Encuentra el empleo que siempre so\u00f1aste.","publisher":{"@id":"https:\/\/contratame.online\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/contratame.online\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/contratame.online\/#organization","name":"CONTRATA ME","url":"https:\/\/contratame.online\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/contratame.online\/#\/schema\/logo\/image\/","url":"https:\/\/contratame.online\/wp-content\/uploads\/2023\/07\/logohd.png","contentUrl":"https:\/\/contratame.online\/wp-content\/uploads\/2023\/07\/logohd.png","width":150,"height":50,"caption":"CONTRATA ME"},"image":{"@id":"https:\/\/contratame.online\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/contratamegt"]}]}},"metas":{"_candidate_location":{"167":"Guatemala"},"_candidate_age":"22","_candidate_gender":"Femenino","_candidate_phone":"45392389","_candidate_email":"dmalvarezj43@gmail.com","_candidate_qualification":"Licenciatura","_candidate_job_title":"Ingenier\u00eda en alimentos","_candidate_experience_time":"1 A\u00f1o","_candidate_salary":"","_candidate_languages":["Ingl\u00e9s"],"_candidate_skill":[{"title":"Laboratorios","percentage":"70"},{"title":"Calidad","percentage":"60"},{"title":"Liderazgo","percentage":"90"}],"_candidate_category":[],"_candidate_cv_attachment":{"77663":"https:\/\/contratame.online\/wp-content\/uploads\/2026\/08\/curriculum-vitae-dannia-alvarez_20260803_092326_0000.pdf"},"_candidate_education":"","_candidate_experience":""},"_links":{"self":[{"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/candidate\/77661","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/candidate"}],"about":[{"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/types\/candidate"}],"replies":[{"embeddable":true,"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/comments?post=77661"}],"version-history":[{"count":1,"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/candidate\/77661\/revisions"}],"predecessor-version":[{"id":77662,"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/candidate\/77661\/revisions\/77662"}],"wp:attachment":[{"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/media?parent=77661"}],"wp:term":[{"taxonomy":"candidate_category","embeddable":true,"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/candidate_category?post=77661"},{"taxonomy":"candidate_location","embeddable":true,"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/candidate_location?post=77661"},{"taxonomy":"candidate_tag","embeddable":true,"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/candidate_tag?post=77661"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}