{"id":77702,"date":"2026-08-08T19:24:18","date_gmt":"2026-08-09T01:24:18","guid":{"rendered":"https:\/\/contratame.online\/es\/candidate\/lesbiavicente84\/"},"modified":"2026-08-08T20:16:47","modified_gmt":"2026-08-09T02:16:47","slug":"lesbiavicente84","status":"publish","type":"candidate","link":"https:\/\/contratame.online\/es\/candidate\/lesbiavicente84\/","title":{"rendered":"Lesbia Lizeth Yax Vicente"},"content":{"rendered":"<p>Me he diferenciado por optimizar flujos de trabajo, reducir tiempos de gesti\u00f3n y coordinar reuniones y actividades sin contratiempos. Destaco por mi proactividad, agilidad y\u00a0 total discreci\u00f3n en procesos administrativos, garantizando que la gerencia cuente con todo listo para su labor.<\/p>\n","protected":false},"featured_media":77714,"comment_status":"open","ping_status":"closed","template":"","candidate_category":[],"candidate_location":[167],"candidate_tag":[],"class_list":["post-77702","candidate","type-candidate","status-publish","has-post-thumbnail","hentry","candidate_location-guatemala"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Lesbia Lizeth Yax Vicente - Contratame.online<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lesbia Lizeth Yax Vicente - Contratame.online\" \/>\n<meta property=\"og:description\" content=\"Me he diferenciado por optimizar flujos de trabajo, reducir tiempos de gesti\u00f3n y coordinar reuniones y actividades sin contratiempos. Destaco por mi proactividad, agilidad y\u00a0 total discreci\u00f3n en procesos administrativos, garantizando que la gerencia cuente con todo listo para su labor.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/contratame.online\/es\/candidate\/lesbiavicente84\/\" \/>\n<meta property=\"og:site_name\" content=\"Contratame.online\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/contratamegt\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-09T02:16:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/contratame.online\/wp-content\/uploads\/wp-job-board-pro-uploads\/_candidate_featured_image\/2026\/08\/Mi-foto-de-perfil-png.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1044\" \/>\n\t<meta property=\"og:image:height\" content=\"1656\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/contratame.online\/es\/candidate\/lesbiavicente84\/\",\"url\":\"https:\/\/contratame.online\/es\/candidate\/lesbiavicente84\/\",\"name\":\"Lesbia Lizeth Yax Vicente - Contratame.online\",\"isPartOf\":{\"@id\":\"https:\/\/contratame.online\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/contratame.online\/es\/candidate\/lesbiavicente84\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/contratame.online\/es\/candidate\/lesbiavicente84\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/contratame.online\/wp-content\/uploads\/wp-job-board-pro-uploads\/_candidate_featured_image\/2026\/08\/Mi-foto-de-perfil-png.png\",\"datePublished\":\"2026-08-09T01:24:18+00:00\",\"dateModified\":\"2026-08-09T02:16:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/contratame.online\/es\/candidate\/lesbiavicente84\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/contratame.online\/es\/candidate\/lesbiavicente84\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/contratame.online\/es\/candidate\/lesbiavicente84\/#primaryimage\",\"url\":\"https:\/\/contratame.online\/wp-content\/uploads\/wp-job-board-pro-uploads\/_candidate_featured_image\/2026\/08\/Mi-foto-de-perfil-png.png\",\"contentUrl\":\"https:\/\/contratame.online\/wp-content\/uploads\/wp-job-board-pro-uploads\/_candidate_featured_image\/2026\/08\/Mi-foto-de-perfil-png.png\",\"width\":1044,\"height\":1656},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/contratame.online\/es\/candidate\/lesbiavicente84\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/contratame.online\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Candidates\",\"item\":\"https:\/\/contratame.online\/en\/candidate\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Lesbia Lizeth Yax Vicente\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/contratame.online\/#website\",\"url\":\"https:\/\/contratame.online\/\",\"name\":\"Contratame.online\",\"description\":\"Encuentra el empleo que siempre so\u00f1aste.\",\"publisher\":{\"@id\":\"https:\/\/contratame.online\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/contratame.online\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/contratame.online\/#organization\",\"name\":\"CONTRATA ME\",\"url\":\"https:\/\/contratame.online\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/contratame.online\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/contratame.online\/wp-content\/uploads\/2023\/07\/logohd.png\",\"contentUrl\":\"https:\/\/contratame.online\/wp-content\/uploads\/2023\/07\/logohd.png\",\"width\":150,\"height\":50,\"caption\":\"CONTRATA ME\"},\"image\":{\"@id\":\"https:\/\/contratame.online\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/contratamegt\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lesbia Lizeth Yax Vicente - Contratame.online","robots":{"index":"noindex","follow":"follow"},"og_locale":"es_ES","og_type":"article","og_title":"Lesbia Lizeth Yax Vicente - Contratame.online","og_description":"Me he diferenciado por optimizar flujos de trabajo, reducir tiempos de gesti\u00f3n y coordinar reuniones y actividades sin contratiempos. Destaco por mi proactividad, agilidad y\u00a0 total discreci\u00f3n en procesos administrativos, garantizando que la gerencia cuente con todo listo para su labor.","og_url":"https:\/\/contratame.online\/es\/candidate\/lesbiavicente84\/","og_site_name":"Contratame.online","article_publisher":"https:\/\/www.facebook.com\/contratamegt","article_modified_time":"2026-08-09T02:16:47+00:00","og_image":[{"width":1044,"height":1656,"url":"https:\/\/contratame.online\/wp-content\/uploads\/wp-job-board-pro-uploads\/_candidate_featured_image\/2026\/08\/Mi-foto-de-perfil-png.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/contratame.online\/es\/candidate\/lesbiavicente84\/","url":"https:\/\/contratame.online\/es\/candidate\/lesbiavicente84\/","name":"Lesbia Lizeth Yax Vicente - Contratame.online","isPartOf":{"@id":"https:\/\/contratame.online\/#website"},"primaryImageOfPage":{"@id":"https:\/\/contratame.online\/es\/candidate\/lesbiavicente84\/#primaryimage"},"image":{"@id":"https:\/\/contratame.online\/es\/candidate\/lesbiavicente84\/#primaryimage"},"thumbnailUrl":"https:\/\/contratame.online\/wp-content\/uploads\/wp-job-board-pro-uploads\/_candidate_featured_image\/2026\/08\/Mi-foto-de-perfil-png.png","datePublished":"2026-08-09T01:24:18+00:00","dateModified":"2026-08-09T02:16:47+00:00","breadcrumb":{"@id":"https:\/\/contratame.online\/es\/candidate\/lesbiavicente84\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/contratame.online\/es\/candidate\/lesbiavicente84\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/contratame.online\/es\/candidate\/lesbiavicente84\/#primaryimage","url":"https:\/\/contratame.online\/wp-content\/uploads\/wp-job-board-pro-uploads\/_candidate_featured_image\/2026\/08\/Mi-foto-de-perfil-png.png","contentUrl":"https:\/\/contratame.online\/wp-content\/uploads\/wp-job-board-pro-uploads\/_candidate_featured_image\/2026\/08\/Mi-foto-de-perfil-png.png","width":1044,"height":1656},{"@type":"BreadcrumbList","@id":"https:\/\/contratame.online\/es\/candidate\/lesbiavicente84\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/contratame.online\/"},{"@type":"ListItem","position":2,"name":"Candidates","item":"https:\/\/contratame.online\/en\/candidate\/"},{"@type":"ListItem","position":3,"name":"Lesbia Lizeth Yax Vicente"}]},{"@type":"WebSite","@id":"https:\/\/contratame.online\/#website","url":"https:\/\/contratame.online\/","name":"Contratame.online","description":"Encuentra el empleo que siempre so\u00f1aste.","publisher":{"@id":"https:\/\/contratame.online\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/contratame.online\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/contratame.online\/#organization","name":"CONTRATA ME","url":"https:\/\/contratame.online\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/contratame.online\/#\/schema\/logo\/image\/","url":"https:\/\/contratame.online\/wp-content\/uploads\/2023\/07\/logohd.png","contentUrl":"https:\/\/contratame.online\/wp-content\/uploads\/2023\/07\/logohd.png","width":150,"height":50,"caption":"CONTRATA ME"},"image":{"@id":"https:\/\/contratame.online\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/contratamegt"]}]}},"metas":{"_candidate_location":{"167":"Guatemala"},"_candidate_age":"41","_candidate_gender":"Femenino","_candidate_phone":"42658443","_candidate_email":"lesbiavicente84@gmail.com","_candidate_qualification":"Diversificado","_candidate_job_title":"Secretaria de gerencia","_candidate_experience_time":"+6 A\u00f1os","_candidate_salary":"","_candidate_languages":["Espa\u00f1ol"],"_candidate_skill":[{"title":"Pensamiento anal\u00edtico","percentage":"90"},{"title":"Resoluci\u00f3n de problemas","percentage":"95"},{"title":"Atenci\u00f3n al detalle","percentage":"90"},{"title":"Gesti\u00f3n de tr\u00e1mites","percentage":"98"},{"title":"Responsabilidad","percentage":"100"},{"title":"Adaptabilidad","percentage":"100"},{"title":"Manejo de Microsoft office","percentage":"75"}],"_candidate_category":[],"_candidate_cv_attachment":{"77704":"https:\/\/contratame.online\/wp-content\/uploads\/2026\/08\/CV-Lebia-Yax-2026.pdf"},"_candidate_education":"","_candidate_experience":"","_candidate_logo":"https:\/\/contratame.online\/wp-content\/uploads\/wp-job-board-pro-uploads\/_candidate_featured_image\/2026\/08\/Mi-foto-de-perfil-png-150x150.png"},"_links":{"self":[{"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/candidate\/77702","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/candidate"}],"about":[{"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/types\/candidate"}],"replies":[{"embeddable":true,"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/comments?post=77702"}],"version-history":[{"count":1,"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/candidate\/77702\/revisions"}],"predecessor-version":[{"id":77703,"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/candidate\/77702\/revisions\/77703"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/media\/77714"}],"wp:attachment":[{"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/media?parent=77702"}],"wp:term":[{"taxonomy":"candidate_category","embeddable":true,"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/candidate_category?post=77702"},{"taxonomy":"candidate_location","embeddable":true,"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/candidate_location?post=77702"},{"taxonomy":"candidate_tag","embeddable":true,"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/candidate_tag?post=77702"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}