{"id":77736,"date":"2026-08-08T21:22:29","date_gmt":"2026-08-09T03:22:29","guid":{"rendered":"https:\/\/contratame.online\/es\/candidate\/ochoaadriana352\/"},"modified":"2026-08-12T09:09:41","modified_gmt":"2026-08-12T15:09:41","slug":"ochoaadriana352","status":"publish","type":"candidate","link":"https:\/\/contratame.online\/es\/candidate\/ochoaadriana352\/","title":{"rendered":"Adriana Del Rosario Perdomo Ochoa"},"content":{"rendered":"<p>Soy una persona que tiene mucha empat\u00eda con el servicio al cliente, he aprendido a desarrollar mi capacidad de resolver y mejorado mi inteligencia emocional trabajando bajo presion, he aprendido a trasmitir de forma amable y directa la soluci\u00f3n al cliente ayudandolos en el proceso, en mi ultimo trabajo estuve a cargo del \u00e1rea de captura y digitaci\u00f3n de datos verificando informaci\u00f3n de 6 pa\u00edses (centroam\u00e9rica y el caribe) bridando atenci\u00f3n a socias interesadas en afilirse para vender productos de belleza por cat\u00e1logo.<\/p>\n","protected":false},"featured_media":77752,"comment_status":"open","ping_status":"closed","template":"","candidate_category":[],"candidate_location":[167],"candidate_tag":[],"class_list":["post-77736","candidate","type-candidate","status-publish","has-post-thumbnail","hentry","candidate_location-guatemala"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Adriana Del Rosario Perdomo Ochoa - Contratame.online<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Adriana Del Rosario Perdomo Ochoa - Contratame.online\" \/>\n<meta property=\"og:description\" content=\"Soy una persona que tiene mucha empat\u00eda con el servicio al cliente, he aprendido a desarrollar mi capacidad de resolver y mejorado mi inteligencia emocional trabajando bajo presion, he aprendido a trasmitir de forma amable y directa la soluci\u00f3n al cliente ayudandolos en el proceso, en mi ultimo trabajo estuve a cargo del \u00e1rea de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/contratame.online\/es\/candidate\/ochoaadriana352\/\" \/>\n<meta property=\"og:site_name\" content=\"Contratame.online\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/contratamegt\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-12T15:09:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/contratame.online\/wp-content\/uploads\/wp-job-board-pro-uploads\/_candidate_featured_image\/2026\/08\/IMG-20221218-WA0064.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1079\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/contratame.online\/es\/candidate\/ochoaadriana352\/\",\"url\":\"https:\/\/contratame.online\/es\/candidate\/ochoaadriana352\/\",\"name\":\"Adriana Del Rosario Perdomo Ochoa - Contratame.online\",\"isPartOf\":{\"@id\":\"https:\/\/contratame.online\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/contratame.online\/es\/candidate\/ochoaadriana352\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/contratame.online\/es\/candidate\/ochoaadriana352\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/contratame.online\/wp-content\/uploads\/wp-job-board-pro-uploads\/_candidate_featured_image\/2026\/08\/IMG-20221218-WA0064.jpg\",\"datePublished\":\"2026-08-09T03:22:29+00:00\",\"dateModified\":\"2026-08-12T15:09:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/contratame.online\/es\/candidate\/ochoaadriana352\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/contratame.online\/es\/candidate\/ochoaadriana352\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/contratame.online\/es\/candidate\/ochoaadriana352\/#primaryimage\",\"url\":\"https:\/\/contratame.online\/wp-content\/uploads\/wp-job-board-pro-uploads\/_candidate_featured_image\/2026\/08\/IMG-20221218-WA0064.jpg\",\"contentUrl\":\"https:\/\/contratame.online\/wp-content\/uploads\/wp-job-board-pro-uploads\/_candidate_featured_image\/2026\/08\/IMG-20221218-WA0064.jpg\",\"width\":1080,\"height\":1079},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/contratame.online\/es\/candidate\/ochoaadriana352\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/contratame.online\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Candidates\",\"item\":\"https:\/\/contratame.online\/en\/candidate\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Adriana Del Rosario Perdomo Ochoa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/contratame.online\/#website\",\"url\":\"https:\/\/contratame.online\/\",\"name\":\"Contratame.online\",\"description\":\"Encuentra el empleo que siempre so\u00f1aste.\",\"publisher\":{\"@id\":\"https:\/\/contratame.online\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/contratame.online\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/contratame.online\/#organization\",\"name\":\"CONTRATA ME\",\"url\":\"https:\/\/contratame.online\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/contratame.online\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/contratame.online\/wp-content\/uploads\/2023\/07\/logohd.png\",\"contentUrl\":\"https:\/\/contratame.online\/wp-content\/uploads\/2023\/07\/logohd.png\",\"width\":150,\"height\":50,\"caption\":\"CONTRATA ME\"},\"image\":{\"@id\":\"https:\/\/contratame.online\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/contratamegt\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Adriana Del Rosario Perdomo Ochoa - Contratame.online","robots":{"index":"noindex","follow":"follow"},"og_locale":"es_ES","og_type":"article","og_title":"Adriana Del Rosario Perdomo Ochoa - Contratame.online","og_description":"Soy una persona que tiene mucha empat\u00eda con el servicio al cliente, he aprendido a desarrollar mi capacidad de resolver y mejorado mi inteligencia emocional trabajando bajo presion, he aprendido a trasmitir de forma amable y directa la soluci\u00f3n al cliente ayudandolos en el proceso, en mi ultimo trabajo estuve a cargo del \u00e1rea de [&hellip;]","og_url":"https:\/\/contratame.online\/es\/candidate\/ochoaadriana352\/","og_site_name":"Contratame.online","article_publisher":"https:\/\/www.facebook.com\/contratamegt","article_modified_time":"2026-08-12T15:09:41+00:00","og_image":[{"width":1080,"height":1079,"url":"https:\/\/contratame.online\/wp-content\/uploads\/wp-job-board-pro-uploads\/_candidate_featured_image\/2026\/08\/IMG-20221218-WA0064.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/contratame.online\/es\/candidate\/ochoaadriana352\/","url":"https:\/\/contratame.online\/es\/candidate\/ochoaadriana352\/","name":"Adriana Del Rosario Perdomo Ochoa - Contratame.online","isPartOf":{"@id":"https:\/\/contratame.online\/#website"},"primaryImageOfPage":{"@id":"https:\/\/contratame.online\/es\/candidate\/ochoaadriana352\/#primaryimage"},"image":{"@id":"https:\/\/contratame.online\/es\/candidate\/ochoaadriana352\/#primaryimage"},"thumbnailUrl":"https:\/\/contratame.online\/wp-content\/uploads\/wp-job-board-pro-uploads\/_candidate_featured_image\/2026\/08\/IMG-20221218-WA0064.jpg","datePublished":"2026-08-09T03:22:29+00:00","dateModified":"2026-08-12T15:09:41+00:00","breadcrumb":{"@id":"https:\/\/contratame.online\/es\/candidate\/ochoaadriana352\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/contratame.online\/es\/candidate\/ochoaadriana352\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/contratame.online\/es\/candidate\/ochoaadriana352\/#primaryimage","url":"https:\/\/contratame.online\/wp-content\/uploads\/wp-job-board-pro-uploads\/_candidate_featured_image\/2026\/08\/IMG-20221218-WA0064.jpg","contentUrl":"https:\/\/contratame.online\/wp-content\/uploads\/wp-job-board-pro-uploads\/_candidate_featured_image\/2026\/08\/IMG-20221218-WA0064.jpg","width":1080,"height":1079},{"@type":"BreadcrumbList","@id":"https:\/\/contratame.online\/es\/candidate\/ochoaadriana352\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/contratame.online\/"},{"@type":"ListItem","position":2,"name":"Candidates","item":"https:\/\/contratame.online\/en\/candidate\/"},{"@type":"ListItem","position":3,"name":"Adriana Del Rosario Perdomo Ochoa"}]},{"@type":"WebSite","@id":"https:\/\/contratame.online\/#website","url":"https:\/\/contratame.online\/","name":"Contratame.online","description":"Encuentra el empleo que siempre so\u00f1aste.","publisher":{"@id":"https:\/\/contratame.online\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/contratame.online\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/contratame.online\/#organization","name":"CONTRATA ME","url":"https:\/\/contratame.online\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/contratame.online\/#\/schema\/logo\/image\/","url":"https:\/\/contratame.online\/wp-content\/uploads\/2023\/07\/logohd.png","contentUrl":"https:\/\/contratame.online\/wp-content\/uploads\/2023\/07\/logohd.png","width":150,"height":50,"caption":"CONTRATA ME"},"image":{"@id":"https:\/\/contratame.online\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/contratamegt"]}]}},"metas":{"_candidate_location":{"167":"Guatemala"},"_candidate_age":"36","_candidate_gender":"Femenino","_candidate_phone":"54968466","_candidate_email":"ochoaadriana352@gmail.com","_candidate_qualification":"Diversificado","_candidate_job_title":"Secretaria Biling\u00fce","_candidate_experience_time":"+6 A\u00f1os","_candidate_salary":"","_candidate_languages":["Espa\u00f1ol"],"_candidate_skill":[{"title":"Servicio al cliente","percentage":"90"},{"title":"Resoluci\u00f3n de problemas","percentage":"90"},{"title":"Escucha activa","percentage":"85"},{"title":"Captura de informaci\u00f3n y revisi\u00f3n de documentos","percentage":"95"}],"_candidate_category":[],"_candidate_cv_attachment":{"77738":"https:\/\/contratame.online\/wp-content\/uploads\/2026\/08\/Curriculum-Vitae-CV-Profesional-Beige_20260807_121636_0000.pdf_20260808_212120_0000.pdf"},"_candidate_education":[{"title":"Secretaria Biling\u00fce","academy":"Colegio VillaFlor","year":"2008","description":"Me gradu\u00e9 en el 2008 como secretaria Biling\u00fce, realizando mis pr\u00e1cticas en el \u00e1rea de secretaria de la cl\u00ednica m\u00e9dica de la Cervecer\u00eda Centroamericana"},{"title":"Ciencias Jur\u00eddicas y Sociales","academy":"Universidad Mariano Galvez","year":"2020","description":"Estudios pausados debido al horario de trabajo, sin embargo este a\u00f1o que viene retomar\u00e9 los estudios nuevamente."}],"_candidate_experience":[{"title":"Agente de Contacto Center","start_date":"2015","end_date":"2018","company":"Banco Agromercantil","description":"Atenci\u00f3n de llamadas, manejo de correos, chat y redes sociales, brindado informaci\u00f3n sobre productos adquiridos por el cliente.\r\n\r\nEstuve en el \u00e1rea de cliente VIP a quienes se les gestionaba su solicitud por tel\u00e9fono para cuando llegara agencia ya estuviera todo listo para que ellos autorizar\u00e1n."},{"title":"Analista de Reclamos","start_date":"2018","end_date":"2021","company":"Banco Agromercantil","description":"Analista de Reclamos de clientes presenciales y v\u00eda tel\u00e9fono, gestionaba solicitudes de cuentas inactivas, cuentas canceladas, reclamos por cobros no reconocidos, billetes falsos, revisi\u00f3n con otras \u00e1reas sobre fraudes y robos.\r\n\r\nInternamente ve\u00eda cargos de sobrantes o faltantes a receptores."},{"title":"Analista de Reclamos","start_date":"2022","end_date":"2024","company":"Forza Delivery","description":"Realizaba la revisi\u00f3n de reclamos por extravio o robo de paqueter\u00eda, as\u00ed como la paqueter\u00eda da\u00f1ada, realizaba compromisos de pago al encontrar a un responsable, entrega de reporteria detallada al \u00e1rea contable sobre pago de reclamos, as\u00ed como la entrega de inventario sobre productos a destrucci\u00f3n y enviados a bodega"},{"title":"Operador Directo Servicio al Socio","start_date":"2024","end_date":"2026","company":"Oriflame de Guatemala","description":"Atenci\u00f3n de llamadas a socios de centroam\u00e9rica y el caribe brindado informaci\u00f3n sobre productos de campa\u00f1a vigente (cat\u00e1logo) toma de pedido, recepci\u00f3n de pagos en diferentes plataformas,revisi\u00f3n y captura de informaci\u00f3n de socios para creditos as\u00ed como afiliaciones para socios nuevos."}],"_candidate_logo":"https:\/\/contratame.online\/wp-content\/uploads\/wp-job-board-pro-uploads\/_candidate_featured_image\/2026\/08\/IMG-20221218-WA0064-150x150.jpg"},"_links":{"self":[{"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/candidate\/77736","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/candidate"}],"about":[{"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/types\/candidate"}],"replies":[{"embeddable":true,"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/comments?post=77736"}],"version-history":[{"count":1,"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/candidate\/77736\/revisions"}],"predecessor-version":[{"id":77737,"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/candidate\/77736\/revisions\/77737"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/media\/77752"}],"wp:attachment":[{"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/media?parent=77736"}],"wp:term":[{"taxonomy":"candidate_category","embeddable":true,"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/candidate_category?post=77736"},{"taxonomy":"candidate_location","embeddable":true,"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/candidate_location?post=77736"},{"taxonomy":"candidate_tag","embeddable":true,"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/candidate_tag?post=77736"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}