{"id":79196,"date":"2026-08-10T20:41:27","date_gmt":"2026-08-11T02:41:27","guid":{"rendered":"https:\/\/contratame.online\/es\/candidate\/obregsilvana\/"},"modified":"2026-08-10T20:43:47","modified_gmt":"2026-08-11T02:43:47","slug":"obregsilvana","status":"publish","type":"candidate","link":"https:\/\/contratame.online\/es\/candidate\/obregsilvana\/","title":{"rendered":"obregsilvana"},"content":{"rendered":"<p>Mi \u00fanica experiencia laboral ha sido en callcenter, gane experiencia en servicio al cliente, bancos, escucha activa, etc<\/p>\n","protected":false},"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","candidate_category":[],"candidate_location":[167],"candidate_tag":[],"class_list":["post-79196","candidate","type-candidate","status-publish","hentry","candidate_location-guatemala"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>obregsilvana - Contratame.online<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"obregsilvana - Contratame.online\" \/>\n<meta property=\"og:description\" content=\"Mi \u00fanica experiencia laboral ha sido en callcenter, gane experiencia en servicio al cliente, bancos, escucha activa, etc\" \/>\n<meta property=\"og:url\" content=\"https:\/\/contratame.online\/es\/candidate\/obregsilvana\/\" \/>\n<meta property=\"og:site_name\" content=\"Contratame.online\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/contratamegt\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-11T02:43:47+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/contratame.online\/es\/candidate\/obregsilvana\/\",\"url\":\"https:\/\/contratame.online\/es\/candidate\/obregsilvana\/\",\"name\":\"obregsilvana - Contratame.online\",\"isPartOf\":{\"@id\":\"https:\/\/contratame.online\/#website\"},\"datePublished\":\"2026-08-11T02:41:27+00:00\",\"dateModified\":\"2026-08-11T02:43:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/contratame.online\/es\/candidate\/obregsilvana\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/contratame.online\/es\/candidate\/obregsilvana\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/contratame.online\/es\/candidate\/obregsilvana\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/contratame.online\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Candidates\",\"item\":\"https:\/\/contratame.online\/en\/candidate\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"obregsilvana\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/contratame.online\/#website\",\"url\":\"https:\/\/contratame.online\/\",\"name\":\"Contratame.online\",\"description\":\"Encuentra el empleo que siempre so\u00f1aste.\",\"publisher\":{\"@id\":\"https:\/\/contratame.online\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/contratame.online\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/contratame.online\/#organization\",\"name\":\"CONTRATA ME\",\"url\":\"https:\/\/contratame.online\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/contratame.online\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/contratame.online\/wp-content\/uploads\/2023\/07\/logohd.png\",\"contentUrl\":\"https:\/\/contratame.online\/wp-content\/uploads\/2023\/07\/logohd.png\",\"width\":150,\"height\":50,\"caption\":\"CONTRATA ME\"},\"image\":{\"@id\":\"https:\/\/contratame.online\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/contratamegt\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"obregsilvana - Contratame.online","robots":{"index":"noindex","follow":"follow"},"og_locale":"es_ES","og_type":"article","og_title":"obregsilvana - Contratame.online","og_description":"Mi \u00fanica experiencia laboral ha sido en callcenter, gane experiencia en servicio al cliente, bancos, escucha activa, etc","og_url":"https:\/\/contratame.online\/es\/candidate\/obregsilvana\/","og_site_name":"Contratame.online","article_publisher":"https:\/\/www.facebook.com\/contratamegt","article_modified_time":"2026-08-11T02:43:47+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/contratame.online\/es\/candidate\/obregsilvana\/","url":"https:\/\/contratame.online\/es\/candidate\/obregsilvana\/","name":"obregsilvana - Contratame.online","isPartOf":{"@id":"https:\/\/contratame.online\/#website"},"datePublished":"2026-08-11T02:41:27+00:00","dateModified":"2026-08-11T02:43:47+00:00","breadcrumb":{"@id":"https:\/\/contratame.online\/es\/candidate\/obregsilvana\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/contratame.online\/es\/candidate\/obregsilvana\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/contratame.online\/es\/candidate\/obregsilvana\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/contratame.online\/"},{"@type":"ListItem","position":2,"name":"Candidates","item":"https:\/\/contratame.online\/en\/candidate\/"},{"@type":"ListItem","position":3,"name":"obregsilvana"}]},{"@type":"WebSite","@id":"https:\/\/contratame.online\/#website","url":"https:\/\/contratame.online\/","name":"Contratame.online","description":"Encuentra el empleo que siempre so\u00f1aste.","publisher":{"@id":"https:\/\/contratame.online\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/contratame.online\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/contratame.online\/#organization","name":"CONTRATA ME","url":"https:\/\/contratame.online\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/contratame.online\/#\/schema\/logo\/image\/","url":"https:\/\/contratame.online\/wp-content\/uploads\/2023\/07\/logohd.png","contentUrl":"https:\/\/contratame.online\/wp-content\/uploads\/2023\/07\/logohd.png","width":150,"height":50,"caption":"CONTRATA ME"},"image":{"@id":"https:\/\/contratame.online\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/contratamegt"]}]}},"metas":{"_candidate_location":{"167":"Guatemala"},"_candidate_age":"20","_candidate_gender":"Femenino","_candidate_phone":"57113148","_candidate_email":"obregsilvana@gmail.com","_candidate_qualification":"Diversificado","_candidate_job_title":"Estudiante","_candidate_experience_time":"1 A\u00f1o","_candidate_salary":"Q5,000","_candidate_languages":["Espa\u00f1ol","Ingl\u00e9s"],"_candidate_skill":"","_candidate_category":[],"_candidate_cv_attachment":{"79198":"https:\/\/contratame.online\/wp-content\/uploads\/2026\/08\/Curriculum-Abigail-Obregon_20260615_114817_0000.pdf"},"_candidate_education":"","_candidate_experience":""},"_links":{"self":[{"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/candidate\/79196","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/candidate"}],"about":[{"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/types\/candidate"}],"replies":[{"embeddable":true,"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/comments?post=79196"}],"version-history":[{"count":1,"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/candidate\/79196\/revisions"}],"predecessor-version":[{"id":79197,"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/candidate\/79196\/revisions\/79197"}],"wp:attachment":[{"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/media?parent=79196"}],"wp:term":[{"taxonomy":"candidate_category","embeddable":true,"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/candidate_category?post=79196"},{"taxonomy":"candidate_location","embeddable":true,"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/candidate_location?post=79196"},{"taxonomy":"candidate_tag","embeddable":true,"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/candidate_tag?post=79196"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}