{"id":79436,"date":"2026-08-11T08:47:25","date_gmt":"2026-08-11T14:47:25","guid":{"rendered":"https:\/\/contratame.online\/es\/candidate\/keygramajo17\/"},"modified":"2026-08-11T08:56:16","modified_gmt":"2026-08-11T14:56:16","slug":"keygramajo17","status":"publish","type":"candidate","link":"https:\/\/contratame.online\/es\/candidate\/keygramajo17\/","title":{"rendered":"keygramajo17"},"content":{"rendered":"<p style=\"text-align: left\">Trabaje en Delega Abogados como Gestor de Cobros<\/p>\n<p>Funciones como Gestor de Cobros eran las siguientes<\/p>\n<p>Investigar al clientes y una base de batos.<\/p>\n<p>Llamar al cliente para cobrarle cerrar la negociaci\u00f3n.<\/p>\n<p>Contestar en WhatsApp sus consultas.<\/p>\n","protected":false},"featured_media":79443,"comment_status":"open","ping_status":"closed","template":"","candidate_category":[285],"candidate_location":[167],"candidate_tag":[],"class_list":["post-79436","candidate","type-candidate","status-publish","has-post-thumbnail","hentry","candidate_category-programador","candidate_location-guatemala"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>keygramajo17 - Contratame.online<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"keygramajo17 - Contratame.online\" \/>\n<meta property=\"og:description\" content=\"Trabaje en Delega Abogados como Gestor de Cobros Funciones como Gestor de Cobros eran las siguientes Investigar al clientes y una base de batos. Llamar al cliente para cobrarle cerrar la negociaci\u00f3n. Contestar en WhatsApp sus consultas.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/contratame.online\/es\/candidate\/keygramajo17\/\" \/>\n<meta property=\"og:site_name\" content=\"Contratame.online\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/contratamegt\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-11T14:56:16+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/contratame.online\/es\/candidate\/keygramajo17\/\",\"url\":\"https:\/\/contratame.online\/es\/candidate\/keygramajo17\/\",\"name\":\"keygramajo17 - Contratame.online\",\"isPartOf\":{\"@id\":\"https:\/\/contratame.online\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/contratame.online\/es\/candidate\/keygramajo17\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/contratame.online\/es\/candidate\/keygramajo17\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/contratame.online\/wp-content\/uploads\/wp-job-board-pro-uploads\/_candidate_featured_image\/2026\/08\/IMG-20260811-WA0003.jpg\",\"datePublished\":\"2026-08-11T14:47:25+00:00\",\"dateModified\":\"2026-08-11T14:56:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/contratame.online\/es\/candidate\/keygramajo17\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/contratame.online\/es\/candidate\/keygramajo17\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/contratame.online\/es\/candidate\/keygramajo17\/#primaryimage\",\"url\":\"https:\/\/contratame.online\/wp-content\/uploads\/wp-job-board-pro-uploads\/_candidate_featured_image\/2026\/08\/IMG-20260811-WA0003.jpg\",\"contentUrl\":\"https:\/\/contratame.online\/wp-content\/uploads\/wp-job-board-pro-uploads\/_candidate_featured_image\/2026\/08\/IMG-20260811-WA0003.jpg\",\"width\":1201,\"height\":1600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/contratame.online\/es\/candidate\/keygramajo17\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/contratame.online\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Candidates\",\"item\":\"https:\/\/contratame.online\/en\/candidate\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"keygramajo17\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/contratame.online\/#website\",\"url\":\"https:\/\/contratame.online\/\",\"name\":\"Contratame.online\",\"description\":\"Encuentra el empleo que siempre so\u00f1aste.\",\"publisher\":{\"@id\":\"https:\/\/contratame.online\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/contratame.online\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/contratame.online\/#organization\",\"name\":\"CONTRATA ME\",\"url\":\"https:\/\/contratame.online\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/contratame.online\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/contratame.online\/wp-content\/uploads\/2023\/07\/logohd.png\",\"contentUrl\":\"https:\/\/contratame.online\/wp-content\/uploads\/2023\/07\/logohd.png\",\"width\":150,\"height\":50,\"caption\":\"CONTRATA ME\"},\"image\":{\"@id\":\"https:\/\/contratame.online\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/contratamegt\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"keygramajo17 - Contratame.online","robots":{"index":"noindex","follow":"follow"},"og_locale":"es_ES","og_type":"article","og_title":"keygramajo17 - Contratame.online","og_description":"Trabaje en Delega Abogados como Gestor de Cobros Funciones como Gestor de Cobros eran las siguientes Investigar al clientes y una base de batos. Llamar al cliente para cobrarle cerrar la negociaci\u00f3n. Contestar en WhatsApp sus consultas.","og_url":"https:\/\/contratame.online\/es\/candidate\/keygramajo17\/","og_site_name":"Contratame.online","article_publisher":"https:\/\/www.facebook.com\/contratamegt","article_modified_time":"2026-08-11T14:56:16+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/contratame.online\/es\/candidate\/keygramajo17\/","url":"https:\/\/contratame.online\/es\/candidate\/keygramajo17\/","name":"keygramajo17 - Contratame.online","isPartOf":{"@id":"https:\/\/contratame.online\/#website"},"primaryImageOfPage":{"@id":"https:\/\/contratame.online\/es\/candidate\/keygramajo17\/#primaryimage"},"image":{"@id":"https:\/\/contratame.online\/es\/candidate\/keygramajo17\/#primaryimage"},"thumbnailUrl":"https:\/\/contratame.online\/wp-content\/uploads\/wp-job-board-pro-uploads\/_candidate_featured_image\/2026\/08\/IMG-20260811-WA0003.jpg","datePublished":"2026-08-11T14:47:25+00:00","dateModified":"2026-08-11T14:56:16+00:00","breadcrumb":{"@id":"https:\/\/contratame.online\/es\/candidate\/keygramajo17\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/contratame.online\/es\/candidate\/keygramajo17\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/contratame.online\/es\/candidate\/keygramajo17\/#primaryimage","url":"https:\/\/contratame.online\/wp-content\/uploads\/wp-job-board-pro-uploads\/_candidate_featured_image\/2026\/08\/IMG-20260811-WA0003.jpg","contentUrl":"https:\/\/contratame.online\/wp-content\/uploads\/wp-job-board-pro-uploads\/_candidate_featured_image\/2026\/08\/IMG-20260811-WA0003.jpg","width":1201,"height":1600},{"@type":"BreadcrumbList","@id":"https:\/\/contratame.online\/es\/candidate\/keygramajo17\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/contratame.online\/"},{"@type":"ListItem","position":2,"name":"Candidates","item":"https:\/\/contratame.online\/en\/candidate\/"},{"@type":"ListItem","position":3,"name":"keygramajo17"}]},{"@type":"WebSite","@id":"https:\/\/contratame.online\/#website","url":"https:\/\/contratame.online\/","name":"Contratame.online","description":"Encuentra el empleo que siempre so\u00f1aste.","publisher":{"@id":"https:\/\/contratame.online\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/contratame.online\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/contratame.online\/#organization","name":"CONTRATA ME","url":"https:\/\/contratame.online\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/contratame.online\/#\/schema\/logo\/image\/","url":"https:\/\/contratame.online\/wp-content\/uploads\/2023\/07\/logohd.png","contentUrl":"https:\/\/contratame.online\/wp-content\/uploads\/2023\/07\/logohd.png","width":150,"height":50,"caption":"CONTRATA ME"},"image":{"@id":"https:\/\/contratame.online\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/contratamegt"]}]}},"metas":{"_candidate_location":{"167":"Guatemala"},"_candidate_age":"22","_candidate_gender":"Femenino","_candidate_phone":"4677-0026","_candidate_email":"keygramajo17@gmail.com","_candidate_qualification":"Diversificado","_candidate_job_title":"Estudiante","_candidate_experience_time":"Sin experiencia","_candidate_salary":"","_candidate_languages":["Espa\u00f1ol"],"_candidate_skill":"","_candidate_category":{"285":"Programador"},"_candidate_cv_attachment":{"79438":"https:\/\/contratame.online\/wp-content\/uploads\/2026\/08\/Keyla-Cruz-CV.pdf","79444":"https:\/\/contratame.online\/wp-content\/uploads\/wp-job-board-pro-uploads\/_candidate_cv_attachment\/2026\/08\/Keyla-Cruz-CV.pdf","81601":"https:\/\/contratame.online\/wp-content\/uploads\/wp-job-board-pro-uploads\/_candidate_cv_attachment\/2026\/08\/Keyla-Cruz-CV-1.pdf"},"_candidate_education":"","_candidate_experience":"","_candidate_logo":"https:\/\/contratame.online\/wp-content\/uploads\/wp-job-board-pro-uploads\/_candidate_featured_image\/2026\/08\/IMG-20260811-WA0003-150x150.jpg"},"_links":{"self":[{"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/candidate\/79436","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/candidate"}],"about":[{"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/types\/candidate"}],"replies":[{"embeddable":true,"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/comments?post=79436"}],"version-history":[{"count":1,"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/candidate\/79436\/revisions"}],"predecessor-version":[{"id":79437,"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/candidate\/79436\/revisions\/79437"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/media\/79443"}],"wp:attachment":[{"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/media?parent=79436"}],"wp:term":[{"taxonomy":"candidate_category","embeddable":true,"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/candidate_category?post=79436"},{"taxonomy":"candidate_location","embeddable":true,"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/candidate_location?post=79436"},{"taxonomy":"candidate_tag","embeddable":true,"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/candidate_tag?post=79436"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}