{"id":79618,"date":"2026-08-11T12:14:20","date_gmt":"2026-08-11T18:14:20","guid":{"rendered":"https:\/\/contratame.online\/es\/candidate\/kennygc10\/"},"modified":"2026-08-12T16:10:06","modified_gmt":"2026-08-12T22:10:06","slug":"kennygc10","status":"publish","type":"candidate","link":"https:\/\/contratame.online\/es\/candidate\/kennygc10\/","title":{"rendered":"KENNY ESTUARDO GARC\u00cdA CAAL"},"content":{"rendered":"<p>Soy una persona responsable, con ganas de aprender y de trabajar. Me adapto f\u00e1cilmente a diferentes tareas y me gusta trabajar en equipo. Siempre trato de dar lo mejor de m\u00ed, cumplir con mi trabajo y aprender cosas nuevas. Tambi\u00e9n tengo conocimientos b\u00e1sicos de computaci\u00f3n y busco una oportunidad para seguir creciendo tanto en lo personal como en lo profesional.<\/p>\n<p>NO TENGO EXPERIENCIA PERO ESTOY DISPUESTO A APRENDER<\/p>\n","protected":false},"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","candidate_category":[],"candidate_location":[167],"candidate_tag":[],"class_list":["post-79618","candidate","type-candidate","status-publish","hentry","candidate_location-guatemala"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>KENNY ESTUARDO GARC\u00cdA CAAL - Contratame.online<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"KENNY ESTUARDO GARC\u00cdA CAAL - Contratame.online\" \/>\n<meta property=\"og:description\" content=\"Soy una persona responsable, con ganas de aprender y de trabajar. Me adapto f\u00e1cilmente a diferentes tareas y me gusta trabajar en equipo. Siempre trato de dar lo mejor de m\u00ed, cumplir con mi trabajo y aprender cosas nuevas. Tambi\u00e9n tengo conocimientos b\u00e1sicos de computaci\u00f3n y busco una oportunidad para seguir creciendo tanto en lo [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/contratame.online\/es\/candidate\/kennygc10\/\" \/>\n<meta property=\"og:site_name\" content=\"Contratame.online\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/contratamegt\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-12T22:10:06+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/contratame.online\/es\/candidate\/kennygc10\/\",\"url\":\"https:\/\/contratame.online\/es\/candidate\/kennygc10\/\",\"name\":\"KENNY ESTUARDO GARC\u00cdA CAAL - Contratame.online\",\"isPartOf\":{\"@id\":\"https:\/\/contratame.online\/#website\"},\"datePublished\":\"2026-08-11T18:14:20+00:00\",\"dateModified\":\"2026-08-12T22:10:06+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/contratame.online\/es\/candidate\/kennygc10\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/contratame.online\/es\/candidate\/kennygc10\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/contratame.online\/es\/candidate\/kennygc10\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/contratame.online\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Candidates\",\"item\":\"https:\/\/contratame.online\/en\/candidate\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"KENNY ESTUARDO GARC\u00cdA CAAL\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/contratame.online\/#website\",\"url\":\"https:\/\/contratame.online\/\",\"name\":\"Contratame.online\",\"description\":\"Encuentra el empleo que siempre so\u00f1aste.\",\"publisher\":{\"@id\":\"https:\/\/contratame.online\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/contratame.online\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/contratame.online\/#organization\",\"name\":\"CONTRATA ME\",\"url\":\"https:\/\/contratame.online\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/contratame.online\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/contratame.online\/wp-content\/uploads\/2023\/07\/logohd.png\",\"contentUrl\":\"https:\/\/contratame.online\/wp-content\/uploads\/2023\/07\/logohd.png\",\"width\":150,\"height\":50,\"caption\":\"CONTRATA ME\"},\"image\":{\"@id\":\"https:\/\/contratame.online\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/contratamegt\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"KENNY ESTUARDO GARC\u00cdA CAAL - Contratame.online","robots":{"index":"noindex","follow":"follow"},"og_locale":"es_ES","og_type":"article","og_title":"KENNY ESTUARDO GARC\u00cdA CAAL - Contratame.online","og_description":"Soy una persona responsable, con ganas de aprender y de trabajar. Me adapto f\u00e1cilmente a diferentes tareas y me gusta trabajar en equipo. Siempre trato de dar lo mejor de m\u00ed, cumplir con mi trabajo y aprender cosas nuevas. Tambi\u00e9n tengo conocimientos b\u00e1sicos de computaci\u00f3n y busco una oportunidad para seguir creciendo tanto en lo [&hellip;]","og_url":"https:\/\/contratame.online\/es\/candidate\/kennygc10\/","og_site_name":"Contratame.online","article_publisher":"https:\/\/www.facebook.com\/contratamegt","article_modified_time":"2026-08-12T22:10:06+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/contratame.online\/es\/candidate\/kennygc10\/","url":"https:\/\/contratame.online\/es\/candidate\/kennygc10\/","name":"KENNY ESTUARDO GARC\u00cdA CAAL - Contratame.online","isPartOf":{"@id":"https:\/\/contratame.online\/#website"},"datePublished":"2026-08-11T18:14:20+00:00","dateModified":"2026-08-12T22:10:06+00:00","breadcrumb":{"@id":"https:\/\/contratame.online\/es\/candidate\/kennygc10\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/contratame.online\/es\/candidate\/kennygc10\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/contratame.online\/es\/candidate\/kennygc10\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/contratame.online\/"},{"@type":"ListItem","position":2,"name":"Candidates","item":"https:\/\/contratame.online\/en\/candidate\/"},{"@type":"ListItem","position":3,"name":"KENNY ESTUARDO GARC\u00cdA CAAL"}]},{"@type":"WebSite","@id":"https:\/\/contratame.online\/#website","url":"https:\/\/contratame.online\/","name":"Contratame.online","description":"Encuentra el empleo que siempre so\u00f1aste.","publisher":{"@id":"https:\/\/contratame.online\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/contratame.online\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/contratame.online\/#organization","name":"CONTRATA ME","url":"https:\/\/contratame.online\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/contratame.online\/#\/schema\/logo\/image\/","url":"https:\/\/contratame.online\/wp-content\/uploads\/2023\/07\/logohd.png","contentUrl":"https:\/\/contratame.online\/wp-content\/uploads\/2023\/07\/logohd.png","width":150,"height":50,"caption":"CONTRATA ME"},"image":{"@id":"https:\/\/contratame.online\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/contratamegt"]}]}},"metas":{"_candidate_location":{"167":"Guatemala"},"_candidate_age":"18","_candidate_gender":"Masculino","_candidate_phone":"57613248","_candidate_email":"kennygc10@gmail.com","_candidate_qualification":"Diversificado","_candidate_job_title":"TECNOLOGIA","_candidate_experience_time":"Sin experiencia","_candidate_salary":"Q4,500","_candidate_languages":["Espa\u00f1ol"],"_candidate_skill":[{"title":"CONOCIMIENTO DE COMPUTACI\u00d3N","percentage":"85"}],"_candidate_category":[],"_candidate_cv_attachment":{"79620":"https:\/\/contratame.online\/wp-content\/uploads\/2026\/08\/inbound707044291523798460.pdf"},"_candidate_education":"","_candidate_experience":""},"_links":{"self":[{"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/candidate\/79618","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/candidate"}],"about":[{"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/types\/candidate"}],"replies":[{"embeddable":true,"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/comments?post=79618"}],"version-history":[{"count":1,"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/candidate\/79618\/revisions"}],"predecessor-version":[{"id":79619,"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/candidate\/79618\/revisions\/79619"}],"wp:attachment":[{"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/media?parent=79618"}],"wp:term":[{"taxonomy":"candidate_category","embeddable":true,"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/candidate_category?post=79618"},{"taxonomy":"candidate_location","embeddable":true,"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/candidate_location?post=79618"},{"taxonomy":"candidate_tag","embeddable":true,"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/candidate_tag?post=79618"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}