{"id":80171,"date":"2026-08-11T20:45:15","date_gmt":"2026-08-12T02:45:15","guid":{"rendered":"https:\/\/contratame.online\/es\/candidate\/melanygonzalezov\/"},"modified":"2026-08-11T21:02:07","modified_gmt":"2026-08-12T03:02:07","slug":"melanygonzalezov","status":"publish","type":"candidate","link":"https:\/\/contratame.online\/es\/candidate\/melanygonzalezov\/","title":{"rendered":"Melany Paola Gonz\u00e1lez Ovando"},"content":{"rendered":"<p>Durante mis pr\u00e1cticas en el \u00e1rea de presupuesto destaqu\u00e9 por mi responsabilidad, organizaci\u00f3n, atenci\u00f3n al detalle y manejo de informaci\u00f3n, apoyando en la elaboraci\u00f3n y revisi\u00f3n de presupuestos.<\/p>\n","protected":false},"featured_media":80185,"comment_status":"open","ping_status":"closed","template":"","candidate_category":[],"candidate_location":[167],"candidate_tag":[],"class_list":["post-80171","candidate","type-candidate","status-publish","has-post-thumbnail","hentry","candidate_location-guatemala"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Melany Paola Gonz\u00e1lez Ovando - Contratame.online<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Melany Paola Gonz\u00e1lez Ovando - Contratame.online\" \/>\n<meta property=\"og:description\" content=\"Durante mis pr\u00e1cticas en el \u00e1rea de presupuesto destaqu\u00e9 por mi responsabilidad, organizaci\u00f3n, atenci\u00f3n al detalle y manejo de informaci\u00f3n, apoyando en la elaboraci\u00f3n y revisi\u00f3n de presupuestos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/contratame.online\/es\/candidate\/melanygonzalezov\/\" \/>\n<meta property=\"og:site_name\" content=\"Contratame.online\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/contratamegt\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-12T03:02:07+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/contratame.online\/es\/candidate\/melanygonzalezov\/\",\"url\":\"https:\/\/contratame.online\/es\/candidate\/melanygonzalezov\/\",\"name\":\"Melany Paola Gonz\u00e1lez Ovando - Contratame.online\",\"isPartOf\":{\"@id\":\"https:\/\/contratame.online\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/contratame.online\/es\/candidate\/melanygonzalezov\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/contratame.online\/es\/candidate\/melanygonzalezov\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/contratame.online\/wp-content\/uploads\/wp-job-board-pro-uploads\/_candidate_featured_image\/2026\/08\/Diseno-sin-titulo-1.png\",\"datePublished\":\"2026-08-12T02:45:15+00:00\",\"dateModified\":\"2026-08-12T03:02:07+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/contratame.online\/es\/candidate\/melanygonzalezov\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/contratame.online\/es\/candidate\/melanygonzalezov\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/contratame.online\/es\/candidate\/melanygonzalezov\/#primaryimage\",\"url\":\"https:\/\/contratame.online\/wp-content\/uploads\/wp-job-board-pro-uploads\/_candidate_featured_image\/2026\/08\/Diseno-sin-titulo-1.png\",\"contentUrl\":\"https:\/\/contratame.online\/wp-content\/uploads\/wp-job-board-pro-uploads\/_candidate_featured_image\/2026\/08\/Diseno-sin-titulo-1.png\",\"width\":208,\"height\":243},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/contratame.online\/es\/candidate\/melanygonzalezov\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/contratame.online\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Candidates\",\"item\":\"https:\/\/contratame.online\/en\/candidate\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Melany Paola Gonz\u00e1lez Ovando\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/contratame.online\/#website\",\"url\":\"https:\/\/contratame.online\/\",\"name\":\"Contratame.online\",\"description\":\"Encuentra el empleo que siempre so\u00f1aste.\",\"publisher\":{\"@id\":\"https:\/\/contratame.online\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/contratame.online\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/contratame.online\/#organization\",\"name\":\"CONTRATA ME\",\"url\":\"https:\/\/contratame.online\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/contratame.online\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/contratame.online\/wp-content\/uploads\/2023\/07\/logohd.png\",\"contentUrl\":\"https:\/\/contratame.online\/wp-content\/uploads\/2023\/07\/logohd.png\",\"width\":150,\"height\":50,\"caption\":\"CONTRATA ME\"},\"image\":{\"@id\":\"https:\/\/contratame.online\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/contratamegt\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Melany Paola Gonz\u00e1lez Ovando - Contratame.online","robots":{"index":"noindex","follow":"follow"},"og_locale":"es_ES","og_type":"article","og_title":"Melany Paola Gonz\u00e1lez Ovando - Contratame.online","og_description":"Durante mis pr\u00e1cticas en el \u00e1rea de presupuesto destaqu\u00e9 por mi responsabilidad, organizaci\u00f3n, atenci\u00f3n al detalle y manejo de informaci\u00f3n, apoyando en la elaboraci\u00f3n y revisi\u00f3n de presupuestos.","og_url":"https:\/\/contratame.online\/es\/candidate\/melanygonzalezov\/","og_site_name":"Contratame.online","article_publisher":"https:\/\/www.facebook.com\/contratamegt","article_modified_time":"2026-08-12T03:02:07+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/contratame.online\/es\/candidate\/melanygonzalezov\/","url":"https:\/\/contratame.online\/es\/candidate\/melanygonzalezov\/","name":"Melany Paola Gonz\u00e1lez Ovando - Contratame.online","isPartOf":{"@id":"https:\/\/contratame.online\/#website"},"primaryImageOfPage":{"@id":"https:\/\/contratame.online\/es\/candidate\/melanygonzalezov\/#primaryimage"},"image":{"@id":"https:\/\/contratame.online\/es\/candidate\/melanygonzalezov\/#primaryimage"},"thumbnailUrl":"https:\/\/contratame.online\/wp-content\/uploads\/wp-job-board-pro-uploads\/_candidate_featured_image\/2026\/08\/Diseno-sin-titulo-1.png","datePublished":"2026-08-12T02:45:15+00:00","dateModified":"2026-08-12T03:02:07+00:00","breadcrumb":{"@id":"https:\/\/contratame.online\/es\/candidate\/melanygonzalezov\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/contratame.online\/es\/candidate\/melanygonzalezov\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/contratame.online\/es\/candidate\/melanygonzalezov\/#primaryimage","url":"https:\/\/contratame.online\/wp-content\/uploads\/wp-job-board-pro-uploads\/_candidate_featured_image\/2026\/08\/Diseno-sin-titulo-1.png","contentUrl":"https:\/\/contratame.online\/wp-content\/uploads\/wp-job-board-pro-uploads\/_candidate_featured_image\/2026\/08\/Diseno-sin-titulo-1.png","width":208,"height":243},{"@type":"BreadcrumbList","@id":"https:\/\/contratame.online\/es\/candidate\/melanygonzalezov\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/contratame.online\/"},{"@type":"ListItem","position":2,"name":"Candidates","item":"https:\/\/contratame.online\/en\/candidate\/"},{"@type":"ListItem","position":3,"name":"Melany Paola Gonz\u00e1lez Ovando"}]},{"@type":"WebSite","@id":"https:\/\/contratame.online\/#website","url":"https:\/\/contratame.online\/","name":"Contratame.online","description":"Encuentra el empleo que siempre so\u00f1aste.","publisher":{"@id":"https:\/\/contratame.online\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/contratame.online\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/contratame.online\/#organization","name":"CONTRATA ME","url":"https:\/\/contratame.online\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/contratame.online\/#\/schema\/logo\/image\/","url":"https:\/\/contratame.online\/wp-content\/uploads\/2023\/07\/logohd.png","contentUrl":"https:\/\/contratame.online\/wp-content\/uploads\/2023\/07\/logohd.png","width":150,"height":50,"caption":"CONTRATA ME"},"image":{"@id":"https:\/\/contratame.online\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/contratamegt"]}]}},"metas":{"_candidate_location":{"167":"Guatemala"},"_candidate_age":"22","_candidate_gender":"Femenino","_candidate_phone":"49895315","_candidate_email":"melanygonzalezov@gmail.com","_candidate_qualification":"Diversificado","_candidate_job_title":"Estudiante universitaria","_candidate_experience_time":"Sin experiencia","_candidate_salary":"","_candidate_languages":["Espa\u00f1ol","Ingl\u00e9s"],"_candidate_skill":[{"title":"Microsoft Office","percentage":"60"},{"title":"Comunicaci\u00f3n","percentage":"75"},{"title":"Organizaci\u00f3n","percentage":"84"},{"title":"Atenci\u00f3n al cliente","percentage":"75"},{"title":"Ingl\u00e9s","percentage":"60"},{"title":"Redacci\u00f3n","percentage":"78"},{"title":"Trabajo en equipo","percentage":"88"},{"title":"Gesti\u00f3n administrativa","percentage":"50"},{"title":"An\u00e1lisis de datos","percentage":"60"},{"title":"Resoluci\u00f3n de problemas","percentage":"70"},{"title":"Excel","percentage":"40"}],"_candidate_category":[],"_candidate_cv_attachment":{"80173":"https:\/\/contratame.online\/wp-content\/uploads\/2026\/08\/Melany_Gonzalez_CV_.pdf"},"_candidate_education":"","_candidate_experience":"","_candidate_logo":"https:\/\/contratame.online\/wp-content\/uploads\/wp-job-board-pro-uploads\/_candidate_featured_image\/2026\/08\/Diseno-sin-titulo-1-150x150.png"},"_links":{"self":[{"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/candidate\/80171","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/candidate"}],"about":[{"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/types\/candidate"}],"replies":[{"embeddable":true,"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/comments?post=80171"}],"version-history":[{"count":1,"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/candidate\/80171\/revisions"}],"predecessor-version":[{"id":80172,"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/candidate\/80171\/revisions\/80172"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/media\/80185"}],"wp:attachment":[{"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/media?parent=80171"}],"wp:term":[{"taxonomy":"candidate_category","embeddable":true,"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/candidate_category?post=80171"},{"taxonomy":"candidate_location","embeddable":true,"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/candidate_location?post=80171"},{"taxonomy":"candidate_tag","embeddable":true,"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/candidate_tag?post=80171"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}