{"id":80613,"date":"2026-08-12T09:16:32","date_gmt":"2026-08-12T15:16:32","guid":{"rendered":"https:\/\/contratame.online\/es\/candidate\/herlopzherrera93\/"},"modified":"2026-08-12T09:21:13","modified_gmt":"2026-08-12T15:21:13","slug":"herlopzherrera93","status":"publish","type":"candidate","link":"https:\/\/contratame.online\/es\/candidate\/herlopzherrera93\/","title":{"rendered":"Eliseo Isaac Herrera Coxaj"},"content":{"rendered":"<p>Atenci\u00f3n al cliente<br \/>\nComunicaci\u00f3n<br \/>\nTrabajo en equipo<br \/>\nOrganizaci\u00f3n<br \/>\nResponsabilidad<br \/>\nAprendizaje r\u00e1pido<br \/>\nManejo de computadora<br \/>\nResoluci\u00f3n de problemas<\/p>\n","protected":false},"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","candidate_category":[277],"candidate_location":[167],"candidate_tag":[],"class_list":["post-80613","candidate","type-candidate","status-publish","hentry","candidate_category-disenador","candidate_location-guatemala"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Eliseo Isaac Herrera Coxaj - Contratame.online<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Eliseo Isaac Herrera Coxaj - Contratame.online\" \/>\n<meta property=\"og:description\" content=\"Atenci\u00f3n al cliente Comunicaci\u00f3n Trabajo en equipo Organizaci\u00f3n Responsabilidad Aprendizaje r\u00e1pido Manejo de computadora Resoluci\u00f3n de problemas\" \/>\n<meta property=\"og:url\" content=\"https:\/\/contratame.online\/es\/candidate\/herlopzherrera93\/\" \/>\n<meta property=\"og:site_name\" content=\"Contratame.online\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/contratamegt\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-12T15:21:13+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/contratame.online\/es\/candidate\/herlopzherrera93\/\",\"url\":\"https:\/\/contratame.online\/es\/candidate\/herlopzherrera93\/\",\"name\":\"Eliseo Isaac Herrera Coxaj - Contratame.online\",\"isPartOf\":{\"@id\":\"https:\/\/contratame.online\/#website\"},\"datePublished\":\"2026-08-12T15:16:32+00:00\",\"dateModified\":\"2026-08-12T15:21:13+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/contratame.online\/es\/candidate\/herlopzherrera93\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/contratame.online\/es\/candidate\/herlopzherrera93\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/contratame.online\/es\/candidate\/herlopzherrera93\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/contratame.online\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Candidates\",\"item\":\"https:\/\/contratame.online\/en\/candidate\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Eliseo Isaac Herrera Coxaj\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/contratame.online\/#website\",\"url\":\"https:\/\/contratame.online\/\",\"name\":\"Contratame.online\",\"description\":\"Encuentra el empleo que siempre so\u00f1aste.\",\"publisher\":{\"@id\":\"https:\/\/contratame.online\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/contratame.online\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/contratame.online\/#organization\",\"name\":\"CONTRATA ME\",\"url\":\"https:\/\/contratame.online\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/contratame.online\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/contratame.online\/wp-content\/uploads\/2023\/07\/logohd.png\",\"contentUrl\":\"https:\/\/contratame.online\/wp-content\/uploads\/2023\/07\/logohd.png\",\"width\":150,\"height\":50,\"caption\":\"CONTRATA ME\"},\"image\":{\"@id\":\"https:\/\/contratame.online\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/contratamegt\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Eliseo Isaac Herrera Coxaj - Contratame.online","robots":{"index":"noindex","follow":"follow"},"og_locale":"es_ES","og_type":"article","og_title":"Eliseo Isaac Herrera Coxaj - Contratame.online","og_description":"Atenci\u00f3n al cliente Comunicaci\u00f3n Trabajo en equipo Organizaci\u00f3n Responsabilidad Aprendizaje r\u00e1pido Manejo de computadora Resoluci\u00f3n de problemas","og_url":"https:\/\/contratame.online\/es\/candidate\/herlopzherrera93\/","og_site_name":"Contratame.online","article_publisher":"https:\/\/www.facebook.com\/contratamegt","article_modified_time":"2026-08-12T15:21:13+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/contratame.online\/es\/candidate\/herlopzherrera93\/","url":"https:\/\/contratame.online\/es\/candidate\/herlopzherrera93\/","name":"Eliseo Isaac Herrera Coxaj - Contratame.online","isPartOf":{"@id":"https:\/\/contratame.online\/#website"},"datePublished":"2026-08-12T15:16:32+00:00","dateModified":"2026-08-12T15:21:13+00:00","breadcrumb":{"@id":"https:\/\/contratame.online\/es\/candidate\/herlopzherrera93\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/contratame.online\/es\/candidate\/herlopzherrera93\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/contratame.online\/es\/candidate\/herlopzherrera93\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/contratame.online\/"},{"@type":"ListItem","position":2,"name":"Candidates","item":"https:\/\/contratame.online\/en\/candidate\/"},{"@type":"ListItem","position":3,"name":"Eliseo Isaac Herrera Coxaj"}]},{"@type":"WebSite","@id":"https:\/\/contratame.online\/#website","url":"https:\/\/contratame.online\/","name":"Contratame.online","description":"Encuentra el empleo que siempre so\u00f1aste.","publisher":{"@id":"https:\/\/contratame.online\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/contratame.online\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/contratame.online\/#organization","name":"CONTRATA ME","url":"https:\/\/contratame.online\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/contratame.online\/#\/schema\/logo\/image\/","url":"https:\/\/contratame.online\/wp-content\/uploads\/2023\/07\/logohd.png","contentUrl":"https:\/\/contratame.online\/wp-content\/uploads\/2023\/07\/logohd.png","width":150,"height":50,"caption":"CONTRATA ME"},"image":{"@id":"https:\/\/contratame.online\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/contratamegt"]}]}},"metas":{"_candidate_location":{"167":"Guatemala"},"_candidate_age":"33","_candidate_gender":"Masculino","_candidate_phone":"40501057","_candidate_email":"Herlopzherrera93@gmail.com","_candidate_qualification":"Diversificado","_candidate_job_title":"Auxiliar de merchandising","_candidate_experience_time":"+6 A\u00f1os","_candidate_salary":"","_candidate_languages":["Espa\u00f1ol"],"_candidate_skill":"","_candidate_category":{"277":"Dise\u00f1ador"},"_candidate_cv_attachment":{"80615":"https:\/\/contratame.online\/wp-content\/uploads\/2026\/08\/CV-Isaac-Herrera-.pdf"},"_candidate_education":"","_candidate_experience":""},"_links":{"self":[{"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/candidate\/80613","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/candidate"}],"about":[{"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/types\/candidate"}],"replies":[{"embeddable":true,"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/comments?post=80613"}],"version-history":[{"count":1,"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/candidate\/80613\/revisions"}],"predecessor-version":[{"id":80614,"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/candidate\/80613\/revisions\/80614"}],"wp:attachment":[{"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/media?parent=80613"}],"wp:term":[{"taxonomy":"candidate_category","embeddable":true,"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/candidate_category?post=80613"},{"taxonomy":"candidate_location","embeddable":true,"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/candidate_location?post=80613"},{"taxonomy":"candidate_tag","embeddable":true,"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/candidate_tag?post=80613"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}