{"id":38,"date":"2021-03-10T09:28:48","date_gmt":"2021-03-10T09:28:48","guid":{"rendered":"https:\/\/apusthemes.com\/wp-demo\/superio\/?page_id=38"},"modified":"2026-02-09T23:57:31","modified_gmt":"2026-02-10T05:57:31","slug":"terminos-y-condiciones","status":"publish","type":"page","link":"https:\/\/contratame.online\/es\/terminos-y-condiciones\/","title":{"rendered":"T\u00e9rminos y condiciones"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"38\" class=\"elementor elementor-38\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2e81926 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2e81926\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7ebfa76\" data-id=\"7ebfa76\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9c6216e elementor-widget elementor-widget-heading\" data-id=\"9c6216e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.23.0 - 25-07-2024 *\/\n.elementor-heading-title{padding:0;margin:0;line-height:1}.elementor-widget-heading .elementor-heading-title[class*=elementor-size-]>a{color:inherit;font-size:inherit;line-height:inherit}.elementor-widget-heading .elementor-heading-title.elementor-size-small{font-size:15px}.elementor-widget-heading .elementor-heading-title.elementor-size-medium{font-size:19px}.elementor-widget-heading .elementor-heading-title.elementor-size-large{font-size:29px}.elementor-widget-heading .elementor-heading-title.elementor-size-xl{font-size:39px}.elementor-widget-heading .elementor-heading-title.elementor-size-xxl{font-size:59px}<\/style><h2 class=\"elementor-heading-title elementor-size-default\">CONDICIONES GENERALES DE USO DEL PORTAL<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9afb672 elementor-widget elementor-widget-text-editor\" data-id=\"9afb672\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.23.0 - 25-07-2024 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#69727d;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#69727d;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t<p><span style=\"font-family: var(--superio-main-font), Helvetica, Arial, sans-serif;\">PRE\u00c1MBULO<\/span><\/p><p>CONTRATAME ONLINE (en adelante \u201cCONTRATAME.ONLINE\u201d o &#8220;CONTRATAME.ONLINE&#8221;) ofrece a los usuarios del Sitio Web CONTRATAME.ONLINE de forma gratuita, reservando algunos servicios espec\u00edficos al pago de una suscripci\u00f3n o pago puntual.<\/p><p>CONTRATAME.ONLINE entiende por \u201cUsuario Particular\u201d o \u201cDemandante de Trabajo o &#8220;Candidato&#8221;\u201d aquellas personas f\u00edsicas que accedan a los sitios web de CONTRATAME.ONLINE para buscar empleo o recibir servicios relacionados.<\/p><p>CONTRATAME.ONLINE entiende por \u201cUsuario Profesional\u201d u \u201cOfertante de Empleo\u201d o &#8220;Empresa&#8221;, aquellas empresas o reclutadores que utilicen los servicios de CONTRATAME.ONLINE y accedan a los Sitios Web de los que \u00e9ste \u00faltimo es titular.<\/p><p>El Usuario Particular y el Usuario Profesional ser\u00e1n referidos conjuntamente, cuando as\u00ed proceda, como \u201cUsuario\u201d o \u201cUsuarios\u201d.<\/p><p>Todo Usuario acepta, desde el mismo momento en el que accede, sin ning\u00fan tipo de reserva, el contenido de las presentes Condiciones Legales, la \u201cPol\u00edtica de Privacidad y Cookies\u201d, as\u00ed como, en su caso, las Condiciones Particulares que puedan complementar, sustituir o modificar las referidas condiciones en relaci\u00f3n con los servicios y contenidos del contenidos del Portal Web acordadas, en su caso, la correspondiente Orden de Servicio, Contrato o Condiciones de Servicio Espec\u00edficas (en adelante, referidas conjuntamente como las \u201cCondiciones Legales\u201d). El Usuario deber\u00e1 leer detenidamente las Condiciones Legales antes del uso y\/o contrataci\u00f3n de cualquier servicio del Portal Web bajo su entera responsabilidad.<\/p><p>Para acceder a nuestro portal web el Usuario debe tener 16 a\u00f1os de edad o m\u00e1s. Si el Usuario es menor de 18 a\u00f1os o menor a la mayor\u00eda legal de su pa\u00eds, el uso de nuestro Portal Web y asunci\u00f3n de cualquier obligaci\u00f3n debe estar bajo la supervisi\u00f3n de sus padres o tutor u otro adulto responsable. En caso de acceder al Portal Web o utilizarlo en calidad de empleado o representante de un Usuario Profesional, se considera que \u00e9ste declara y garantiza que tiene la autoridad para vincular al Usuario Profesional a las presentes Condiciones Legales.<\/p><p>Con car\u00e1cter general el acceso al Portal Web no exige la previa suscripci\u00f3n o registro de los Usuarios. No obstante, CONTRATAME.ONLINE condiciona la utilizaci\u00f3n de algunos de los servicios al Registro del Usuario. El tratamiento de los datos personales que se incluyan ser\u00e1 conforme a nuestra Pol\u00edtica de Privacidad.<\/p><p>El Usuario puede acceder, imprimir, descargar y guardar las Condiciones Legales, las cuales est\u00e1n permanentemente accesibles en el Sitio Web a trav\u00e9s del enlace \u201cAviso Legal\u201d y \u201cPrivacidad\u201d.<\/p><p>CONTRATAME.ONLINE podr\u00e1 modificar sin previo aviso el contenido de las Condiciones Legales. Por ello recomienda al Usuario leerlas cada vez que acceda al Portal Web. Asimismo, CONTRATAME.ONLINE podr\u00e1 modificar sin previo aviso el dise\u00f1o, presentaci\u00f3n y\/o configuraci\u00f3n de este Sitio Web, as\u00ed como algunos o todos los servicios ofrecidos, y a\u00f1adir servicios nuevos.<\/p><p>En cualquier caso, CONTRATAME.ONLINE se reserva el derecho de denegar el acceso a este Sitio Web, en cualquier momento y sin necesidad de previo aviso, a aquellos Usuarios que incumplan cualesquiera de las Condiciones Legales que les sean de aplicaci\u00f3n.<\/p><p>OBJETO<\/p><p>La finalidad de este Portal Web es la de poner en contacto a Demandantes de Trabajo que buscan empleo con Ofertantes de empleo que buscan candidatos para ofrecerles trabajo, ofreciendo principalmente los siguientes servicios:<\/p><p>Un directorio de ofertas de trabajo categorizadas por funci\u00f3n y lugar.<\/p><p>La publicaci\u00f3n de ofertas de trabajo y la posibilidad de obtener un contacto directo con las personas interesadas en dichas ofertas de trabajo.<\/p><p>OBLIGACIONES DE LOS USUARIOS EN EL PORTAL WEB<\/p><p>Las siguientes obligaciones deben cumplirlas todos los Usuarios, ya sea Candidato o Empresa.<\/p><p>El Usuario se compromete a:<\/p><p>Hacer un uso diligente del Portal Web y de sus servicios y \u00fanicamente para la finalidad del mismo. Debe cumplir con todas las leyes aplicables y las presentes Condiciones Legales del Portal Web, respetando a los dem\u00e1s Usuarios.<\/p><p>Respetar los derechos de terceros al utilizar servicios del Sitio Web. Por tanto, queda prohibida la reproducci\u00f3n, distribuci\u00f3n, transmisi\u00f3n, adaptaci\u00f3n o modificaci\u00f3n, por cualquier medio y en cualquier forma, de los contenidos del Sitio Web, propiedad de CONTRATAME.ONLINE o de terceros, (textos, dise\u00f1os, gr\u00e1ficos, informaciones, bases de datos, archivos de sonido y\/o imagen, marcas, software, logos, etc.) y dem\u00e1s elementos de este Sitio Web, salvo autorizaci\u00f3n previa de sus leg\u00edtimos titulares o cuando as\u00ed resulte permitido por la ley.<\/p><p>Publicar Contenido en el Portal Web de conformidad con lo dispuesto m\u00e1s adelante en las presentes Condiciones Legales.<\/p><p>No utilizar mecanismos, software o scripts en relaci\u00f3n con la utilizaci\u00f3n del Sitio Web.<\/p><p>No bloquear, sobrescribir, modificar o copiar contenidos, a no ser que ello sea estrictamente necesario para la correcta utilizaci\u00f3n de los servicios del Sitio Web y para la finalidad descrita anteriormente. Por ejemplo, el copiado mediante tecnolog\u00edas de buscador tipo \u201cRobot\/Crawler\u201d no es necesario para la correcta utilizaci\u00f3n de los servicios, por lo que queda prohibido expresamente.<\/p><p>No difundir y reproducir p\u00fablicamente contenidos del Sitio Web o de otros Usuarios.<\/p><p>No realizar ninguna acci\u00f3n que pueda perjudicar la funcionalidad de la infraestructura del Sitio Web, especialmente para sobrecargarla.<\/p><p>No realizar ninguna acci\u00f3n que da\u00f1e o inutilice los materiales e informaciones contenidos en la misma, los sistemas de informaci\u00f3n o los documentos, archivos o cualquier clase de contenido almacenado en cualquier equipo inform\u00e1tico (hacking) del Portal Web, los Usuarios del mismo y\/o terceros.<\/p><p>En caso de registrarse en el Portal Web, debe custodiar la contrase\u00f1a por \u00e9l seleccionada, evitando el uso de la misma por terceros.<\/p><p>De conformidad con la pol\u00edtica anti-spamming de CONTRATAME.ONLINE, el Usuario se abstendr\u00e1 de recabar o utilizar datos y contenido de otros Usuarios publicado el Portal Web para actividades con fines promocionales o publicitarios, as\u00ed como de remitir comunicaciones comerciales de cualquier clase y a trav\u00e9s de cualquier soporte no solicitado ni previamente consentido por CONTRATAME.ONLINE y\/o los interesados.<\/p><p>El Usuario tiene prohibido realizar cualquier actividad publicitaria, ofreciendo o distribuyendo bienes o servicios protegidos legalmente, as\u00ed como realizar o fomentar acciones contrarias a la libre competencia, incluidas las encaminadas a la captaci\u00f3n de clientes progresiva (como sistemas en cadena, de bola de nieve o piramidales).<\/p><p>Publicaci\u00f3n de contenidos en el Portal Web<\/p><p>I.-Contenido de Usuario<\/p><p>Los Usuarios pueden incluir informaci\u00f3n diversa en el Portal Web como textos, ofertas de empleo, im\u00e1genes, audio, videos, comentarios, mensajes, marcas, logotipos y cualquier otro tipo de informaci\u00f3n y\/o documento en el soporte que resulte de aplicaci\u00f3n. Todo el material e informaci\u00f3n que un Usuario env\u00ede publique, muestre o ponga a disposici\u00f3n de alg\u00fan otro modo en el Portal Web o a trav\u00e9s de \u00e9ste se denomina \u201cContenido de Usuario\u201d.<\/p><p>Determinado Contenido de Usuario podr\u00e1 estar disponible p\u00fablicamente en algunas secciones del Portal Web o dependiendo de la configuraci\u00f3n de privacidad del Usuario. El Usuario s\u00f3lo debe enviar Contenido de Usuario que desee compartir con otros p\u00fablicamente bajo las presentes Condiciones Legales de uso y de conformidad con la Pol\u00edtica de Privacidad del Portal Web.<\/p><p>El Usuario es el \u00fanico responsable por todo el Contenido de Usuario que incluya en el Portal Web y expresamente declara y garantiza que (i) es propietario del Contenido de Usuario que env\u00eda, publica, muestra o de otro modo pone a disposici\u00f3n en el Portal Web o a trav\u00e9s de \u00e9ste, o que de otra manera tiene el derecho o autorizaci\u00f3n a publicarlo y ponerlo a disposici\u00f3n en el Portal Web y de otorgar una licencia de uso a CONTRATAME.ONLINE estipulada en esta secci\u00f3n, (ii) dicho Contenido de Usuario y su env\u00edo, publicaci\u00f3n, exhibici\u00f3n o disponibilidad en el Portal Web o a trav\u00e9s de \u00e9ste no infringe la ley aplicable ni los derechos de privacidad, derechos de publicidad, derechos de autor, derechos contractuales, derechos de propiedad intelectual ni ning\u00fan otro derecho de cualquier persona o entidad, y (iii) tal env\u00edo, publicaci\u00f3n, exhibici\u00f3n o disponibilidad en el Portal Web o a trav\u00e9s de este no dar\u00e1 lugar a ning\u00fan incumplimiento de un contrato entre el Usuario y un tercero. El Usuario expresamente acepta pagar todas las regal\u00edas, honorarios, da\u00f1os y cualquier otro importe adeudado a cualquier persona o entidad a causa de dicho Contenido de Usuario enviado, publicado o exhibido en el Portal Web o a trav\u00e9s de \u00e9ste.<\/p><p>El Usuario declara y garantiza que respecto de aqu\u00e9l Contenido de Usuario que sea considerado dato personal, incluyendo aquellas im\u00e1genes en las que aparezcan personas f\u00edsicas que se incluyan en el Portal Web (i) cuenta con el consentimiento libre, previo, expreso, inequ\u00edvoco e informado de cada uno de los individuos cuyo dato personal o imagen ha sido publicada por \u00e9ste mismo o por CONTRATAME.ONLINE siguiendo sus instrucciones, a trav\u00e9s del Portal Web\/herramienta online y que (ii) dicha publicaci\u00f3n la efect\u00faa en cumplimiento de toda la normativa en materia de protecci\u00f3n de datos que se encuentre vigente y sea de aplicaci\u00f3n.<\/p><p>Es responsabilidad del Usuario mantener todo el Contenido de Usuario permanentemente actualizado de forma que responda en cada momento a su situaci\u00f3n real. El Usuario acepta defender, indemnizar y eximir de responsabilidad a CONTRATAME.ONLINE y a las empresas de su grupo empresarial, ante cualquier reclamaci\u00f3n resultante de tal Contenido de Usuario puesto a disposici\u00f3n por el mismo.<\/p><p>En la medida permitida por la ley, si usted como Usuario publica Contenido de Usuario en el Portal Web, otorga a CONTRATAME.ONLINE un derecho y una licencia no exclusivos, mundiales, perpetuos, irrevocable, totalmente pagados, libres de regal\u00edas y aptos para su sublicencia para hacer, utilizar, vender, sublicenciar, reproducir, distribuir, realizar, publicar, preparar trabajos derivados de ellos y aprovechar de cualquier otro modo todo ese Contenido de Usuario con el prop\u00f3sito de hacer p\u00fablico ese material en el Portal Web o de sus socios colaboradores, y de mantener y promover el Portal Web sin restricciones.<\/p><p>Adem\u00e1s, el Usuario Profesional concede a CONTRATAME.ONLINE, sus asociados y sublicenciatarios la licencia en los anteriores t\u00e9rminos para utilizar su nombre, nombre de usuario o marcas comerciales y logotipos en relaci\u00f3n con cualquier Contenido de Usuario o los materiales de marketing del Portal Web, o en acciones iniciadas por CONTRATAME.ONLINE para promover o publicitar ese Contenido de Usuario (p. ej., Ofertas de empleo), incluido el uso de palabras clave en motores de b\u00fasqueda en Internet de terceros y para mostrar y promocionar en programas de publicidad o marketing online, en particular en redes sociales, los servicios de CONTRATAME.ONLINE y el perfil empleador del Usuario Profesional. Dicho uso por parte de CONTRATAME.ONLINE ser\u00e1 consistente con las directrices que, en su caso, proporcione el Usuario Profesional a CONTRATAME.ONLINE y se realizar\u00e1 en todo momento respetando el nombre, prestigio, reputaci\u00f3n e imagen del Usuario Profesional y s\u00f3lo para los prop\u00f3sitos previstos en las presentes Condiciones Legales.<\/p><p>II.-Reglas de publicaci\u00f3n de Contenido de Usuario<\/p><p>El Usuario se obliga y compromete a cumplir con las siguientes reglas:<\/p><p>El Contenido de Usuario que facilite el Usuario a CONTRATAME.ONLINE deber\u00e1 ser veraz y exacto. A estos efectos, el Usuario garantiza la autenticidad de todos aquellos datos que comunique en el Portal Web, as\u00ed como su derecho o autorizaci\u00f3n para facilitarlos.<\/p><p>Es responsabilidad del Usuario mantener todo el Contenido de Usuario permanentemente actualizado de forma que responda en cada momento a su situaci\u00f3n real. El Usuario ser\u00e1 el \u00fanico responsable de las manifestaciones falsas o inexactas que realice y de los perjuicios que \u00e9stas pudieran causar a CONTRATAME.ONLINE y\/ o a terceros.<\/p><p>El Usuario debe abstenerse de utilizar, publicar o poner a disposici\u00f3n en el Portal Web cualquier Contenido de Usuario que sea o pueda interpretarse como injurioso, difamatorio, calumnioso, discriminatorio, abusivo, obsceno, que contenga insultos de car\u00e1cter sexual, \u00e9tnico o racial o que sabe que es falso, enga\u00f1oso o inexacto.<\/p><p>El Usuario debe abstenerse de utilizar, publicar o poner a disposici\u00f3n en el Portal Web cualquier Contenido de Usuario que sea de car\u00e1cter ilegal, pornogr\u00e1fico o que vulnere las leyes de protecci\u00f3n de menores, que incluya im\u00e1genes de menores, o con la intenci\u00f3n de publicitar, ofrecer o distribuir productos pornogr\u00e1ficos o que vulneren las leyes de protecci\u00f3n de menores, molestar a otros usuarios (especialmente mediante spam).<\/p><p>El Usuario debe abstenerse de utilizar, publicar o poner a disposici\u00f3n en el Portal Web cualquier Contenido de Usuario que se encuentre protegido legalmente (en particular, por la legislaci\u00f3n relativa a la propiedad intelectual e industrial. Por ejemplo: marcas, patentes, modelos de utilidad o modelos est\u00e9ticos, secretos comerciales) sin tener derecho o autorizaci\u00f3n para a ello.<\/p><p>El Usuario debe abstenerse de utilizar, publicar o poner a disposici\u00f3n en el Portal Web cualquier Contenido de Usuario que deteriore o pueda deteriorar o en modo alguno afectar la calidad de los servicios ofrecidos en el Portal Web.<\/p><p>El Usuario conoce y acepta que el uso de los servicios del Portal Web tiene lugar bajo su \u00fanica y exclusiva responsabilidad.<\/p><p>CONTRATAME.ONLINE se reserva el derecho de eliminar cualquier Contenido de Usuario o parte del mismo que, a exclusivo criterio de CONTRATAME.ONLINE, infrinja las reglas de publicaci\u00f3n anteriores o cualquier otra obligaci\u00f3n recogida en las presentes Condiciones Legales. Si considera que un Contenido de Usuario incumple lo dispuesto en este apartado, contacte con nuestro equipo de atenci\u00f3n al cliente para que podamos tener la oportunidad de analizar y considerar, en su caso, su eliminaci\u00f3n.<\/p><p>El Usuario responder\u00e1 de los da\u00f1os y perjuicios de cualquier naturaleza que CONTRATAME.ONLINE pueda sufrir como consecuencia del incumplimiento intencional o culpable de cualquiera de las obligaciones a las que queda sometido de conformidad con las presentes Condiciones Legales y de la normativa de aplicaci\u00f3n.<\/p><p>III.-Evaluaciones, comentarios y salarios<\/p><p>En algunos de sus Portales Web, CONTRATAME.ONLINE pone a disposici\u00f3n de los Usuarios, el servicio de evaluaciones de las empresas y los procesos de selecci\u00f3n que realizan, as\u00ed como una estad\u00edstica salarial, con el objetivo de contribuir positivamente al mercado laboral, ofreciendo un mayor nivel de transparencia e informaci\u00f3n adecuada para que los Usuarios Particulares o Demandantes de Trabajo, puedan tomar una decisi\u00f3n informada sobre el puesto de trabajo al que aplican.<\/p><p>El Usuario Profesional conoce y acepta que en su perfil p\u00fablico o p\u00e1gina de empresa, as\u00ed como en los avisos de trabajo publicados por el mismo, podr\u00e1n aparecer las evaluaciones que, en su caso, incluyan los Usuarios Particulares sobre el mismo, en base a una experiencia laboral actual o pasada o bien, un proceso de selecci\u00f3n realizado con dicho Usuario Profesional, siempre y cuando el contenido de las evaluaciones y comentarios no sea de car\u00e1cter ofensivo, injurioso, difamatorio o incumpla cualquiera de las reglas de publicaci\u00f3n de Contenido de Usuario. El equipo de moderaci\u00f3n de CONTRATAME.ONLINE har\u00e1 sus mejores esfuerzos para velar por el cumplimiento de lo anterior, pudiendo el Usuario Profesional denunciar, en su caso, el contenido de evaluaci\u00f3n que incumpla las anteriores condiciones en el Portal Web.<\/p><p>El Usuario Profesional no debe ofrecer incentivos a los empleados, exempleados o candidatos a cambio de evaluaciones y\/o comentarios. CONTRATAME.ONLINE eliminar\u00e1 aquellas evaluaciones si tiene evidencia de que \u00e9stos fueron compensados para dejar dichas rese\u00f1as y comentarios en el Portal Web.<\/p><p>El Usuario Profesional no puede amenazar o coaccionar a ninguna persona a realizar evaluaciones. Las evaluaciones son an\u00f3nimas, por lo que el Usuario Profesional no puede requerir a CONTRATAME.ONLINE a que revele qui\u00e9n la ha realizado y tampoco debe instar a los empleados, exempleados o candidatos a mostrar el contenido de las evaluaciones ya realizadas.<\/p><p>En el momento de realizar evaluaciones y\/o comentarios Los Usuarios Particulares deber\u00e1n cumplir con todas las reglas de publicaci\u00f3n expuestas en el anterior apartado, as\u00ed como con el resto de las obligaciones recogidas en las presentes Condiciones Legales.<\/p><p>Cuando un Usuario Particular realiza una evaluaci\u00f3n y\/o comentario \u00e9ste debe representar su opini\u00f3n personal -dentro de los l\u00edmites ya se\u00f1alados anteriormente-, sin coacci\u00f3n y sin seguir instrucciones de la empresa en cuesti\u00f3n.<\/p><p>Los Usuarios Particulares tienen prohibido solicitar incentivos (por ejemplo, regalos, recompensas econ\u00f3micas) a cambio de publicar evaluaciones y\/o comentarios.<\/p><p>Asimismo, el Portal Web puede poner a disposici\u00f3n de los Usuarios estad\u00edsticas salariales estimadas para determinados puestos de trabajo o categor\u00edas de puestos de trabajo. CONTRATAME.ONLINE realiza las referidas estad\u00edsticas salariales con la informaci\u00f3n sobre salarios publicada, en su caso, por los Usuarios Profesionales en sus avisos de empleo y no tiene en cuenta consideraciones legales como salario m\u00ednimo profesional de cada jurisdicci\u00f3n. Las cifras facilitadas por el Portal Web son estimaciones ofrecidas \u00fanicamente con fines informativos y el grado de precisi\u00f3n puede variar. La informaci\u00f3n sobre salarios se proporciona en el Portal Web s\u00f3lo para fines de comparaci\u00f3n generalizada, por lo que en todo caso y el Demandante de Trabajo debe asegurarse en todo caso de confirmar con el Ofertante de Empleo cu\u00e1l es el salario espec\u00edfico de un aviso de trabajo publicado.<\/p><p>IV.-Contenido de terceros<\/p><p>El Portal Web pone a disposici\u00f3n contenido de Usuarios, anunciantes y otros terceros. A estos efectos, \u201cContenido de terceros\u201d significa cualquier trabajo de autor\u00eda o informaci\u00f3n, incluyendo salarios, evaluaciones de la empresa, rese\u00f1as de entrevistas, fotos de la compa\u00f1\u00eda, respuestas de los Ofertantes de Empleo, ofertas de trabajo, informaci\u00f3n del perfil del Ofertante de Empleo, anuncios, comentarios, opiniones, publicaciones, curr\u00edculums, mensajes, texto, archivos, im\u00e1genes, trabajos de autor\u00eda, correo electr\u00f3nico, datos o cualquier otro material que usted como Usuario encuentre en el Portal Web.<\/p><p>Debido a que no controlamos dicho Contenido de terceros, usted como Usuario entiende y acepta que: (i) no somos responsables ni respaldamos dicho Contenido de terceros, incluida la publicidad y la informaci\u00f3n sobre productos y servicios de terceros, anuncios de empleo o informaci\u00f3n relacionada con el Ofertante de Empleo, evaluaciones de la empresa y procesos de selecci\u00f3n, as\u00ed como salarios proporcionada por otros Usuarios; (ii) no garantizamos la exactitud, actualidad, idoneidad, fiabilidad o calidad de la informaci\u00f3n contenida en dicho Contenido de terceros; y (iii) no asumimos ninguna responsabilidad por el Contenido de terceros que resulte censurable, inexacto, enga\u00f1oso o ilegal o que incumpla las presentes Condiciones Legales puesto a disposici\u00f3n por Usuarios, anunciantes y terceros.<\/p><p>El Portal Web puede contener enlaces a sitios web de terceros colocados por nosotros como un servicio a aquellos interesados en esta informaci\u00f3n, o publicados por otros Usuarios o anunciantes. El uso de todos estos enlaces a sitios web de terceros es bajo su propio riesgo. No supervisamos ni tenemos ning\u00fan control sobre los sitios web de terceros. En la medida en que dichos enlaces son proporcionados por nosotros, se proporcionan s\u00f3lo como una conveniencia, y un enlace a un sitio web de terceros no implica nuestro apoyo, adopci\u00f3n o patrocinio de, o afiliaci\u00f3n con, dicho sitio web de terceros.<\/p><p>V.-Contenido de CONTRATAME.ONLINE<\/p><p>CONTRATAME.ONLINE autoriza al Usuario a la utilizaci\u00f3n de Portal Web para los servicios y funcionalidades ofrecidos por el mismo.<\/p><p>El Portal Web contiene contenido proporcionado por CONTRATAME.ONLINE y nuestros licenciatarios. Nosotros y nuestros licenciantes (incluyendo otros Usuarios) poseemos y retenemos todos los derechos de propiedad (incluyendo todos los derechos de propiedad intelectual) en el contenido que cada uno de nosotros proporciona y CONTRATAME.ONLINE posee y retiene todos los derechos de propiedad intelectual e industrial en el Portal Web. Si usted es un Usuario, por la presente le concedemos una licencia limitada, revocable y no sublicenciable bajo los derechos de propiedad intelectual licenciables por nosotros para ver, copiar e imprimir el Contenido de CONTRATAME.ONLINE \u00fanicamente para su uso personal en relaci\u00f3n con el uso del Portal Web y para la finalidad del mismo. CONTRATAME.ONLINE no concede ninguna otra licencia o autorizaci\u00f3n de uso de ninguna clase sobre sus derechos de propiedad intelectual e industrial o sobre cualquier otra propiedad o derecho relacionado con las funcionalidades y servicios de este Portal Web.<\/p><p>Excepto por lo dispuesto anteriormente, los Usuarios deben abstenerse de: (i) reproducir, modificar, publicar, transmitir, distribuir, presentar p\u00fablicamente o exhibir, vender, adaptar o crear trabajos derivados basados en el Portal Web o el contenido (excluyendo su propio Contenido de Usuario); o (ii) alquilar, arrendar, prestar o vender acceso al Portal Web. CONTRATAME.ONLINE \u00ae es una marca registrada de CONTRATAME ONLINE Las marcas registradas, logotipos y marcas de servicio (&#8220;Marcas&#8221;) mostradas en el Portal Web son de nuestra propiedad o propiedad de terceros. No se le permite utilizar estas Marcas sin nuestro consentimiento previo por escrito o el consentimiento de la tercera parte propietaria de la Marca.<\/p><p>REGLAMENTO DE USO PARA LOS USUARIOS PROFESIONALES<\/p><p>Registro de Usuario Profesional, perfil p\u00fablico y uso de la cuenta<\/p><p>La publicaci\u00f3n de ofertas y el uso de determinados servicios de CONTRATAME.ONLINE requiere el registro en el Portal Web del Ofertante de Empleo como Usuario Profesional. Para ello, la persona de contacto del Ofertante de Empleo, que deber\u00e1 ser empleada o representante de la empresa, proporcionar\u00e1 los datos identificativos de la empresa, datos de contacto profesionales y una contrase\u00f1a.<\/p><p>Para el registro en nuestro Portal Web el Usuario Profesional deber\u00e1 aceptar con car\u00e1cter previo las presentes Condiciones Legales y la Pol\u00edtica de Privacidad.<\/p><p>En el registro y uso de la cuenta por parte del Usuario Profesional es obligatorio cumplir con las siguientes disposiciones:<\/p><p>Registrar s\u00f3lo empresas existentes y debidamente constituidas conforme a la normativa de aplicaci\u00f3n.<\/p><p>Cada empresa solo podr\u00e1 ser registrada una \u00fanica vez con independencia de la existencia de filiales, sucursales o de la alteraci\u00f3n de cualquier dato fiscal de la empresa previamente registrada.<\/p><p>Que el registro y el uso de los servicios del Portal Web hayan sido autorizados por los representantes legales de la empresa. Con el registro en el Portal Web el Usuario Profesional declara y garantiza lo anterior.<\/p><p>Que exista alg\u00fan tipo de relaci\u00f3n laboral o profesional directa entre la persona f\u00edsica de contacto encargada de realizar el registro y el Usuario Profesional (Ofertante de empleo). La persona f\u00edsica de contacto o representante del Usuario Profesional no podr\u00e1 ser un agente independiente, ni representar y registrar a m\u00e1s de una empresa Ofertante de Empleo.<\/p><p>Utilizar los servicios del Sitio Web para la publicaci\u00f3n de ofertas de trabajo y b\u00fasqueda de Demandantes de Trabajo y gesti\u00f3n de sus procesos de selecci\u00f3n mediante el uso de las herramientas ofrecidas por el portal web y dentro del mismo, o bien, mediante la herramienta de software de reclutamiento ofrecida por CONTRATAME.ONLINE. Cualquier otro uso est\u00e1 terminantemente prohibido.<\/p><p>Se encuentra expresamente prohibido tanto registrar usuarios de la cuenta como permitir el uso de la misma o revender su acceso, cuando se trate de individuos ajenos a la organizaci\u00f3n del Usuario Profesional, incluyendo sus propios clientes.<\/p><p>El Usuario Profesional debe utilizar el portal web para publicar los procesos de selecci\u00f3n de su organizaci\u00f3n, con excepci\u00f3n de aquellas empresas reclutadoras que lo utilizan en el desarrollo de su propia actividad, excluyendo plataformas digitales, y siempre y cuando no compitan o pretendan competir contra CONTRATAME.ONLINE y\/o las empresas de su grupo.<\/p><p>Acceder a los servicios o cualquier informaci\u00f3n publicada en este sitio web de forma personal e interactiva. El acceso o lectura mediante robots o programas autom\u00e1ticos no est\u00e1 permitido.<\/p><p>Con el registro en el Portal Web, el Usuario Profesional dispone autom\u00e1ticamente de un perfil p\u00fablico o p\u00e1gina de empresa para proporcionar informaci\u00f3n general de la misma, de su marca, incluir sus logotipos, informaci\u00f3n sobre premios y reconocimientos, divulgar los beneficios que ofrece la empresa, as\u00ed como noticias y novedades sobre la misma. Asimismo, el Usuario Profesional o los empleados del mismo, pueden incluir fotos y videos para mostrar la cultura de la empresa o cualquier otro Contenido de Usuario que considere oportuno para la gesti\u00f3n de su reputaci\u00f3n empresarial, para mejorar su visibilidad y contar la historia de su empresa.<\/p><p>Con el objeto de completar, actualizar y\/o mejorar el perfil p\u00fablico o p\u00e1gina de la empresa, el Usuario Profesional autoriza a CONTRATAME.ONLINE a incluir informaci\u00f3n, fotos, videos, marcas o logos o cualquier otra informaci\u00f3n que el Usuario Profesional tenga disponible p\u00fablicamente en su p\u00e1gina web corporativa y\/o en redes sociales. El Usuario Profesional podr\u00e1 editar, modificar, eliminar o actualizar dicho contenido incluido por CONTRATAME.ONLINE en su perfil p\u00fablico o p\u00e1gina de empresa en cualquier momento. CONTRATAME.ONLINE \u00fanicamente incluir\u00e1 contenido que cumpla con las presentes Condiciones Legales y en particular, con las reglas de publicaci\u00f3n de contenido rese\u00f1adas anteriormente.<\/p><p>CONTRATAME.ONLINE validar\u00e1 el cumplimiento de los requisitos para el registro en el Portal Web atendiendo a su mejor criterio o a la demanda leg\u00edtima y acreditada de terceras personas, entidades o instituciones, y se reserva el derecho de no admitir el registro de una empresa o entidad, por motivos comerciales, o por incumplimientos contractuales previos o de las Condiciones Legales, ya sea probado o por fundadas sospechas de dicho incumplimiento, o por haberse recibido denuncias de terceros por actividades inadecuadas.<\/p><p>El incumplimiento de las normas de registro puede significar la cancelaci\u00f3n inmediata de la cuenta de Usuario Profesional y la destrucci\u00f3n de los contenidos asociados a la misma sin posibilidad de recuperaci\u00f3n.<\/p><p>En ning\u00fan caso la suspensi\u00f3n del servicio o la no activaci\u00f3n por incumplimiento de las normas de registro o de cualesquiera de las Condiciones Legales dar\u00e1 lugar al reembolso del producto pagado.<\/p><p>Contenido de las ofertas de trabajo<\/p><p>1. Todos las ofertas de trabajo deben cumplir con lo siguiente:<\/p><p>responder a una oferta de trabajo veraz y real.<\/p><p>y no estar duplicados. puede duplicar una vacante previamente ya publicada.<\/p><p>corresponder a un \u00fanico puesto o cargo.<\/p><p>especificar detalladamente el puesto de trabajo y el \u00e1rea en la que deber\u00e1 desempe\u00f1arse el candidato.<\/p><p>El t\u00edtulo de las ofertas deber\u00e1 contener la ubicaci\u00f3n concreta de la oferta y detalles del puesto de trabajo que se ofrece.<\/p><p>2. El Usuario debe tener en cuenta que est\u00e1 prohibida la inserci\u00f3n de ofertas de trabajo en cualquiera de los siguientes casos:<\/p><p>Que sean presuntamente il\u00edcitas por la normativa nacional, comunitaria o internacional o cuyo objeto sea realizar actividades presuntamente il\u00edcitas o que contravengan las buenas costumbres y los principios de la buena fe.<\/p><p>Que puedan da\u00f1ar el buen nombre y reputaci\u00f3n de CONTRATAME.ONLINE.<\/p><p>Que no cumplan con las reglas de publicaci\u00f3n de Contenido establecidas en las presentes Condiciones Legales.<\/p><p>Que no re\u00fanan los par\u00e1metros de calidad establecidos en CONTRATAME.ONLINE.<\/p><p>Que incluya dentro del campo \u201cDescripci\u00f3n de tareas\u201d una forma de contacto directo con la empresa distinta al n\u00famero de tel\u00e9fono.<\/p><p>Que incluyan m\u00e1s de un puesto de trabajo en la misma oferta.<\/p><p>Que se corresponda a ofertas donde la remuneraci\u00f3n sea exclusivamente por comisi\u00f3n o bien sea superior al salario medio del puesto de trabajo en cuesti\u00f3n.<\/p><p>Que requieran del candidato una inversi\u00f3n de capital.<\/p><p>Que consistan en trabajos de intercambio o voluntariado o trabajos con pagos diferidos.<\/p><p>Que corresponda a ventas por sistema multi-nivel o piramidal.<\/p><p>Que exija el env\u00edo de fotograf\u00edas (exceptu\u00e1ndose de esta limitaci\u00f3n la fotograf\u00eda tama\u00f1o pasaporte incluida en la hoja de vida facilitado por los Usuarios Particulares).<\/p><p>Que se defina como ofertas de &#8220;modelos&#8221; u ofertas de &#8220;masajistas&#8221; sin requerir experiencia ni titulaci\u00f3n espec\u00edfica en este campo.<\/p><p>Que atente contra los derechos fundamentales de las personas, vulnere sus derechos legales, pretenda aprovecharse de ellas, falte a la cortes\u00eda en la red, moleste o pueda generar opiniones negativas a los Usuarios o a terceros. A modo enunciativo, pero no limitativo: est\u00e1 prohibida la inserci\u00f3n de contenidos que favorezcan o potencien la creaci\u00f3n, mantenimiento y fomento de negocios relacionados con la pornograf\u00eda, material obsceno o gesti\u00f3n de contactos er\u00f3ticos; aquellos que est\u00e9n relacionados con la videncia, tarot, \u201cciencias ocultas\u201d o cualquier otro contenido relacionado; y en general, cualesquiera contenidos que CONTRATAME.ONLINE considere no apropiados para los Usuarios.<\/p><p>Que contravengan los principios de legalidad, honradez, responsabilidad, protecci\u00f3n de la dignidad humana, protecci\u00f3n de menores, protecci\u00f3n del orden p\u00fablico, la protecci\u00f3n de la vida privada, la protecci\u00f3n del consumidor y los derechos de propiedad intelectual e industrial.<\/p><p>Adem\u00e1s de lo anterior, las ofertas de trabajo que sean publicadas por plataformas tecnol\u00f3gicas que intermedien en la venta de bienes y\/o servicios expresamente autorizadas por CONTRATAME.ONLINE, adicionalmente deber\u00e1n cumplir con las siguientes especificaciones:<\/p><p>detallar\u00e1n el modelo de negocio en la oferta de trabajo, especificando que se busca individuos interesados en prestar sus servicios como trabajadores independientes, as\u00ed como el sistema retributivo que ser\u00e1 de aplicaci\u00f3n y cualquier otra condici\u00f3n que resulte relevante en funci\u00f3n del referido modelo de negocio.<\/p><p>podr\u00e1n utilizar una \u00fanica categor\u00eda para cada funci\u00f3n, eligi\u00e9ndose la m\u00e1s adecuada al perfil buscado. Se considerar\u00e1 uso fraudulento la publicaci\u00f3n de la oferta de forma indiscriminada en categor\u00edas profesionales diferentes que no resulten de aplicaci\u00f3n al referido perfil buscado.<\/p><p>el t\u00edtulo de las ofertas deber\u00e1 contener la ubicaci\u00f3n concreta de la oferta, si \u00e9sta se publica para distintas ubicaciones.<\/p><p>queda prohibido incitar o proponer al candidato a continuar con el registro para la efectiva postulaci\u00f3n al puesto ofrecido en otro sitio web o aplicaci\u00f3n m\u00f3vil distinta al propio portal web CONTRATAME.ONLINE.<\/p><p>3. CONTRATAME.ONLINE se reserva la potestad de retirar del Portal Web aquellos contenidos que se consideren inapropiados a las caracter\u00edsticas y finalidades del Portal Web. Cualquier Usuario Profesional que inserte un Ccontenido que contravenga la legalidad vigente y las Condiciones Legales asumir\u00e1 la responsabilidad exclusiva de los perjuicios y consecuencias derivadas de su publicaci\u00f3n, eximiendo a CONTRATAME.ONLINE de cualquier responsabilidad al respecto.<\/p><p>Si advierte alg\u00fan contenido inapropiado en el Sitio Web, por favor contacte con nosotros a trav\u00e9s de nuestro formulario de contacto.<\/p><p>Otras obligaciones del Usuario Profesional<\/p><p>Los Usuarios Profesionales no deber\u00e1n utilizar el anuncio publicado para:<\/p><p>Publicar informaci\u00f3n falsa, imprecisa o enga\u00f1osa.<\/p><p>Publicar en nombre de otra persona, viva o muerta.<\/p><p>Publicitar negocios o captar clientes (incluyendo, pero no limitado a: posiciones para empresas de tipo multinivel, franquicias, clubes de membres\u00edas, distribuci\u00f3n de productos, o cualquiera que requiera inversi\u00f3n monetaria por parte del usuario) que no se encuentre expresamente permitido en las presentes Condiciones Legales;<\/p><p>Publicar cadenas de cartas o esquemas piramidales;<\/p><p>Publicar opiniones o noticias, anuncios comerciales, promoci\u00f3n de productos o servicios;<\/p><p>Obtener informaci\u00f3n masiva de los Usuarios, en particular sus CV, para usos distintos del objeto del Sitio Web;<\/p><p>En relaci\u00f3n con los datos obtenidos de los Candidatos (Usuarios Particulares), los Usuarios Profesionales deben cumplir lo siguiente:<\/p><p>Acceder a los datos de los candidatos para las finalidades expl\u00edcitas y leg\u00edtimas de acuerdo con los servicios utilizados y\/o espec\u00edficamente contratados y de conformidad con lo establecido en las presentes Condiciones Legales y \u00fanicamente para finalidades de reclutamiento.<\/p><p>Tratar la informaci\u00f3n de los candidatos con la m\u00e1xima reserva y confidencialidad y de acuerdo con lo establecido en la legislaci\u00f3n sobre protecci\u00f3n de datos personales que resulte en todo momento de aplicaci\u00f3n.<\/p><p>No ceder o transferir los datos personales a personas f\u00edsicas o jur\u00eddicas distintas de las que pudieran haber sido expresamente autorizadas y para usos distintos de la finalidad del Portal Web, que es la puesta en contacto, a trav\u00e9s del Portal Web o de otra herramienta de software de reclutamiento ofrecida por CONTRATAME.ONLINE, entre particulares que buscan trabajo con Ofertantes de Empleo que buscan candidatos para ofrecerles trabajo.<\/p><p>Proteger los datos personales de Candidatos a los que tenga acceso garantizando su confidencialidad e impidiendo que terceros no autorizados puedan tener acceso a los mismos.<\/p><p>El acceso a los datos de las personas inscritas o asignadas a cada proceso de selecci\u00f3n se permite durante un plazo m\u00e1ximo de: (i) sesenta (60) d\u00edas naturales desde su inscripci\u00f3n o asignaci\u00f3n en caso de membres\u00edas; (ii) treinta (30) d\u00edas naturales tras la fecha de vencimiento en el caso de packs de ofertas y (iii) durante la vigencia de la oferta publicada (60 d\u00edas naturales) en el caso de las ofertas b\u00e1sicas.<\/p><p>En ning\u00fan caso, se otorga permiso al Usuario Profesional para almacenar los datos de los Candidatos para otros anuncios de trabajo ni para constituir una base de datos privada de CVs ni para cualquier otro uso distinto a la finalidad del Portal Web, salvo que ello sea permitido por CONTRATAME.ONLINE, ya sea mediante el uso de la herramienta de software de reclutamiento ofrecida por el mismo o mediante autorizaci\u00f3n expresa por escrito.<\/p><p>Reglas de publicaci\u00f3n de ofertas de trabajo<\/p><p>En la publicaci\u00f3n de las ofertas de trabajo en el Portal Web se siguen las siguientes reglas:<\/p><p>CONTRATAME.ONLINE, a su sola discreci\u00f3n, puede ofrecer poner a disposici\u00f3n del Usuario Profesional la posibilidad de publicar un n\u00famero limitado de ofertas sin coste a ser consumidas en un per\u00edodo determinado y con las restricciones que el Portal decida en cada momento. CONTRATAME.ONLINE se reserva el derecho a decidir el n\u00famero de ofertas sin coste que ofrece y las caracter\u00edsticas de las empresas que pueden ser beneficiarias de las mismas, pudiendo tener en consideraci\u00f3n caracter\u00edsticas objetivas del Usuario Profesional (tama\u00f1o, sector, plantilla, ubicaci\u00f3n, etc.), la actividad previa del Usuario Profesional en el Portal Web o cualquier otra que considere relevante. La oferta ser\u00e1 comunicada a trav\u00e9s del \u00e1rea de gesti\u00f3n de la cuenta pe rsonal del Usuario Profesional. CONTRATAME.ONLINE se reserva el derecho de modificar las condiciones de la oferta en cualquier momento.<\/p><p>Todas las ofertas de trabajo son revisadas por el equipo de CONTRATAME.ONLINE para validar su calidad y el cumplimiento de las Condiciones Legales. Una vez validadas, se mostrar\u00e1n en la Portal Web. El proceso de validaci\u00f3n puede tener una duraci\u00f3n aproximada de 12 horas desde su introducci\u00f3n en el Portal Web. No obstante, en ocasiones dicho proceso puede tener una duraci\u00f3n de hasta dos (2) d\u00edas h\u00e1biles. Las ofertas de trabajo tienen un periodo de validez de sesenta (60) d\u00edas, prorrogable por parte del Usuario Profesional, siempre sujeto al plazo de duraci\u00f3n de la membres\u00eda o contrato y seg\u00fan las condiciones del servicio. Una vez superado el periodo de validez y\/o de la membres\u00eda o contrato, las ofertas dejaran autom\u00e1ticamente de ser p\u00fablicas.<\/p><p>Las ofertas de trabajo activas pueden ser modificadas por el Usuario Profesional anunciante en cualquier momento durante el periodo de validez de las mismas y\/o de la membres\u00eda o contrato, a excepci\u00f3n de las ofertas sin coste que no permiten modificaci\u00f3n. Cualquier oferta modificada despu\u00e9s de su validaci\u00f3n inicial quedar\u00e1 pendiente de publicaci\u00f3n hasta la validaci\u00f3n de dichas modificaciones por parte de CONTRATAME.ONLINE. En este caso, el tiempo transcurrido para este proceso no se a\u00f1adir\u00e1 a la validez original.<\/p><p>Si las ofertas de trabajo publicadas han caducado, pero no han sido eliminadas por los motores de b\u00fasqueda de internet ajenos a CONTRATAME.ONLINE, se redirigir\u00e1 el tr\u00e1fico proveniente de estos a una selecci\u00f3n de ofertas similares.<\/p><p>CONTRATAME.ONLINE vela para que el contenido de los anuncios sea correcto. Sin embargo, no se hace responsable de aquellos errores que puedan surgir ni de los perjuicios que \u00e9stos puedan causar a terceros. Los contenidos publicados son responsabilidad exclusiva del Usuario Profesional que los publica.<\/p><p>El Usuario Profesional consiente y acepta que las ofertas publicadas por \u00e9ste podr\u00e1n ser incluidas en agregadores web con el objeto de mejorar la difusi\u00f3n y efectividad de la misma. La informaci\u00f3n facilitada por CONTRATAME.ONLINE a los referidos agregadores web consistir\u00e1 en el t\u00edtulo, descripci\u00f3n de la oferta y resto de informaciones que el Usuario Profesional decide hacer p\u00fablico en CONTRATAME.ONLINE, junto con el enlace de la misma al Portal Web. CONTRATAME.ONLINE velar\u00e1 para que el uso de dichos datos por los agregadores web sea conforme con la finalidad del Portal Web, no pudiendo, sin embargo, hacerse responsable en caso contrario.<\/p><p>Servicios de pago y su funcionamiento<\/p><p>CONTRATAME.ONLINE incluye dentro de su funcionamiento el acceso a servicios de pago, ya sea mediante pago puntual o por suscripci\u00f3n (membres\u00eda), que permiten un uso mejorado del portal. El acceso a estos servicios por parte de los Usuarios Profesionales es voluntario.<\/p><p>Los precios y tarifas aplicados a cada producto o suscripci\u00f3n corresponder\u00e1n a los publicados en el Portal Web en el momento de su contrataci\u00f3n (salvo que exista un error tipogr\u00e1fico pendiente de subsanaci\u00f3n) o bien los acordados mediante orden de servicio o contrato. Se deja expresa constancia que dichos precios y tarifas no incluyen en ning\u00fan caso los gastos derivados del m\u00e9todo de pago elegido por el Usuario Profesional, ni aquellos impuestos o tasas que, en su caso, correspondan, los cuales se aplicar\u00e1n antes del pago efectivo.<\/p><p>CONTRATAME.ONLINE emitir\u00e1 una factura una vez realizado el pago de un producto a trav\u00e9s del Portal Web. Los Usuarios Profesionales tendr\u00e1n a su disposici\u00f3n dicha factura dentro del \u00e1rea de gesti\u00f3n de su cuenta personal. En caso de realizar la contrataci\u00f3n a trav\u00e9s de un representante comercial, \u00e9ste ser\u00e1 quien genere una factura que ser\u00e1 remitida al Usuario Profesional por e-mail, a la vez que estar\u00e1 accesible dentro del \u00c1rea de Gesti\u00f3n del Usuario Profesional dentro de CONTRATAME.ONLINE.<\/p><p>En el momento de publicaci\u00f3n o actualizaci\u00f3n de las presentes Condiciones Legales, los servicios de pago disponibles en el Portal Web son los siguientes:<\/p><p>Terminaci\u00f3n o suspensi\u00f3n de los servicios. Pol\u00edtica de reembolso<\/p><p>Las Condiciones Legales permanecer\u00e1n en vigor mientras el Usuario Profesional utilice el Portal Web y su cuenta permanezca abierta. El Usuario Profesional puede eliminar su perfil y cuenta, as\u00ed como sus ofertas de trabajo en cualquier momento.<\/p><p>CONTRATAME.ONLINE se reserva la potestad de suspender o cancelar el servicio e impedir o limitar el acceso del Usuario Profesional, sin derecho a reembolso del precio pagado en caso de uso fraudulento o no acorde con las presentes Condiciones Legales y en contra de la finalidad del Portal Web.<\/p><p>Asimismo, CONTRATAME.ONLINE se reserva el derecho de suspender o cancelar definitivamente el servicio del Portal Web en caso de no recibirse el correspondiente pago a la fecha de vencimiento de la factura, ello sin perjuicio de la aplicaci\u00f3n de intereses y penalidades por impago y de la reclamaci\u00f3n de las cantidades pendientes.<\/p><p>El incumplimiento de las normas de registro puede significar la cancelaci\u00f3n inmediata de la cuenta de Usuario Profesional y la destrucci\u00f3n de los contenidos asociados a la misma sin posibilidad de recuperaci\u00f3n.<\/p><p>En ning\u00fan caso la suspensi\u00f3n del servicio o la no activaci\u00f3n por incumplimiento de las normas de registro o de cualesquiera de las Condiciones Legales dar\u00e1 lugar al reembolso del producto pagado.<\/p><p>CONTRATAME.ONLINE se reserva el derecho a terminar la relaci\u00f3n contractual con el Usuario Profesional en cualquier momento con o sin previo aviso.<\/p><p>El Usuario Profesional tendr\u00e1 derecho al reembolso de la parte no devengada de los servicios en caso de incumplimiento grave de CONTRATAME.ONLINE de las presentes Condiciones Legales y\/o los t\u00e9rminos acordados en la correspondiente Orden de Servicios o Contrato suscrito.<\/p><p>REGLAMENTO DE USO PARA LOS USUARIOS PARTICULARES<\/p><p>Registro del Usuario Particular y servicios<\/p><p>El acceso general al Portal Web por parte de los Usuarios Particulares o Demandantes de Trabajo no exige su previa suscripci\u00f3n o registro.<\/p><p>Sin embargo, para usar determinados servicios es necesario crear una cuenta en el Portal web, proporcionando los siguientes datos: nombre y apellidos, direcci\u00f3n de correo electr\u00f3nico v\u00e1lida, as\u00ed como una contrase\u00f1a. Asimismo, el Usuario Particular podr\u00e1 incluir en su perfil sus datos acad\u00e9micos, la experiencia laboral y aptitudes, una fotograf\u00eda, su ciudad o ubicaci\u00f3n. Tambi\u00e9n podr\u00e1 subir su C.V. en nuestro Portal Web en formato Word o Pdf.<\/p><p>Los principales servicios ofrecidos de manera gratuita son los siguientes:<\/p><p>un buscador y directorio de ofertas de trabajo por categor\u00eda y lugar.<\/p><p>aplicaci\u00f3n a avisos de trabajo publicados de forma que sus datos de contacto sean accesibles al Ofertante de Empleo.<\/p><p>una relaci\u00f3n de las ofertas de trabajo m\u00e1s buscadas por otros usuarios.<\/p><p>suscripci\u00f3n al env\u00edo de alertas de ofertas de trabajo publicadas recientemente.<\/p><p>publicaci\u00f3n gratuita de su curr\u00edculum en el Portal Web, pudiendo determinar si \u00e9ste puede ser accesible a los Ofertantes de Empleo de manera autom\u00e1tica o bien, \u00fanicamente en caso de aplicar a una oferta de trabajo concreta.<\/p><p>CONTRATAME.ONLINE puede decidir, en cualquier momento y sin previa notificaci\u00f3n, dejar de ofrecer de forma gratuita sus servicios o algunos de ellos.<\/p><p>Mediante el registro como Usuario Particular del Portal Web, el Demandante de Trabajo autoriza expresamente a CONTRATAME.ONLINE a facilitar determinada informaci\u00f3n del mismo para posibilitar el contacto con los Ofertantes de Empleo, ya sea mediante el presente Portal Web o la herramienta de software de reclutamiento online ofrecida por CONTRATAME.ONLINE, en caso de que la vacante haya sido publicada por la empresa a trav\u00e9s de dicha herramienta. CONTRATAME.ONLINE respetar\u00e1 en todo momento el nivel de privacidad determinado por el Usuario Particular y tratar\u00e1 sus datos de conformidad con lo establecido en la Pol\u00edtica de Privacidad.<\/p><p>Comunicaciones electr\u00f3nicas y alertas<\/p><p>El Portal Web ofrece un servicio gratuito de alertas de ofertas de trabajo enviadas al correo electr\u00f3nico indicado por el Candidato tras su registro en el Portal Web.<\/p><p>El Usuario Particular puede modificar o eliminar los servicios de alerta desde, su cuenta personal, desactivando la opci\u00f3n de env\u00edo de alertas siguiendo las instrucciones que se indican en el pie del correo electr\u00f3nico o dando de baja su cuenta.<\/p><p>Asimismo, el Portal Web y\/o la herramienta de software de reclutamiento ofrecida por CONTRATAME.ONLINE ofrecen un servicio de mensajer\u00eda o chat entre Usuarios Particulares y Usuarios Profesionales, ya sea mediante e-mail, chat, notificaciones en App, WhatsApp o cualquier otro medio disponible.<\/p><p>Terminaci\u00f3n o suspensi\u00f3n de los servicios<\/p><p>Las Condiciones Legales permanecer\u00e1n en vigor mientras el Usuario Particular utilice el Portal Web y su cuenta permanezca abierta. El Usuario Particular puede eliminar su perfil y cuenta, as\u00ed como sus ofertas de trabajo en cualquier momento.<\/p><p>CONTRATAME.ONLINE se reserva la potestad de impedir o limitar el acceso y suspender o cancelar la cuenta del Usuario Particular en caso de que se utilice incumpliendo las presentes Condiciones Legales y en contra de la finalidad del Portal Web.<\/p><p>DATOS DE CAR\u00c1CTER PERSONAL<\/p><p>CONTRATAME.ONLINE tratar\u00e1 los datos de car\u00e1cter personal de los Usuarios de conformidad con los t\u00e9rminos de la Pol\u00edtica Privacidad y Protecci\u00f3n de Datos que publicada en el Portal Web.<\/p><p>MEDIDAS DE SEGURIDAD<\/p><p>CONTRATAME.ONLINE ha implantado las medidas de seguridad oportunas en el Portal Web y trabaja constantemente en una protecci\u00f3n adecuada del mismo. No obstante, habida cuenta de que las medidas de seguridad en Internet no son inexpugnables, respecto de la privacidad y seguridad, CONTRATAME.ONLINE no garantiza que terceros, autorizados o no, puedan tener conocimiento de la clase, condiciones, caracter\u00edsticas y circunstancias del uso que los Usuarios hacen de las funcionalidades, o que puedan acceder, interceptar, eliminar, alterar, modificar o manipular los mensajes, comunicaciones y contenidos de cualquier clase que los Usuarios difundan o pongan a disposici\u00f3n de terceros a trav\u00e9s de dichas funcionalidades.<\/p><p>EXCLUSI\u00d3N DE GARANT\u00cdAS Y LIMITACI\u00d3N DE RESPONSABILIDAD<\/p><p>Las exclusiones y limitaciones de responsabilidad de esta secci\u00f3n se aplican en la medida m\u00e1xima permitida por la ley aplicable. Nada en esta secci\u00f3n tiene la intenci\u00f3n de limitar cualquier derecho de los Usuarios que no pueda ser limitado legalmente.<\/p><p>CONTRATAME.ONLINE proporciona los servicios y el acceso al Portal Web \u201ctal y como es\u201d y seg\u00fan disponibilidad. Renunciamos expresamente a cualquier garant\u00eda de cualquier tipo, ya sea expresa o impl\u00edcita, incluyendo las garant\u00edas o condiciones de comerciabilidad, idoneidad para un prop\u00f3sito particular, t\u00edtulo, disfrute tranquilo, exactitud o no infracci\u00f3n. CONTRATAME.ONLINE no garantiza que el Portal Web pueda estar disponible de forma ininterrumpida, oportuna, segura o libre de errores ni que los resultados que puedan obtenerse del uso del Portal Web sean precisos o fiables. Debido a razones de mantenimiento, seguridad o capacidad, as\u00ed como a causa de acontecimientos sobre los que CONTRATAME.ONLINE no puede influir (por ejemplo: anomal\u00edas de redes p\u00fablicas de comunicaci\u00f3n, cortes de electricidad, etc.) pueden producirse breves anomal\u00edas o la suspensi\u00f3n pasajera de los servicios del Portal Web. En consecuencia, CONTRATAME.ONLINE excluye, en la m\u00e1xima medida permitida por la legislaci\u00f3n vigente, cualquier responsabilidad por los da\u00f1os y perjuicios de toda naturaleza que puedan deberse a la falta de disponibilidad o de continuidad del funcionamiento del Portal Web y de los servicios habilitados en el mismo, as\u00ed como a los errores en el acceso a las distintas p\u00e1ginas web o aquellas desde las que, en su caso, se presten dichos servicios.<\/p><p>En particular, CONTRATAME.ONLINE expresamente excluye cualquier tipo de responsabilidad por p\u00e9rdida de ingresos o beneficios; p\u00e9rdida de negocios o contratos; por p\u00e9rdida de Datos, eliminaciones o fallos al almacenar la informaci\u00f3n provocados por el Cliente; p\u00e9rdida de prestigio y reputaci\u00f3n sufrida por el Cliente; las deficiencias o da\u00f1os relacionados con la interoperabilidad con Aplicaciones de Terceros o software, servicios o contenido que no sean del Proveedor; cualquier conectividad proporcionada por un tercero, si dicha conectividad hace uso de las API (interfaces de programaci\u00f3n de aplicaciones), en su caso, proporcionadas por el Proveedor; modificaciones a los servicios no realizadas por el Proveedor. Asimismo, CONTRATAME.ONLINE no es responsable de la precisi\u00f3n, idoneidad, ni legalidad de los archivos, publicaciones de Contenido de Usuario ni ninguna otra informaci\u00f3n de la cuenta del Cliente.<\/p><p>Para la implementaci\u00f3n de determinadas funcionalidades, el Portal Web podr\u00e1 incluir algunas \u201cAplicaciones de Terceros\u201d que, a estos efectos, significa una aplicaci\u00f3n on-line, o basada en la web (web-based) o un producto de software off-line suministrado o autorizado por un Tercero que interact\u00faa con los servicios del Portal Web. Debe tenerse en cuenta que CONTRATAME.ONLINE no ofrece ninguna garant\u00eda con respecto a la disponibilidad permanente de dichas Aplicaciones de Terceros y el Cliente reconoce que si cualquier proveedor de una Aplicaci\u00f3n de Terceros cesa o deja de ofrecer el servicio en condiciones que el Proveedor considere razonables, \u00e9ste podr\u00e1, a su discreci\u00f3n, eliminar dichas funcionalidades de los Servicios sin incurrir en ninguna responsabilidad hacia el Cliente.<\/p><p>El Portal Web incluye o puede incluir dentro de sus contenidos enlaces u otro tipo de interacci\u00f3n con sitios web pertenecientes o gestionados por terceros. El uso de cualquiera de estos sitios web y servicios de terceros ser\u00e1 por cuenta y riesgo del Cliente y en absoluto responsabilidad de CONTRATAME.ONLINE. CONTRATAME.ONLINE no acepta ninguna responsabilidad por la disponibilidad, idoneidad, fiabilidad o contenido de dichos sitios web de terceros y no avala o suscribe las opiniones expresadas en ellos. Cualquier uso de los sitios web de terceros se encuentra sujeto a sus respectivos t\u00e9rminos y condiciones de uso de dicho tercero.<\/p><p>Interoperabilidad de datos, Aplicaciones de Terceros y proveedores de terceros: En caso de uso de productos o servicios de terceros, incluyendo Aplicaciones de Terceros o cualquier otra aplicaci\u00f3n que no proceda de CONTRATAME.ONLINE, o si el Cliente intercambia cualesquiera datos con un proveedor de terceros en relaci\u00f3n con los servicios, incluso mediante el uso de interfaces de programaci\u00f3n de aplicaciones (API) proporcionadas por CONTRATAME.ONLINE, las modalidades de esas operaciones son exclusivamente entre el Cliente y los referidos terceros, sin garant\u00edas de CONTRATAME.ONLINE, quien no ser\u00e1 responsable por cualquier divulgaci\u00f3n, modificaci\u00f3n o cancelaci\u00f3n de datos del cliente resultante de cualquier acceso por dicha Aplicaci\u00f3n de Terceros o proveedores de servicios elegidos por el Cliente.<\/p><p>CONTRATAME.ONLINE no puede responsabilizarse por los da\u00f1os y perjuicios de cualquier naturaleza derivados de la falta de exactitud, exhaustividad, actualidad, de errores u omisiones de los que pudieran adolecer las informaciones y servicios contenidos en este Portal Web u otros Contenidos de Usuario y de terceros a los que se pueda acceder a trav\u00e9s del mismo. En caso de que un Usuario considere que existe Contenido en el Portal Web que atente contra sus derechos debe comunicarlo inmediatamente a CONTRATAME.ONLINE a trav\u00e9s del formulario de contacto del Portal Web. Asimismo, CONTRATAME.ONLINE no asume ning\u00fan deber o compromiso de verificar ni de vigilar sus contenidos e informaciones m\u00e1s all\u00e1 de las verificaciones de su equipo de moderaci\u00f3n y tras aquellas denuncias remitidas por los Usuarios mediante el formulario de contacto accesible f\u00e1cilmente en el Portal Web.<\/p><p>CONTRATAME.ONLINE no puede responsabilizarse por los da\u00f1os y perjuicios que pudieran deberse a los servicios prestados por terceros a trav\u00e9s de este Portal Web, as\u00ed como a los medios que \u00e9stos habilitan para gestionar las solicitudes de servicio, y concretamente, a modo enunciativo y no limitativo: por los actos de competencia desleal y publicidad il\u00edcita como consecuencia de la prestaci\u00f3n de servicios por terceros a trav\u00e9s del Portal Web, as\u00ed como a la falta de veracidad, exactitud, exhaustividad, vicios, defectos, pertinencia y\/o actualidad de los contenidos transmitidos, difundidos, almacenados, recibidos, obtenidos, puestos a disposici\u00f3n o accesibles mediante los servicios prestados por terceros a trav\u00e9s de este Portal Web.<\/p><p>El Usuario tiene derecho a darse de baja del portal de manera simple y eficaz y a dejar de recibir mensajes con origen en el mismo. CONTRATAME.ONLINE no puede garantizar que otros Usuarios que ya cuentan con la direcci\u00f3n de correo del Usuario a trav\u00e9s de su contacto en el Portal Web puedan volver a contactar con \u00e9ste en un futuro. Asimismo, la inclusi\u00f3n por parte de los Demandantes de Trabajo de su el curr\u00edculum vitae en nuestra base de datos on-line aumenta considerablemente su visibilidad a Ofertantes de empleo en busca de personal. Se deja expresa constancia de que CONTRATAME.ONLINE realiza un esfuerzo para limitar el acceso al curr\u00edculum vitae de los Usuarios Particulares solamente por Ofertantes de empleo con este fin. Sin embargo, CONTRATAME.ONLINE no puede ofrecer una garant\u00eda a este respecto. En cualquier caso, prohibiremos el acceso al servicio a cualquier empresa que descubramos que hace un uso de los datos con fines diferentes a \u00e9ste.<\/p><p>El Portal Web incluye dentro de sus contenidos enlaces a sitios web pertenecientes o gestionados por terceros, con el objeto de facilitar el acceso a informaci\u00f3n disponible a trav\u00e9s de Internet. CONTRATAME.ONLINE no asume ninguna responsabilidad derivada de la existencia de enlaces entre los contenidos de este sitio y contenidos situados fuera del mismo o de cualquier otra menci\u00f3n de contenidos externos a este sitio. Tales enlaces o menciones tienen una finalidad exclusivamente informativa y, en ning\u00fan caso, implican el apoyo, aprobaci\u00f3n, comercializaci\u00f3n o relaci\u00f3n alguna entre CONTRATAME.ONLINE y las personas o entidades autoras o gestoras de tales contenidos o titulares de los sitios donde se encuentren.<\/p><p>El uso de la contrase\u00f1a es personal e intransferible, no estando permitida la cesi\u00f3n, ni siquiera temporal, a terceros. El Usuario deber\u00e1 adoptar las medidas necesarias para la custodia de la contrase\u00f1a por \u00e9l seleccionada, evitando el uso de la misma por terceros. El Usuario es el \u00fanico responsable de la utilizaci\u00f3n que se realice de su contrase\u00f1a, con completa indemnidad para CONTRATAME.ONLINE. En el supuesto de que el Usuario conozca o sospeche del uso de su contrase\u00f1a por terceros, deber\u00e1 ponerlo en conocimiento de CONTRATAME.ONLINE a la mayor brevedad posible.<\/p><p>MODIFICACI\u00d3N DE LAS CONDICIONES LEGALES<\/p><p>CONTRATAME.ONLINE se reserva la posibilidad de modificar sin previo aviso el contenido de las Condiciones Legales, de manera que recomienda al Usuario leerlas cada vez que acceda y utilice el Portal Web. Asimismo, CONTRATAME.ONLINE se reserva la posibilidad de modificar sin previo aviso el dise\u00f1o, presentaci\u00f3n y\/o configuraci\u00f3n de este Sitio Web, as\u00ed como algunos o todos los servicios ofrecidos, y a\u00f1adir servicios nuevos.<\/p><p>Ninguno de los cambios se aplicar\u00e1 a aquellas reclamaciones presentadas antes de la publicaci\u00f3n de dichos cambios. El acceso y uso continuado del Portal Web por parte del Usuario constituir\u00e1 su plena aceptaci\u00f3n de dichos cambios incluidos en las presentes condiciones legales.<\/p><p>LEGISLACI\u00d3N APLICABLE Y JURISDICCI\u00d3N<\/p><p>Las presentes Condiciones Legales y el resto de condiciones del Sitio Web se regir\u00e1n por la legislaci\u00f3n inglesa.<\/p><p>Para cuantas cuestiones o controversias que pudieran suscitarse o acciones ejercitarse, derivadas de la prestaci\u00f3n de los servicios y contenidos de CONTRATAME.ONLINE, as\u00ed como sobre la interpretaci\u00f3n, aplicaci\u00f3n, ejecuci\u00f3n, cumplimiento o incumplimiento de lo aqu\u00ed establecido, CONTRATAME.ONLINE y el Usuario, se someten, salvo que la normativa diga lo contrario, a la jurisdicci\u00f3n de los Juzgados y Tribunales ingleses.<\/p><p>DERECHOS DE PROPIEDAD INTELECTUAL E INDUSTRIAL<\/p><p>Copyright \u00a9 2014-2020 &#8211; CONTRATAME.ONLINE &#8211; Todos los derechos reservados.<\/p><p>Quedan reservados todos los derechos de explotaci\u00f3n.<\/p><p>Los textos, dise\u00f1os, im\u00e1genes, bases de datos, logos, estructura, marcas y dem\u00e1s elementos de este Portal Web est\u00e1n protegidos por los derechos de propiedad intelectual e industrial de CONTRATAME.ONLINE y\/o de terceros titulares de los mismos que han autorizado debidamente su inclusi\u00f3n en el Portal Web, mediante el formulario de registro o en su caso, acuerdos de cesi\u00f3n al respecto.<\/p><p>Cualquier reproducci\u00f3n, transmisi\u00f3n, adaptaci\u00f3n, traducci\u00f3n, modificaci\u00f3n, comunicaci\u00f3n al p\u00fablico, o cualquier otra explotaci\u00f3n de todo o parte del contenido de este Sitio Web titularidad de CONTRATAME.ONLINE, efectuada de cualquier forma o por cualquier medio, electr\u00f3nico, mec\u00e1nico u otro, est\u00e1n estrictamente prohibidos salvo autorizaci\u00f3n previa por escrito de CONTRATAME.ONLINE o de terceros leg\u00edtimos titulares. Cualquier infracci\u00f3n de estos derechos puede dar lugar a procedimientos judiciales civiles o penales que correspondan.<\/p><p>La presencia en el Portal Web de cualesquiera textos, dise\u00f1os, im\u00e1genes, bases de datos, logos, estructura, marcas u otros derechos de propiedad intelectual o industrial de terceros no implica la cesi\u00f3n de la titularidad de los mismos a CONTRATAME.ONLINE. La legitimidad de los derechos de propiedad intelectual o industrial correspondientes a los contenidos aportados por los Usuarios es de la exclusiva responsabilidad de los mismos.<\/p><p>En el caso de que cualquier Usuario o un tercero considere que se ha producido una violaci\u00f3n de sus leg\u00edtimos derechos de propiedad intelectual y\/o industrial por la introducci\u00f3n de un determinado contenido en el Sitio Web deber\u00e1 notificar dicha circunstancia por escrito a CONTRATAME.ONLINE Ltd seg\u00fan los datos de contacto indicados m\u00e1s abajo e indicando:<\/p><p>Datos identificativos del interesado titular de los derechos presuntamente infringidos. Si la reclamaci\u00f3n la presenta un tercero distinto del interesado, deber\u00e1 indicar y acreditar la representaci\u00f3n con la que act\u00faa.<\/p><p>Indicaci\u00f3n de los contenidos protegidos por los derechos de propiedad intelectual y\/o industrial y su ubicaci\u00f3n en el Portal Web.<\/p><p>Acreditaci\u00f3n de la existencia, titularidad y vigencia de los citados derechos de propiedad intelectual y\/o industrial.<\/p><p>Declaraci\u00f3n expresa en la que el interesado se responsabiliza de la veracidad de los datos e informaci\u00f3n facilitados en la notificaci\u00f3n a que se refiere este punto.<\/p><p>INFORMACI\u00d3N DE CONTACTO<\/p><p>Si tienes alguna pregunta, queja, sugerencia o comentario sobre las presentes Condiciones Legales puedes contactar con nosotros de la siguiente forma:<\/p><p>A trav\u00e9s del formulario de contacto:<\/p><p>Si eres Usuario Particular a trav\u00e9s del siguiente enlace: formulario de contacto.<\/p><p>Si eres Usuario Profesional a trav\u00e9s del siguiente enlace: formulario de contacto.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>CONDICIONES GENERALES DE USO DEL PORTAL PRE\u00c1MBULO CONTRATAME ONLINE (en adelante \u201cCONTRATAME.ONLINE\u201d o &#8220;CONTRATAME.ONLINE&#8221;) ofrece a los usuarios del Sitio Web CONTRATAME.ONLINE de forma gratuita, reservando algunos servicios espec\u00edficos al pago de una suscripci\u00f3n o pago puntual. CONTRATAME.ONLINE entiende por \u201cUsuario Particular\u201d o \u201cDemandante de Trabajo o &#8220;Candidato&#8221;\u201d aquellas personas f\u00edsicas que accedan a los [&hellip;]<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"inline_featured_image":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"class_list":["post-38","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>T\u00e9rminos y condiciones - Contratame.online<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/contratame.online\/es\/terminos-y-condiciones\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"T\u00e9rminos y condiciones - Contratame.online\" \/>\n<meta property=\"og:description\" content=\"CONDICIONES GENERALES DE USO DEL PORTAL PRE\u00c1MBULO CONTRATAME ONLINE (en adelante \u201cCONTRATAME.ONLINE\u201d o &#8220;CONTRATAME.ONLINE&#8221;) ofrece a los usuarios del Sitio Web CONTRATAME.ONLINE de forma gratuita, reservando algunos servicios espec\u00edficos al pago de una suscripci\u00f3n o pago puntual. CONTRATAME.ONLINE entiende por \u201cUsuario Particular\u201d o \u201cDemandante de Trabajo o &#8220;Candidato&#8221;\u201d aquellas personas f\u00edsicas que accedan a los [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/contratame.online\/es\/terminos-y-condiciones\/\" \/>\n<meta property=\"og:site_name\" content=\"Contratame.online\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/contratamegt\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-10T05:57:31+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"48 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/contratame.online\/terminos-y-condiciones\/\",\"url\":\"https:\/\/contratame.online\/terminos-y-condiciones\/\",\"name\":\"T\u00e9rminos y condiciones - Contratame.online\",\"isPartOf\":{\"@id\":\"https:\/\/contratame.online\/#website\"},\"datePublished\":\"2021-03-10T09:28:48+00:00\",\"dateModified\":\"2026-02-10T05:57:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/contratame.online\/terminos-y-condiciones\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/contratame.online\/terminos-y-condiciones\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/contratame.online\/terminos-y-condiciones\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/contratame.online\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"T\u00e9rminos y condiciones\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/contratame.online\/#website\",\"url\":\"https:\/\/contratame.online\/\",\"name\":\"Contratame.online\",\"description\":\"Encuentra el empleo que siempre so\u00f1aste.\",\"publisher\":{\"@id\":\"https:\/\/contratame.online\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/contratame.online\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/contratame.online\/#organization\",\"name\":\"CONTRATA ME\",\"url\":\"https:\/\/contratame.online\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/contratame.online\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/contratame.online\/wp-content\/uploads\/2023\/07\/logohd.png\",\"contentUrl\":\"https:\/\/contratame.online\/wp-content\/uploads\/2023\/07\/logohd.png\",\"width\":150,\"height\":50,\"caption\":\"CONTRATA ME\"},\"image\":{\"@id\":\"https:\/\/contratame.online\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/contratamegt\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"T\u00e9rminos y condiciones - Contratame.online","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/contratame.online\/es\/terminos-y-condiciones\/","og_locale":"es_ES","og_type":"article","og_title":"T\u00e9rminos y condiciones - Contratame.online","og_description":"CONDICIONES GENERALES DE USO DEL PORTAL PRE\u00c1MBULO CONTRATAME ONLINE (en adelante \u201cCONTRATAME.ONLINE\u201d o &#8220;CONTRATAME.ONLINE&#8221;) ofrece a los usuarios del Sitio Web CONTRATAME.ONLINE de forma gratuita, reservando algunos servicios espec\u00edficos al pago de una suscripci\u00f3n o pago puntual. CONTRATAME.ONLINE entiende por \u201cUsuario Particular\u201d o \u201cDemandante de Trabajo o &#8220;Candidato&#8221;\u201d aquellas personas f\u00edsicas que accedan a los [&hellip;]","og_url":"https:\/\/contratame.online\/es\/terminos-y-condiciones\/","og_site_name":"Contratame.online","article_publisher":"https:\/\/www.facebook.com\/contratamegt","article_modified_time":"2026-02-10T05:57:31+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"48 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/contratame.online\/terminos-y-condiciones\/","url":"https:\/\/contratame.online\/terminos-y-condiciones\/","name":"T\u00e9rminos y condiciones - Contratame.online","isPartOf":{"@id":"https:\/\/contratame.online\/#website"},"datePublished":"2021-03-10T09:28:48+00:00","dateModified":"2026-02-10T05:57:31+00:00","breadcrumb":{"@id":"https:\/\/contratame.online\/terminos-y-condiciones\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/contratame.online\/terminos-y-condiciones\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/contratame.online\/terminos-y-condiciones\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/contratame.online\/"},{"@type":"ListItem","position":2,"name":"T\u00e9rminos y condiciones"}]},{"@type":"WebSite","@id":"https:\/\/contratame.online\/#website","url":"https:\/\/contratame.online\/","name":"Contratame.online","description":"Encuentra el empleo que siempre so\u00f1aste.","publisher":{"@id":"https:\/\/contratame.online\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/contratame.online\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/contratame.online\/#organization","name":"CONTRATA ME","url":"https:\/\/contratame.online\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/contratame.online\/#\/schema\/logo\/image\/","url":"https:\/\/contratame.online\/wp-content\/uploads\/2023\/07\/logohd.png","contentUrl":"https:\/\/contratame.online\/wp-content\/uploads\/2023\/07\/logohd.png","width":150,"height":50,"caption":"CONTRATA ME"},"image":{"@id":"https:\/\/contratame.online\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/contratamegt"]}]}},"_links":{"self":[{"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/pages\/38","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/comments?post=38"}],"version-history":[{"count":4,"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/pages\/38\/revisions"}],"predecessor-version":[{"id":73710,"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/pages\/38\/revisions\/73710"}],"wp:attachment":[{"href":"https:\/\/contratame.online\/es\/wp-json\/wp\/v2\/media?parent=38"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}